{"id":282,"date":"2007-04-29T06:45:00","date_gmt":"2007-04-29T06:45:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=282"},"modified":"2007-04-29T06:45:00","modified_gmt":"2007-04-29T06:45:00","slug":"el-estadounidense-paul-auster-y-mexicano-guillermo-arriaga","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/04\/29\/el-estadounidense-paul-auster-y-mexicano-guillermo-arriaga\/","title":{"rendered":"El estadounidense Paul Auster y el mexicano Guillermo Arriaga"},"content":{"rendered":"<p>El estadounidense Paul Auster y el mexicano Guillermo Arriaga mantuvieron el viernes por la noche una charla casi de amigos \u00edntimos en el marco del Festival Literario del PEN Club, que se celebra en Nueva York. Ambos creadores intercambiaron ideas ante una audiencia atenta a sus opiniones sobre el cine y la literatura, sin olvidarse de temas tan universales como el dolor y la muerte. La charla se produjo en el marco del festival, que se celebra esta semana en Nueva York, donde se re\u00fanen unos 162 escritores y cr\u00edticos culturales de 45 pa\u00edses para presentar sus obras, hablar sobre literatura y debatir sobre asuntos culturales, pol\u00edticos y sociales. Durante una hora hablaron sobre sus carreras literarias y sus incursiones en el mundo del cine, en una charla que tom\u00f3 tintes personales desde un principio y en la que destacaron los relatos de sus experiencias con el dolor y la muerte como puntos de partida en sus trayectorias vitales y profesionales.<br \/>\nLe\u00eddo en <A href=\"http:\/\/estadis.eluniversal.com.mx\/cultura\/52422.html\">El Universal<\/a>, <A href=\"http:\/\/www.elporvenir.com.mx\/notas.asp?nota_id=129548\">El Porvenir<\/a> y otra prensa sudamericana.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El estadounidense Paul Auster y el mexicano Guillermo Arriaga mantuvieron el viernes por la noche una charla casi de amigos \u00edntimos en el marco del Festival Literario del PEN Club, que se celebra en Nueva York. Ambos creadores intercambiaron ideas ante una audiencia atenta a sus opiniones sobre el cine y la literatura, sin olvidarse [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}