{"id":260,"date":"2007-05-29T06:17:00","date_gmt":"2007-05-29T06:17:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=260"},"modified":"2007-05-29T06:17:00","modified_gmt":"2007-05-29T06:17:00","slug":"elliott-murphy-antitaurino","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/05\/29\/elliott-murphy-antitaurino\/","title":{"rendered":"Elliott Murphy, antitaurino"},"content":{"rendered":"<p><A href=\"http:\/\/bp3.blogger.com\/_LSCWnEpAnto\/RlteocL5xcI\/AAAAAAAAAHw\/P_h_LxR3yN0\/s1600-h\/foto_218792_CAS.jpg\"><IMG id=\"BLOGGER_PHOTO_ID_5069749854389519810\" style=\"margin: 0px auto 10px; display: block; text-align: center;\" alt=\"\" src=\"\/\/bp3.blogger.com\/_LSCWnEpAnto\/RlteocL5xcI\/AAAAAAAAAHw\/P_h_LxR3yN0\/s320\/foto_218792_CAS.jpg\" border=\"0\"><\/a><\/p>\n<div>Con cierto retraso, me llega esta curiosa informaci\u00f3n de <A href=\"http:\/\/www.elperiodico.com\/default.asp?idpublicacio_PK=46&#038;idioma=CAS&amp;amp;amp;amp;idnoticia_PK=407218&#038;idseccio_PK=1026\">El Periodico de Catalunya<\/a>:<\/p>\n<div>\n<blockquote><p>Elliott Murphy canta gratis en BCN contra el sufrimiento de los toros<\/p>\n<p>BCN. <em>Rock y compromiso siempre han ido unidos para Elliott Murphy. El polifac\u00e9tico cantautor norteamericano residente en Par\u00eds demostrar\u00e1 hoy hasta qu\u00e9 punto sus ideales siguen intactos participando en un concierto gratuito en la plaza de la Revoluci\u00f3, en Gr\u00e0cia (20.00 horas) con su banda, The Normandy All Stars. Lo organiza el Partido Antitaurino Contra el Maltrato Animal (PACMA). &#8220;No estoy en contra de la tradici\u00f3n, pero s\u00ed contra la crueldad con los animales por diversi\u00f3n&#8221;, declara Murphy, buen conocedor de Espa\u00f1a. El autor de Last of the<br \/>\nrock stars y Diamonds by the yard solo ha visto corridas de toros por televisi\u00f3n. &#8220;Hay quienes por los animales se hacen vegetarianos, otros que se niegan a calzar zapatos de piel. Yo estoy contra la crueldad, me incomoda el sufrimiento de un animal&#8221;. No le convence el argumento de que, al menos, los toros viven dignamente hasta el d\u00eda final. &#8220;Tambi\u00e9n antes de ser ejecutado en EEUU te dan una buena comida&#8221;, razona.A diferencia de su famoso amigo Bruce Springsteen, que nunca ha respondido a la llamada del PACMA, Murphy acept\u00f3 a la primera. Ana Bayle, miembro del partido, abogada y fan de Murphy, le contact\u00f3 v\u00eda correo electr\u00f3nico hace un mes. &#8220;Es mi primer concierto por los animales. Antes estuve en otras campa\u00f1as. Uno debe defender lo que piensa&#8221;.<\/em><\/p>\n<p><em>HEMINGWAY, UN DILEMA<\/em><\/p>\n<p><em>Escritor de novelas y admirador de autores como F. Scott Fitzgerald y Jack Kerouac, reconoce que le cost\u00f3 no poder amar a los toros tanto como Hemingway. &#8220;He le\u00eddo todos sus libros y me encanta. Por eso su pasi\u00f3n taurina me cre\u00f3 un conflicto. \u00c9l escrib\u00eda sobre los toros de forma bell\u00edsima pero tambi\u00e9n lo hizo con la guerra, y no es que sea bonita&#8221;.Nunca olvidar\u00e1 la primera vez que actu\u00f3 en Espa\u00f1a. &#8220;Era en 1982, empezaba a haber conciertos de manera regular. Nos trataban como si fu\u00e9semos los Beatles&#8221;, recuerda. Desde entonces ha vuelto casi cada a\u00f1o.Muchas cosas han cambiado en la m\u00fasica desde su primer vinilo. Lo que m\u00e1s le sorprende es la banalizaci\u00f3n del rock, tan subversivo en los 70 y que hoy se utiliza para vender de todo. &#8220;Si hasta una canci\u00f3n de Dylan acompa\u00f1\u00f3 un anuncio de lencer\u00eda de Victoria&#8217;s Secret&#8221;, dice divertido. &#8220;Lo \u00fanico que envidio de los cantantes famosos es los recursos de que disponen para contar con m\u00e1s m\u00fasicos y mejor sonido. La m\u00fasica es cara, no como la pintura, donde solo necesitas telas y pinceles&#8221;.Admirado por Lou Reed, Elvis Costello, Tom Petty y otras leyendas, Murphy ha envejecido bien, igual que su primer disco, Aquashow.<br \/>\nY, como entonces, sigue pensando que no importa qui\u00e9n ocupa la Gran Casa, como bautiz\u00f3 a la Casa Blanca en aquel trabajo. &#8220;Lo importante es la mentalidad de la gente&#8221;, afirma.En su \u00faltimo CD, Coming home again, vuelve a sus ra\u00edces. &#8220;Recupera el sonido de los 70, que musicalmente fueron muy buenos pero que se cargaron el idealismo de los 60&#8221;. A\u00fan no sabe qu\u00e9 tocar\u00e1 hoy. Tiene m\u00e1s de 300 bras donde escoger.<\/em><\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Con cierto retraso, me llega esta curiosa informaci\u00f3n de El Periodico de Catalunya: Elliott Murphy canta gratis en BCN contra el sufrimiento de los toros BCN. Rock y compromiso siempre han ido unidos para Elliott Murphy. El polifac\u00e9tico cantautor norteamericano residente en Par\u00eds demostrar\u00e1 hoy hasta qu\u00e9 punto sus ideales siguen intactos participando en un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-260","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/260\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}