{"id":205,"date":"2007-07-29T03:50:00","date_gmt":"2007-07-29T03:50:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=205"},"modified":"2007-07-29T03:50:00","modified_gmt":"2007-07-29T03:50:00","slug":"la-vida-interior-martin-frost-anagrama","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2007\/07\/29\/la-vida-interior-martin-frost-anagrama\/","title":{"rendered":"La vida interior de Martin Frost, en Anagrama"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp3.blogger.com\/_LSCWnEpAnto\/Rqy0R6bijbI\/AAAAAAAAAMw\/xqBwVKjo2Sk\/s1600-h\/0312427034M.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/bp3.blogger.com\/_LSCWnEpAnto\/Rqy0R6bijbI\/AAAAAAAAAMw\/xqBwVKjo2Sk\/s400\/0312427034M.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5092643498484731314\" border=\"0\"><\/a>De acuerdo con <A href=\"http:\/\/www.elcultural.es\/HTML\/20070726\/Letras\/Letras21054.asp\">El Cultural<\/a>, la editorial <A href=\"http:\/\/www.anagrama-ed.es\/novedades\">Anagrama<\/a> publicar\u00e1 en los pr\u00f3ximos meses el gui\u00f3n de la \u00faltima pel\u00edcula de Paul Auster, La vida interior de Martin Frost (The inner life of Martin Frost), que el propio escritor presentar\u00e1 en Espa\u00f1a en septiembre en el marco del festival de cine de San Sebasti\u00e1n (fuera de concurso), cuyo jurado presudir\u00e1. El gui\u00f3n <A href=\"http:\/\/paulauster.blogspot.com\/2007\/05\/publican-el-guin-de-inner-life.html\">ya ha visto la luz en Estados Unidos<\/a> bajo la editorial Picador.<\/p>\n<p><span style=\"font-weight: bold;\">Otras novedades (<\/span><A style=\"font-weight: bold;\" href=\"http:\/\/www.elcultural.es\/HTML\/20070726\/Letras\/Letras21054.asp\">El Cultural<\/a><span style=\"font-weight: bold;\">)<\/span><br \/>\n<span class=\"Texto\"><\/span><\/p>\n<blockquote><p><span class=\"Texto\"> (&#8230;) En septiembre nos esperan jugosas novedades: para empezar, por lo que a la narrativa en castellano se refiere, adem\u00e1s de la recuperaci\u00f3n de <em>Antonio B. el Ruso, ciudadano                          de tercera<\/em>, de<strong> Ramiro Pinilla <\/strong>(Tusquets), y                          de la reedici\u00f3n de <em>Historia del silencio,<\/em>                          de<strong> Pedro Zarraluki<\/strong> (RBA), estrenan novela <strong>Enrique Vila-Matas, Bel\u00e9n Gopegui, Rafael Chirbes, Ricardo Piglia, Sergi Pami\u00e8s<\/strong> (todos ellos en Anagrama);<strong>                          Guillermo Mart\u00ednez<\/strong> y<strong> Laura Freixas <\/strong>(Destino);<strong>                          Jos\u00e9 Carlos Llop <\/strong>(RBA); <strong>Federico Andahazi<\/strong>                          y<strong> Alfredo Plagio <\/strong>Echenique (Planeta); <strong>Javier                          Mar\u00edas <\/strong>(Alfaguara) <strong>F\u00e9lix de Az\u00faa                          <\/strong>y <strong>Esther Tusquets<\/strong> (Bruguera) y <strong>Luis Antonio                          de Villena<\/strong> (El Aleph), entre otros<br \/>\n                      La narrativa extranjera no se queda atr\u00e1s, ni falta que le hace, con t\u00edtulos como <em>Falling man<\/em>, de <strong>Don DeLillo<\/strong> (Seix Barral), novela sobre el 11S que tiene un arranque perturbador&#8230; Tambi\u00e9n llegan <em>Las ben\u00e9volas, <\/em>de <strong>Jonathan Littell <\/strong>(RBA), <em> La carretera,<\/em> de <strong>Cormac McCarthy<\/strong> (Mondadori), premiada con el Pulitzer; <em>El legado de la p\u00e9rdida,<\/em> de <strong>Kiran Desai,<\/strong> premio Booket (Salamandra); <em>Pura anarqu\u00eda<\/em>, con 18 relatos de <strong>Woody Allen<\/strong> (Tusquets); <em>La vida interior de Martin Frost,<\/em> el gui\u00f3n de la \u00faltima pel\u00edcula de <strong>Paul Auster <\/strong>(Anagrama), El caballero <em>Hector de Sainte Hermine<\/em>, novela in\u00e9dita de <strong>Alejandro Dumas <\/strong>que lanza Emec\u00e9&#8230;  Y <em>Desorden moral <\/em>de <strong>Margaret Atwood<\/strong> (Bruguera); <em>Cardenio, <\/em>una obra in\u00e9dita de <strong>Shakespeare <\/strong>inspirada en el personaje de la primera parte del Quijote que ver\u00e1 la luz \u2013\u00bfd\u00f3nde si no?\u2013 en Rey Lear. Y el vendid\u00edsimo en todo el mundo <em>Mil soles espl\u00e9ndidos<\/em> de<strong> Khaled Hosseini<\/strong> (Salamandra), y <em>Un peque\u00f1o inconveniente<\/em> de <strong>Mark Haddon<\/strong> (Alfaguara); yel \u00faltimo <strong>Coetzee <\/strong><em>(Diario de un mal a\u00f1o)<\/em>, y el novel\u00f3n de<strong> Vikram Chandra,<\/strong> ambas en Mondadori, y la \u00faltima novela in\u00e9dita de <strong>Nemirovsky <\/strong>(Salamandra)&#8230;<\/span><\/p><\/blockquote>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>De acuerdo con El Cultural, la editorial Anagrama publicar\u00e1 en los pr\u00f3ximos meses el gui\u00f3n de la \u00faltima pel\u00edcula de Paul Auster, La vida interior de Martin Frost (The inner life of Martin Frost), que el propio escritor presentar\u00e1 en Espa\u00f1a en septiembre en el marco del festival de cine de San Sebasti\u00e1n (fuera de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-205","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}