{"id":173,"date":"2008-01-08T02:36:00","date_gmt":"2008-01-08T02:36:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=173"},"modified":"2008-01-08T02:36:00","modified_gmt":"2008-01-08T02:36:00","slug":"ken-follett-vitoria","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/01\/08\/ken-follett-vitoria\/","title":{"rendered":"Ken Follett en Vitoria"},"content":{"rendered":"<p><A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp2.blogger.com\/_LSCWnEpAnto\/R4N1c1iGTfI\/AAAAAAAAAXE\/RrSjGV3qV7k\/s1600-h\/_DSC0243.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/bp2.blogger.com\/_LSCWnEpAnto\/R4N1c1iGTfI\/AAAAAAAAAXE\/RrSjGV3qV7k\/s400\/_DSC0243.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5153091536908865010\" border=\"0\"><\/a>Vitoria espera con expectaci\u00f3n la llegada de Ken Follett, quiz\u00e1 el autor de <span style=\"font-style: italic;\">bestsellers<\/span> de mayor renombre mundial, para presentar en la ciudad su nueva novela, Un mundo sin fin, la continuaci\u00f3n de la archi-vendida Los Pilares de la Tierra. Es la <A href=\"http:\/\/paulauster.blogspot.com\/2007\/12\/ken-follett-presenta-en-vitoria-un.html\">presentaci\u00f3n oficial del libro<\/a> en su versi\u00f3n castellana (a la venta desde el pasado 28 de diciembre) y la repercusi\u00f3n se espera m\u00e1xima, todo un acontecimiento para una capital mediana como Vitoria. Follett ha elegido como lugar de presentaci\u00f3n la catedral de Santa Mar\u00eda, un templo g\u00f3tico enclavado en la parte vieja de la ciudad que es desde finales de los 90 un ejemplo en materia de rehabilitaci\u00f3n y reconstrucci\u00f3n del patrimonio. Santa Mar\u00eda es un templo aquejado de notables defectos constructivos por los que tuve que cerrarse al culto. Su rehabilitaci\u00f3n, de la mano de la <A href=\"http:\/\/www.catedralvitoria.com\/\">Fundaci\u00f3n Catedral de Santa Mar\u00eda<\/a>, sigue el concepto de <span style=\"font-style: italic;\">Abierto por obras<\/span>, de manera que puede visitarse en visitas guiadas diarias que ya han disfrutado m\u00e1s de 600.000 personas. Follett encontr\u00f3 en la catedral vitoriana una fuente de inspiraci\u00f3n para escribir Un mundo sin fin, como lo reconoce en el cap\u00edtulo de agradecimientos del volumen. Y junto a la inspiraci\u00f3n, recibi\u00f3 valiosa informaci\u00f3n sobre el proceso de deterioro de la catedral, que le sirvi\u00f3 para narrar en el libro los problemas de la imaginaria catedral de Kingsbridge, tambi\u00e9n protagonista de Los Pilares.<br \/>\nFollett llega esta tarde\/noche a Vitoria con una agenda cargada de actos. A los t\u00edpicamente promocionales (prev\u00e9 entrevistas con medios escritos, radio y televisi\u00f3n, a las que dedicar\u00e1 un d\u00eda completo), se unen un encuentro con su p\u00fablico en el Teatro Principal (invitaciones agotadas, ni lo intenten), actos institucionales y la ceremonia de descubrimiento de la estatua que la ciudad colocar\u00e1 en su honor en el exterior de Santa Mar\u00eda.<br \/>\n<A href=\"http:\/\/www.elcorreo.com\/alava\/20080108\/cultura\/retrato-hombre-nombre-20080108.html\">&#8220;Es un retrato del hombre, no del nombre&#8221;<\/a> | El Correo desvela hoy la escultura que se le dedicar\u00e1 en Vitoria.<br \/>\n<A href=\"http:\/\/www.elcorreo.com\/alava\/20080108\/cultura\/merluza-almejas-nuevo-portalon-20080108.html\">Merluza con almejas en el nuevo Portal\u00f3n<\/a> | El Correo<br \/>\n<A href=\"http:\/\/www.noticiasdealava.com\/ediciones\/2008\/01\/06\/mirarte\/cultura\/d06cul66.810904.php\">Bienvenido, Mister Follett<\/a> | Diario de Noticias<br \/>\n<A href=\"http:\/\/www.abc.es\/20080105\/cultura-libros\/segundas-partes-nunca-fueron_200801050249.html\">Follett revienta el mercado<\/a> | ABC<br \/>\n<A href=\"http:\/\/www.abc.es\/20071229\/cultura-libros\/follett-sienta-pilares-otro_200712290254.html\">Follett sienta los pilares de otro terremoto editorial<\/a> | ABC<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Vitoria espera con expectaci\u00f3n la llegada de Ken Follett, quiz\u00e1 el autor de bestsellers de mayor renombre mundial, para presentar en la ciudad su nueva novela, Un mundo sin fin, la continuaci\u00f3n de la archi-vendida Los Pilares de la Tierra. Es la presentaci\u00f3n oficial del libro en su versi\u00f3n castellana (a la venta desde el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-173","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}