{"id":162,"date":"2008-01-24T02:18:00","date_gmt":"2008-01-24T02:18:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=162"},"modified":"2008-01-24T02:18:00","modified_gmt":"2008-01-24T02:18:00","slug":"peripecias-una-megaurbe-auster","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/01\/24\/peripecias-una-megaurbe-auster\/","title":{"rendered":"Peripecias en una megaurbe: Auster"},"content":{"rendered":"<p> Jorge Mel\u00e9ndez Preciado, en <A href=\"http:\/\/www.eluniversal.com.mx\/columnas\/69518.html\">El Universal<\/a>.<br \/>\n<A onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/bp3.blogger.com\/_LSCWnEpAnto\/R5jkix9ezJI\/AAAAAAAAAX8\/Mws6cKPpyC4\/s1600-h\/9788433906991.jpg\"><IMG style=\"margin: 0pt 10px 10px 0pt; float: left; cursor: pointer;\" src=\"\/\/bp3.blogger.com\/_LSCWnEpAnto\/R5jkix9ezJI\/AAAAAAAAAX8\/Mws6cKPpyC4\/s200\/9788433906991.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5159124659330796690\" border=\"0\"><\/a> El libro m\u00e1s vendido y emblem\u00e1tico de Paul Auster es, sin duda, La trilog\u00eda de Nueva York. Va en su nueva reimpresi\u00f3n, al parecer son casi 20. Y es que el estilo del autor, la manera en que nos va relatando las historias, las referencias que hace a otros escritores y las citas de obras maestras; su relaci\u00f3n con la m\u00fasica y, sobre todo, el que casi siempre ocurra lo inesperado, es lo que sit\u00faa en un primer plano al elaborador de ficciones.<br \/>\nCinematogr\u00e1ficamente Nueva York ha estado presente siempre. Baste recordar Manhattan de Woody Allen (el amor y la perdici\u00f3n) o la escalofriante El d\u00eda despu\u00e9s de ma\u00f1ana (el cambio clim\u00e1tico) de Roland Emmerich y la reciente Soy leyenda (un bodrio entre vital y m\u00edstico) de Francis Lawrence. Nadie ha intentado llevar a la pantalla grande la citada obra de Paul, que dividida en tres episodios concluye en el suspenso, algo que admirar\u00edan Dashiell Hammett y Raymond Chandler, maestros de la novela policiaca estadounidense.<br \/>\nEn el primer episodio, La ciudad de cristal, una llamada equivocada lleva a un literato a convertirse en detective. Lo que descubrir\u00e1 acerca de una pareja ser\u00e1 m\u00e1s interesante que sumergirse en sus tareas. Resulta un homenaje a Dostoievski que planteaba algo maravilloso y terrible: la realidad supera a la ficci\u00f3n, como vemos a diario en esta hora cr\u00edtica.<br \/>\nAuster hace un relato medido, donde las sorpresa van apareciendo constantemente, las cuales se conjugan con erudiciones nada petulantes sino que brotan para que el lector recoja joyas que han estado presentes siempre y no hab\u00eda descubierto. [<A href=\"http:\/\/www.eluniversal.com.mx\/columnas\/69518.html\">leer +<\/a>]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Jorge Mel\u00e9ndez Preciado, en El Universal. El libro m\u00e1s vendido y emblem\u00e1tico de Paul Auster es, sin duda, La trilog\u00eda de Nueva York. Va en su nueva reimpresi\u00f3n, al parecer son casi 20. Y es que el estilo del autor, la manera en que nos va relatando las historias, las referencias que hace a otros [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-162","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=162"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/162\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}