{"id":144,"date":"2008-05-09T01:48:00","date_gmt":"2008-05-09T01:48:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/estoesbrooklyn\/?p=144"},"modified":"2008-05-09T01:48:00","modified_gmt":"2008-05-09T01:48:00","slug":"el-rebelde-accidental","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/2008\/05\/09\/el-rebelde-accidental\/","title":{"rendered":"El rebelde accidental"},"content":{"rendered":"<p><A href=\"http:\/\/www.nytimes.com\/2008\/04\/23\/opinion\/23auster.html?_r=1&#038;hp&#038;oref=slogin\">he Accidental Rebel<\/a>. Art\u00edculo de Paul Auster en The New York Times el pasado 23 de abril. Arranca as\u00ed. <span style=\"font-style: italic;\"><br \/>\n&#8220;Fue el a\u00f1o de los a\u00f1os, el a\u00f1o de la locura, el a\u00f1o del fuego, la sangre y la muerte. Hab\u00eda cumplido los 21 y estaba tan loco como todos los dem\u00e1s. Medio mill\u00f3n de soldados americanos permanec\u00edan en Vietnam; Martin Luther King hab\u00eda sido asesinado recientemente; ciudades a lo largo y ancho de am\u00e9rica estaban en llamas y el mundo parec\u00eda encaminado hacia una crisis apocal\u00edptica&#8221;<\/span>.<br \/>\nActualizaci\u00f3n: Interesante debate sobre las movilizaciones de 1968 en <A href=\"http:\/\/www.nytimes.com\/2008\/04\/30\/opinion\/lweb30rebel.html?ref=opinion\">la secci\u00f3n de cartas al editor del Times<\/a>, al hilo del art\u00edculo de Auster. \u00bfSirvieron de algo?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>he Accidental Rebel. Art\u00edculo de Paul Auster en The New York Times el pasado 23 de abril. Arranca as\u00ed. &#8220;Fue el a\u00f1o de los a\u00f1os, el a\u00f1o de la locura, el a\u00f1o del fuego, la sangre y la muerte. Hab\u00eda cumplido los 21 y estaba tan loco como todos los dem\u00e1s. Medio mill\u00f3n de soldados [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-144","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/estoesbrooklyn\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}