{"id":448,"date":"2012-02-02T18:38:10","date_gmt":"2012-02-02T17:38:10","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/elcorner\/?p=448"},"modified":"2012-02-02T18:38:10","modified_gmt":"2012-02-02T17:38:10","slug":"josemi-goldaracena-beti-aurrera","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/elcorner\/2012\/02\/02\/josemi-goldaracena-beti-aurrera\/","title":{"rendered":"Josemi Goldaracena, beti aurrera"},"content":{"rendered":"<p><a href=\"\/elcorner\/wp-content\/uploads\/sites\/4\/2012\/02\/josemi.jpg\"><img loading=\"lazy\" class=\"alignright size-full wp-image-449\" title=\"josemi\" src=\"\/elcorner\/wp-content\/uploads\/sites\/4\/2012\/02\/josemi.jpg\" alt=\"\" width=\"327\" height=\"351\" srcset=\"https:\/\/blogs.elcorreo.com\/elcorner\/wp-content\/uploads\/sites\/4\/2012\/02\/josemi.jpg 407w, https:\/\/blogs.elcorreo.com\/elcorner\/wp-content\/uploads\/sites\/4\/2012\/02\/josemi-279x300.jpg 279w\" sizes=\"(max-width: 327px) 100vw, 327px\" \/><\/a>Hay hombres que crean afici\u00f3n. Transmiten una pasi\u00f3n desmedida que se contagia como un virus ben\u00e9fico que una vez inoculado nos acompa\u00f1a para siempre. Acabo de enterarme de la p\u00e9rdida de uno de ellos: el sacerdote jesuita Josemi Goldaracena. Permitidme que acerque un apunte a este blog personal porque Josemi, adem\u00e1s de un gran hombre y un excelente profesor, era aficionado del Athletic\u00a0 -socio, si no recuerdo mal- y uno de los pilares junto al Padre Mendibelzua del Loyola Indautxu. Es decir, pura historia del f\u00fatbol base vizca\u00edno, de la que rara vez llega a los titulares de los peri\u00f3dicos pero que marca la vida de generaciones enteras. Desde ese club, desde su tarima e incluso desde el altar de alguna capilla, Goldaracena nos ense\u00f1\u00f3 la importancia de la fe en el f\u00fatbol y tambi\u00e9n en la vida. Nos trajo a la memoria las haza\u00f1as remotas de los \u2018once aldeanos\u2019, y nos mostr\u00f3 c\u00f3mo los equipos humildes son los que merecen mayor admiraci\u00f3n. Todo ello, regado con un desaforado bilba\u00ednismo y algunas dosis de provocaci\u00f3n. As\u00ed atra\u00eda las miradas de aquellos j\u00f3venes a los que apasionaba con su discurso. Y luego, cuando sent\u00eda que ya hab\u00eda captado nuestra atenci\u00f3n, nos dejaba caer algunas grandes ense\u00f1anzas. Tenerle delante resultaba inolvidable.<\/p>\n<p>Los de mi a\u00f1o recordamos con cari\u00f1o aquellas convivencias en que entr\u00f3 en la sala donde le esper\u00e1bamos y exclam\u00f3: \u201c\u00a1\u00a1Dios es tonto!!\u201d. A aquel grito entre la sorpresa general le sigui\u00f3 un apag\u00f3n, que sospecho que propici\u00f3 varias vocaciones en mi quinta. Era el modo que ten\u00eda Josemi de explicarnos que &#8220;Dios nos ama, hagamos lo que hagamos&#8221;, cuando hacemos bien las cosas y cuando nos equivocamos, siempre. Pero pocos sacerdotes se habr\u00edan atrevido a explicarlo de un modo tan gr\u00e1fico. O aquellas inolvidables misas que deten\u00eda cada cinco minutos con comentarios futbol\u00edsticos sobre el Loyola y el Athletic: \u201cVamos a pedir perd\u00f3n, especialmente alguno que el s\u00e1bado no bot\u00f3 ni un c\u00f3rner en condiciones\u201d. Y luego miraba al interesado, por si quedaban dudas. Siempre con una cercan\u00eda, un humor y un cari\u00f1o inolvidables.<\/p>\n<p>Por eso, hoy se me ha encogido el alma al saber que ha muerto el gran Josemi Goldaracena. El mismo que nos escrib\u00eda a cientos de alumnos \u2013miles, seguramente- una felicitaci\u00f3n navide\u00f1a todos los a\u00f1os. El apasionado del Athletic que nos ense\u00f1\u00f3 a so\u00f1ar con finales como esa a la que echaremos el guante la semana que viene (paradojas de las fechas). Y el que, tras cada conversaci\u00f3n, tras cada clase, nos miraba a los ojos y nos dec\u00eda: \u201cEh, beti aurrera\u201d. Siempre hacia adelante. Descansa en paz, maestro.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay hombres que crean afici\u00f3n. Transmiten una pasi\u00f3n desmedida que se contagia como un virus ben\u00e9fico que una vez inoculado nos acompa\u00f1a para siempre. Acabo de enterarme de la p\u00e9rdida de uno de ellos: el sacerdote jesuita Josemi Goldaracena. Permitidme que acerque un apunte a este blog personal porque Josemi, adem\u00e1s de un gran hombre [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts\/448"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/comments?post=448"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts\/448\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/media?parent=448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/categories?post=448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/tags?post=448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}