{"id":403,"date":"2011-01-09T03:52:00","date_gmt":"2011-01-09T03:52:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/elcorner\/?p=403"},"modified":"2011-01-09T03:52:00","modified_gmt":"2011-01-09T03:52:00","slug":"un-empate-diferente","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/elcorner\/2011\/01\/09\/un-empate-diferente\/","title":{"rendered":"Un empate diferente"},"content":{"rendered":"<p><IMG style=\"width: 195px; height: 268px;\" src=\"\/elcorner\/wp-content\/uploads\/sites\/4\" id=\"img_0\" class=\"imgizqda\">Hay d\u00edas que a uno le da por reinventarse y esas cosas tambi\u00e9n le pasan al M\u00e1laga. Nos recibi\u00f3 as\u00ed, con un &#8216;once&#8217; improvisado que hizo los deberes al son de un jeque \u00e1rabe. En esos casos, urge sobrevivir. Y es a lo que se empe\u00f1\u00f3 el equipo de Caparr\u00f3s. Pudo ser Apo\u00f1o, en una ocasi\u00f3n de patio de colegio. Hubo muchas de los locales. Y acab\u00f3 siendo Demichelis en un saque de c\u00f3rner. <\/p>\n<p>Pero el desierto de diez minutos de espera para el final fue demasiado para este M\u00e1laga inexperto -desacostumbrado a jugar juntos- a las \u00f3rdenes de Pellegrini. Bast\u00f3 un esfuerzo m\u00e1s y un saque de falta lejano y -tambi\u00e9n- el desorden en las filas locales para que Javi Mart\u00ednez lograra el empate sobre la bocina. Empate a uno fuera de casa. Un punto que sabe a gloria y a rutina. Tras el esfuerzo del Bar\u00e7a, a m\u00ed me vale. No s\u00e9 qu\u00e9 pensar\u00e1n ustedes. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay d\u00edas que a uno le da por reinventarse y esas cosas tambi\u00e9n le pasan al M\u00e1laga. Nos recibi\u00f3 as\u00ed, con un &#8216;once&#8217; improvisado que hizo los deberes al son de un jeque \u00e1rabe. En esos casos, urge sobrevivir. Y es a lo que se empe\u00f1\u00f3 el equipo de Caparr\u00f3s. Pudo ser Apo\u00f1o, en una [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,15],"tags":[34,57,111,160],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts\/403"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/comments?post=403"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/posts\/403\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/media?parent=403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/categories?post=403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/elcorner\/wp-json\/wp\/v2\/tags?post=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}