{"id":4616,"date":"2015-04-21T11:59:02","date_gmt":"2015-04-21T10:59:02","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/el-navegante\/?p=4616"},"modified":"2015-04-21T11:59:02","modified_gmt":"2015-04-21T10:59:02","slug":"cuatro-interesantes-videos-del-eclipse-solar-del-20-de-marzo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/el-navegante\/2015\/04\/21\/cuatro-interesantes-videos-del-eclipse-solar-del-20-de-marzo\/","title":{"rendered":"Cuatro interesantes v\u00eddeos del eclipse solar del 20 de marzo"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"\/el-navegante\/wp-content\/uploads\/sites\/18\/2015\/04\/Clipboard021.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4617\" title=\"Clipboard02\" src=\"\/el-navegante\/wp-content\/uploads\/sites\/18\/2015\/04\/Clipboard021.jpg\" alt=\"\" width=\"599\" height=\"421\" srcset=\"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-content\/uploads\/sites\/18\/2015\/04\/Clipboard021.jpg 999w, https:\/\/blogs.elcorreo.com\/el-navegante\/wp-content\/uploads\/sites\/18\/2015\/04\/Clipboard021-300x211.jpg 300w, https:\/\/blogs.elcorreo.com\/el-navegante\/wp-content\/uploads\/sites\/18\/2015\/04\/Clipboard021-768x540.jpg 768w\" sizes=\"auto, (max-width: 599px) 100vw, 599px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Ha pasado ya un mes del ultimo eclipse de Sol del 20 de marzo de 2015. Ponemos por aqu\u00ed hoy cuatro v\u00eddeos, interesantes por diversos motivos.<\/p>\n<p style=\"text-align: left;\">Este primero es de los pocos en los que se muestra una visi\u00f3n telesc\u00f3pica del mismo. Unas protuberancias chulas adornan el momento. Tiembla la imagen, pero es el \u00fanico testimonio que hemos encontrado de ese momento. Con anillo de diamantes incluido.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/418Lf5VRd_Y?rel=0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<p>Este segundo v\u00eddeo lo ponemos por la curiosidad de que se ve Venus una vez que el cielo est\u00e1 suficientemente oscuro. Arriba, centrado, un poco a la izquierda. \u00bfLo veis?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/dRAkhQ6CfmA?rel=0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<p>En estos dos \u00faltimos, se muestra el eclipse visto desde el espacio. En este caso no resulta especialmente espectacular, por producirse el eclipse muy al norte y al amanecer. Pero es siempre curioso verlo desde esa otra perspectiva, para entenderlo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/GYa-6e4PJBo?rel=0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/KY3muVVPFvA?rel=0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ha pasado ya un mes del ultimo eclipse de Sol del 20 de marzo de 2015. Ponemos por aqu\u00ed hoy cuatro v\u00eddeos, interesantes por diversos motivos. Este primero es de los pocos en los que se muestra una visi\u00f3n telesc\u00f3pica del mismo. Unas protuberancias chulas adornan el momento. Tiembla la imagen, pero es el \u00fanico [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[311],"class_list":["post-4616","post","type-post","status-publish","format-standard","hentry","category-eclipses","tag-eclipse-de-sol"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts\/4616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/comments?post=4616"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts\/4616\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/media?parent=4616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/categories?post=4616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/tags?post=4616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}