{"id":148,"date":"2010-04-23T11:00:00","date_gmt":"2010-04-23T11:00:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/el-navegante\/?p=148"},"modified":"2010-04-23T11:00:00","modified_gmt":"2010-04-23T11:00:00","slug":"timelapses-astronomicos-kike-herrero","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/el-navegante\/2010\/04\/23\/timelapses-astronomicos-kike-herrero\/","title":{"rendered":"Timelapses astron\u00f3micos de Kike Herrero"},"content":{"rendered":"<p>Nuestra amiga Ane Garces nos descubre la magn\u00edfica p\u00e1gina de <A id=link_1 title=http:\/\/www.celdenit.com\/es\/quant-a\/ href=\"http:\/\/www.celdenit.com\/es\/quant-a\/\">Kike Herrero<\/A>, <A id=link_0 title=http:\/\/www.celdenit.com\/es\/ href=\"http:\/\/www.celdenit.com\/es\/\">Celdenit<\/A>. M\u00e1gnifica colecci\u00f3n de fotos, la de este catal\u00e1n. Las pod\u00e9is ver en su web. Sus timelapses os los colgamos aqu\u00ed. Sobran las palabras. Muy bueno.<\/p>\n<p>Para conocer detalles sobre los timelapses y verlos en mejor calidad, ir a <A id=link_0 title=http:\/\/vimeo.com\/user2272566\/videos\/sort:date href=\"http:\/\/vimeo.com\/user2272566\/videos\/sort:date\">vimeo<\/A>.<\/p>\n<p><STRONG>Nit de Lluna al Roque de los Muchachos<\/STRONG> <\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=401><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=10620823&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">           <embed                       src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=10620823&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"401\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/10620823\">Nit de Lluna al Roque de los Muchachos (IAC)<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>El telescopi TNG observant<\/STRONG> <\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=399><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=10646693&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">          <embed                     src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=10646693&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"399\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/10646693\">El telescopi TNG observant<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>Fotografiant M42 des del Montsec<\/STRONG><\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=401><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=9269518&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">         <embed                   src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=9269518&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"401\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/9269518\">Fotografiant M42 des del Montsec<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>Primera observaci\u00f3 des d&#8217;Aitona<\/STRONG><\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=401><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=8120991&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">        <embed                 src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=8120991&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"401\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/8120991\">Primera observaci\u00f3 des d&#8217;Aitona<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>Cel de Pinyana (nit del 7 al 8 de novembre del 2009)<\/STRONG><\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=401><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=7533105&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">       <embed               src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=7533105&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"401\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/7533105\">Cel de Pinyana (nit del 7 al 8 de novembre del 2009)<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>Timelapse des de Ca de Perutxo<\/STRONG><\/p>\n<p> <DIV align=center><\/p>\n<p> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=398><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=6504404&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">      <embed             src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=6504404&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"398\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/6504404\">Timelapse des de Ca de Perutxo<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<p><STRONG>El cel de Pinyana<\/STRONG> <\/p>\n<p> <DIV align=center> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=600 height=398><PARAM NAME=\"allowfullscreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"><PARAM NAME=\"movie\" VALUE=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=6497240&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\">     <embed           src=\"\/\/vimeo.com\/moogaloop.swf?clip_id=6497240&#038;server=vimeo.com&#038;show_title=1&#038;show_byline=1&#038;show_portrait=0&#038;color=00ADEF&#038;fullscreen=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" allowscriptaccess=\"always\" width=\"600\" height=\"398\"><\/embed><\/OBJECT><A href=\"http:\/\/vimeo.com\/6497240\">El cel de Pinyana<\/A> from <A href=\"http:\/\/vimeo.com\/user2272566\">celdenit.com<\/A> on <A href=\"http:\/\/vimeo.com\">Vimeo<\/A>.<\/DIV><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nuestra amiga Ane Garces nos descubre la magn\u00edfica p\u00e1gina de Kike Herrero, Celdenit. M\u00e1gnifica colecci\u00f3n de fotos, la de este catal\u00e1n. Las pod\u00e9is ver en su web. Sus timelapses os los colgamos aqu\u00ed. Sobran las palabras. Muy bueno. Para conocer detalles sobre los timelapses y verlos en mejor calidad, ir a vimeo. Nit de Lluna [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-timelapses-astronomicos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/el-navegante\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}