{"id":91,"date":"2006-04-05T21:08:47","date_gmt":"2006-04-05T21:08:47","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=90"},"modified":"2006-04-05T21:08:47","modified_gmt":"2006-04-05T21:08:47","slug":"productividad-sin-igual","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/04\/05\/productividad-sin-igual\/","title":{"rendered":"Productividad sin igual"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/vidal_02.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"250\"><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Hay <b>un caso singular<\/b> en la producci\u00f3n editorial espa\u00f1ola: el de <A target=\"_blank\" href=\"http:\/\/www.libertaddigital.com\/ilustracion_liberal\/autor.php\/13\">C\u00e9sar Vidal<\/a>. En 2005, seg\u00fan el <A target=\"_blank\" href=\"http:\/\/www.mcu.es\/bases\/spa\/isbn\/ISBN.html\">ISBN<\/a>, <b>public\u00f3 \u00a116 libros!<\/b>,<br \/>\nsin contar reediciones en formato bolsillo o recuperaciones de textos<br \/>\nanteriores que aparecen en otro sello. Es decir, 16 libros originales. <\/p>\n<p>Har\u00e9 un c\u00e1lculo como el que aplica habitualmente Josu Mezo en <A target=\"_blank\" href=\"http:\/\/www.malaprensa.com\">malaprensa.com<\/a>: una estimaci\u00f3n media puede establecer que <b>un libro tiene unos 250 folios<\/b>. Como quiera que Vidal publica un t\u00edtulo cada tres semanas (d\u00e9mosle un mes de vacaciones, tiene derecho), eso significa que <b>escribe 250 folios en quince d\u00edas h\u00e1biles<\/b>. Consideremos que s\u00f3lo escribe de lunes a viernes, porque durante el fin de semana trabaja en la preparaci\u00f3n de <A target=\"_blank\" href=\"http:\/\/www.lalinterna.com\/index.php?\/la-linterna\/ver-Equipo\/csar_vidal\/\">sus tertulias<\/a>, sus art\u00edculos de prensa, conferencias y dem\u00e1s actividades. Pues bien, de lunes a viernes, <b>Vidal escribe casi 17 folios diarios<\/b>,<br \/>\nsin fallar ni un solo d\u00eda. Folios que deja terminados por completo, con<br \/>\nlas correcciones hechas y listos para enviar a la imprenta. <\/p>\n<p>Pero <b>escribir un libro es algo m\u00e1s que llenar folios<\/b>. Requiere<br \/>\nuna preparaci\u00f3n amplia. Distinta para una novela que para un ensayo,<br \/>\npero en cualquier caso un trabajo notable. Sobre todo cuando, como<br \/>\nVidal, se <b>escribe de todo<\/b>: una novela, un ensayo sobre <A target=\"_blank\" href=\"http:\/\/www.sectas.org\/\">sectas<\/a>, otro sobre la <A target=\"_blank\" href=\"http:\/\/www.vatican.va\/\">Iglesia,<\/a> una obra sobre <A target=\"_blank\" href=\"http:\/\/www.monografias.com\/trabajos6\/reru\/reru.shtml\">la revoluci\u00f3n rusa<\/a> y otra sobre <A target=\"_blank\" href=\"http:\/\/www.unilibro.es\/find_buy_es\/libro\/editorial_planeta_s_a_\/enigmas_historicos_al_descubierto_de_jesus_a_ben_laden.asp?sku=692662&#038;idaff=0\">Bin Laden<\/a>, que este hombre da a todos los palos. <\/p>\n<p>Cada uno de ellos le lleva s\u00f3lo quince d\u00edas de trabajo. Amigos, <b>no puedo ocultar ni un minuto m\u00e1s mi admiraci\u00f3n<\/b>.<br \/>\nM\u00e1xime porque en 2004 ya hab\u00eda conseguido una proeza semejante en<br \/>\ncuanto al n\u00famero de libros publicados, y en 2003, y en 2002&#8230; Este a\u00f1o,<br \/>\nen cambio, su productividad ha descendido. Hasta hoy s\u00f3lo ha publicado<br \/>\ndos libros. <b>Espero que no sea un signo de flaqueza o, lo que ser\u00eda peor, de agotamiento. <\/b><\/p>\n<p><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay un caso singular en la producci\u00f3n editorial espa\u00f1ola: el de C\u00e9sar Vidal. En 2005, seg\u00fan el ISBN, public\u00f3 \u00a116 libros!, sin contar reediciones en formato bolsillo o recuperaciones de textos anteriores que aparecen en otro sello. Es decir, 16 libros originales. Har\u00e9 un c\u00e1lculo como el que aplica habitualmente Josu Mezo en malaprensa.com: una [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-91","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}