{"id":86,"date":"2006-03-23T18:45:43","date_gmt":"2006-03-23T18:45:43","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=85"},"modified":"2006-03-23T18:45:43","modified_gmt":"2006-03-23T18:45:43","slug":"pusilanimes-o-algo-peor","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/03\/23\/pusilanimes-o-algo-peor\/","title":{"rendered":"Pusil\u00e1nimes o algo peor"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/alto_01.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"300\"><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Conf\u00edo en que ayer fuera la \u00faltima vez que tengamos que hacerlo. Me refiero a esa <b>encuesta entre personalidades del mundo de la cultura y el deporte<\/b><br \/>\npreguntando por asuntos relativos a la violencia. Lo hemos hecho otras<br \/>\nveces: con ocasi\u00f3n de atentados, o el a\u00f1o pasado con motivo de la cita<br \/>\nelectoral en Euskadi. El tema ayer era, todo el mundo lo sabe, el alto<br \/>\nel fuego. Por eso digo que espero que sea la \u00faltima vez. Ser\u00eda el mejor<br \/>\ns\u00edntoma del estallido de la paz. <\/p>\n<p>Pero ayer volvimos a tropezar, esta vez de forma inesperada, con <b>un buen grupo de pusil\u00e1nimes o algo peor<\/b>. Todos sab\u00edamos que cuando hab\u00eda alg\u00fan atentado determinados <b>deportistas, escritores, intelectuales y artistas elud\u00edan<\/b><br \/>\nde forma m\u00e1s o menos educada pronunciarse sobre la atrocidad: no cog\u00edan<br \/>\nel tel\u00e9fono o lo desconectaban, disimulaban diciendo de s\u00ed mismos que<br \/>\nno estaban en casa o simplemente rehusaban pronunciarse con <b>la inveros\u00edmil excusa de que no hablan de pol\u00edtica<\/b>.<br \/>\nAlgunos de ellos han vuelto a recurrir a este \u00faltimo argumento para no<br \/>\npronunciarse. Y no estoy acusando a varios de los encuestados que desde<br \/>\nhace alg\u00fan tiempo viven muy lejos y han podido perder la perspectiva de<br \/>\nla importancia real del asunto. Me refiero a <b>personas que est\u00e1n<br \/>\nentre nosotros, tomando ca\u00f1as en los mismos bares, leyendo los mismos<br \/>\nperi\u00f3dicos, votando en las mismas elecciones.<\/b> <\/p>\n<p>No s\u00e9 qu\u00e9 pretenden. <b>No s\u00e9 si son pusil\u00e1nimes o mantienen una<br \/>\nestrategia calculada de ambig\u00fcedad para que nadie pueda pensar que<br \/>\nest\u00e1n &#8220;en el otro bando&#8221;<\/b>, sea el otro el bando que sea. En cualquier caso, son <b>los mismos que peri\u00f3dicamente reclaman<\/b><br \/>\na los periodistas que hablemos de su nuevo libro, su estreno o su<br \/>\nfichaje. Y esperan que la sociedad les lea, vaya al cine o jalee sus<br \/>\ngoles. Ante estos pusil\u00e1nimes -o algo peor-, lo&nbsp; mejor que<br \/>\npodr\u00edamos hacer todos, cuando ellos nos reclamen su apoyo, es<br \/>\nasegurarles que nosotros tampoco entramos en pol\u00edtica.<\/font><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Conf\u00edo en que ayer fuera la \u00faltima vez que tengamos que hacerlo. Me refiero a esa encuesta entre personalidades del mundo de la cultura y el deporte preguntando por asuntos relativos a la violencia. Lo hemos hecho otras veces: con ocasi\u00f3n de atentados, o el a\u00f1o pasado con motivo de la cita electoral en Euskadi. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}