{"id":66,"date":"2006-02-13T17:24:54","date_gmt":"2006-02-13T17:24:54","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=65"},"modified":"2006-02-13T17:24:54","modified_gmt":"2006-02-13T17:24:54","slug":"libros-con-amor","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/02\/13\/libros-con-amor\/","title":{"rendered":"Libros con amor"},"content":{"rendered":"<div align=\"justify\"><font face=\"Arial\" size=\"2\"><IMG alt=\"bovary_01.jpg\" src=\"\/divergencias\/files\/bovary_01.jpg\" width=\"100\"><IMG alt=\"pevear_karenina_01.jpg\" src=\"\/divergencias\/files\/pevear_karenina_01.jpg\" width=\"100\"><IMG alt=\"animal_01.jpg\" src=\"\/divergencias\/files\/animal_01.jpg\" width=\"100\"><\/p>\n<p>\nMa\u00f1ana es <A target=\"_blank\" href=\"http:\/\/www.elalmanaque.com\/sanvalentin\/index.htm\">San Valent\u00edn<\/a>. As\u00ed que voy a copiar directamente una idea de los compa\u00f1eros de <A target=\"_blank\" href=\"http:\/\/blogs.elcorreo.com\/evadidos\">Evadidos<\/a> y dedicar este post al <A target=\"_blank\" href=\"http:\/\/roma.cervantes.es\/Cultura\/pdf\/ElAmor.pdf\">amor en la literatura<\/a>.<br \/>\nAcabo de incurrir en una redundancia: <b>amor y literatura.<\/b> \u00bfCu\u00e1ntas<br \/>\nnovelas existen que no traten, de una u otra forma, sobre el amor? <b>Est\u00e1 en toda obra literaria<\/b>, por presencia o por ausencia, en forma<br \/>\nde felicidad o de dolor, como gozo o como rencor derivado del fracaso. <\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">Amor de todo tipo, por supuesto, y desamor<br \/>\ntambi\u00e9n, porque es una fase del amor en algunos, o en muchos, casos.<br \/>\nAbrir una novela es disponerse, con m\u00ednimas excepciones, a <b>sumergirse<br \/>\nde una u otra forma en una historia de amor<\/b>.<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">Lo que sigue no es, por supuesto, un canon.<br \/>\nEs solamente <b>una breve lista<\/b> con algunas de las novelas cuyas historias<br \/>\nde amor m\u00e1s me han impresionado:<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">&#8211; <i>Madame Bovary<\/i>, de <A target=\"_blank\" href=\"http:\/\/www.epdlp.com\/escritor.php?id=1712\">Gustave Flaubert<\/a>.<br \/>\nContiene probablemente <b>el encuentro amoroso mejor contado<\/b> de la<br \/>\nhistoria de la novela. Me refiero a la escena del coche de caballos, a<br \/>\nla salida de la catedral. Es imposible decir m\u00e1s cosas diciendo tan<br \/>\npoco.<\/font><br \/><font face=\"Arial\" size=\"2\">&#8211; <i>Anna Karenina<\/i>, de <A target=\"_blank\" href=\"http:\/\/www.epdlp.com\/escritor.php?id=2361\">Leon Tolstoi<\/a>. Una de las <b>grandes novelas de todos los tiempos<\/b>, con una arrebatadora historia de amor.<\/font><br \/><font face=\"Arial\" size=\"2\">&#8211; <i>El amor en tiempos del c\u00f3lera<\/i>, de<br \/>\n<A target=\"_blank\" href=\"http:\/\/www.angelfire.com\/mt\/marquez\/\">Gabriel Garc\u00eda M\u00e1rquez<\/a>. En tiempo del c\u00f3lera y en el tr\u00f3pico. Un alarde<br \/>\nnarrativo para contar una pasi\u00f3n de m\u00e1s de medio siglo de duraci\u00f3n<br \/>\n<b>inspirada en el noviazgo de los padres del autor<\/b>.<\/font><br \/><font face=\"Arial\" size=\"2\">&#8211; <i>Una m\u00fasica constante<\/i>, de <A target=\"_blank\" href=\"http:\/\/www.randomhouse.com\/boldtype\/0599\/seth\/interview.html\">Vikram Seth<\/a>.<br \/>\nDe c\u00f3mo <b>las segundas oportunidades a veces se presentan<\/b> pero no siempre pueden aprovecharse. Una historia moderna, en<br \/>\nun ambiente culto, refinado y con un punto de desarraigo, y con mucha<br \/>\nm\u00fasica, que es una de las debilidades del autor de este<br \/>\npost.<\/font><br \/><font face=\"Arial\" size=\"2\">&#8211; <i>Una letra femenina azul p\u00e1lido<\/i>, de<br \/>\n<A target=\"_blank\" href=\"http:\/\/www.epdlp.com\/escritor.php?id=2432\">Franz Werfel<\/a>. La inquietud que suscita <b>la vuelta de un amor que se<br \/>\ncre\u00eda olvidado<\/b>. Los esquemas que puede romper y el ego\u00edsmo que puede<br \/>\ngenerar.<\/font><br \/><font face=\"Arial\" size=\"2\">&#8211; <i>Un animal moribundo<\/i>, de <A target=\"_blank\" href=\"http:\/\/orgs.tamu-commerce.edu\/rothsoc\/\">Philip Roth<\/a>. Un<br \/>\nveterano profesor universitario, a punto de jubilarse, se relaciona con<br \/>\nuna atractiva alumna. Parece&nbsp; una historia m\u00e1s de las muchas que<br \/>\nha vivido, pero a\u00f1os despu\u00e9s <b>aquella relaci\u00f3n puramente f\u00edsica revelar\u00e1<br \/>\nque ten\u00eda una profundidad casi desesperada.<\/b> <\/font><br \/><font face=\"Arial\" size=\"2\">&nbsp;<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">Por supuesto, <b>esta lista debe ser<br \/>\ncompletada<\/b>. Estoy seguro de que todos <b>los lectores de este post tendr\u00e1n<br \/>\nen la cabeza unos cuantos t\u00edtulos<\/b> que a\u00f1adir a \u00e9stos.<\/font><\/p>\n<p><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana es San Valent\u00edn. As\u00ed que voy a copiar directamente una idea de los compa\u00f1eros de Evadidos y dedicar este post al amor en la literatura. Acabo de incurrir en una redundancia: amor y literatura. \u00bfCu\u00e1ntas novelas existen que no traten, de una u otra forma, sobre el amor? Est\u00e1 en toda obra literaria, por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-66","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/66\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=66"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=66"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}