{"id":62,"date":"2006-02-06T21:25:35","date_gmt":"2006-02-06T21:25:35","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=61"},"modified":"2006-02-06T21:25:35","modified_gmt":"2006-02-06T21:25:35","slug":"por-no-se-sublevan","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/02\/06\/por-no-se-sublevan\/","title":{"rendered":"\u00bfPor qu\u00e9 no se sublevan?"},"content":{"rendered":"<p><font face=\"Arial\" size=\"2\"><br \/><IMG src=\"\/divergencias\/files\/kazuo_ishiguro.jpg\" width=\"150\"><\/p>\n<p>Descubr\u00ed a <A href=\"http:\/\/www.epdlp.com\/escritor.php?id=1851\">Kazuo Ishiguro<\/a> fue de una manera casual. En la revista <A href=\"http:\/\/www.granta.com\/espanol\/\">Granta<\/a><br \/>\nencontr\u00e9 un gui\u00f3n para un programa de televisi\u00f3n escrito por el autor<br \/>\nen los 80. Era una lectura extra\u00f1a. M\u00e1s o menos, hablaba de un gourmet<br \/>\nque ha comido de todo en esta vida -(todo, incluido eso en lo que est\u00e1<br \/>\nusted pensando)- y ahora se siente vac\u00edo al no encontrar nuevos<br \/>\nalicientes en su b\u00fasqueda del placer. En una cena de lujo -organizada<br \/>\nen alg\u00fan lugar de Sudam\u00e9rica con capos de la droga y otros personajes<br \/>\nde la misma ralea y donde el plato principal es una extra\u00f1a carne de<br \/>\ncolor rosado-, un viejo cocinero le explica al aburrido protagonista<br \/>\nque hay algo que todav\u00eda no ha comido: carne de fantasma. Y entonces<br \/>\nempieza la trama.<\/p>\n<p>Ahora he terminado &#8216;Nunca me abandones&#8217;, la \u00faltima novela del escritor<br \/>\njapon\u00e9s afincado en Londres. Es mejor que el cuento del gourmet. No<br \/>\ndebo contar nada del libro para no estropear la historia, que est\u00e1<br \/>\nllena de momentos terribles, emocionantes y humanos. No es un libro de<br \/>\nciencia ficci\u00f3n, como algunos lo han catalogado. Es otra cosa. Kazuo<br \/>\nIshiguro nos obliga a hacernos una y otra vez esta pregunta: \u00ab\u00bfPor qu\u00e9<br \/>\nno se sublevan?\u00bb. Y al llegar a la \u00faltima p\u00e1gina, la pregunta sigue<br \/>\nah\u00ed. Y, d\u00edas despu\u00e9s, la pregunta sigue ah\u00ed. \u00ab\u00bfPor qu\u00e9 no nos<br \/>\nsublevamos?\u00bb.<\/font><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Descubr\u00ed a Kazuo Ishiguro fue de una manera casual. En la revista Granta encontr\u00e9 un gui\u00f3n para un programa de televisi\u00f3n escrito por el autor en los 80. Era una lectura extra\u00f1a. M\u00e1s o menos, hablaba de un gourmet que ha comido de todo en esta vida -(todo, incluido eso en lo que est\u00e1 usted [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-62","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=62"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/62\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=62"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=62"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}