{"id":54,"date":"2006-01-24T18:09:57","date_gmt":"2006-01-24T18:09:57","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=53"},"modified":"2006-01-24T18:09:57","modified_gmt":"2006-01-24T18:09:57","slug":"1-kltura-10-sgnds","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/01\/24\/1-kltura-10-sgnds\/","title":{"rendered":"1 kltura de 10 sgnds"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/Cellularmonkey-1.jpg\" height=\"213\" width=\"234\"><\/p>\n<p>El poder que llevamos en el bolsillo es inconmensurable. El tel\u00e9fono<br \/>\nm\u00f3vil no s\u00f3lo ha cambiado nuestras vidas sino que cambiar\u00e1 nuestra<br \/>\nforma de ver el mundo. Cuando McLuhan dijo que el medio era el mensaje,<br \/>\nno hay duda de que se refer\u00eda al mensaje multimedia o al SMS.<\/p>\n<p>La <A href=\"http:\/\/www.elcorreo.com\/vizcaya\/edicion\/\/prensa\/noticias\/Portada_VIZ\/200601\/24\/VIZ-ACT-356.html\">Sociedad General de Autores<\/a><br \/>\nha salvado su campa\u00f1a econ\u00f3mica gracias a los tonos para los tel\u00e9fonos<br \/>\nm\u00f3viles. Es decir, el producto por el que a la gente no el importa<br \/>\ngastar dinero es una simple sinton\u00eda de no m\u00e1s de diez&nbsp; segundos<br \/>\nde duraci\u00f3n y que no tiene otra funci\u00f3n que apuntalar el ego de los<br \/>\nusuarios de celulares.<\/p>\n<p>Pero sigamos. Gente que no se ha le\u00eddo el Estatut ni se lo leer\u00e1 s\u00ed que<br \/>\nha recibido en su m\u00f3vil decenas de mensajes en los que Carod es<br \/>\napaleado, atropellado, electrocutado o encerrado en Guant\u00e1namo. Y todo<br \/>\nesto acompa\u00f1ado de una capacidad de convocatoria sin parang\u00f3n. No s\u00e9 si<br \/>\nel 14-M hubiera sido el mismo sin SMS pero no hay duda que las campa\u00f1as<br \/>\nde boicot a los productos catalanes no han tenido mejor portavoz que<br \/>\nlas pantallas de los celulares.<\/p>\n<p>Pero a\u00fan hay m\u00e1s. Existe una fantas\u00eda sobre directores o autores que<br \/>\ncometen los cr\u00edmenes para despu\u00e9s recrearlos en su obra. Y entonces<br \/>\ntenemos a tres j\u00f3venes, uno de ellos menor, acusados de quemar y matar<br \/>\na una mendiga, con el objetivo de grabarlo y enviarlo por SMS a sus<br \/>\namigos. O un grupo de j\u00f3venes de Barcelona que abofetea a transe\u00fantes<br \/>\npara captarlo con sus tel\u00e9fonos.Y todo ello porque en Estados Unidos<br \/>\nunos dementes grabaron un documental sobre las palizas de vagabundos de<br \/>\nLas Vegas y pusieron de moda el &#8216;bumfihgt&#8217;. <\/p>\n<p>\u00bfA d\u00f3nde nos lleva esto? A la progresiva implantaci\u00f3n masiva de un<br \/>\nmodelo de comunicaci\u00f3n de unos 10 segundos de duraci\u00f3n, que, por su<br \/>\nescaso volumen, necesita unos contenidos de impacto para dejar un<br \/>\nrecuerdo en el receptor. Es decir: violencia y sexo. Algo que no nos<br \/>\nobligue a pensar y que no pase de los restos reptiloides de nuestro<br \/>\ncerebro. Sin moral, sin remordimientos. 1 kltura d no + d 10 sgnds. El<br \/>\nfin de la civilizaci\u00f3n tal y como la conocemos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El poder que llevamos en el bolsillo es inconmensurable. El tel\u00e9fono m\u00f3vil no s\u00f3lo ha cambiado nuestras vidas sino que cambiar\u00e1 nuestra forma de ver el mundo. Cuando McLuhan dijo que el medio era el mensaje, no hay duda de que se refer\u00eda al mensaje multimedia o al SMS. La Sociedad General de Autores ha [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-54","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}