{"id":53,"date":"2006-01-22T17:46:52","date_gmt":"2006-01-22T17:46:52","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=52"},"modified":"2006-01-22T17:46:52","modified_gmt":"2006-01-22T17:46:52","slug":"perez-reverte-goya-picasso-guernica","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/01\/22\/perez-reverte-goya-picasso-guernica\/","title":{"rendered":"P\u00e9rez-Reverte, Goya, Picasso, el &#039;Guernica&#039;"},"content":{"rendered":"<p>Querido Arturo, <\/p>\n<p>Como nos hemos tratado en varias ocasiones me permito mandarte este<br \/>\nbreve carta, ya que adem\u00e1s intuyo que aprecias m\u00e1s la discusi\u00f3n<br \/>\ncivilizada que no la simple y a veces traidora adulaci\u00f3n. Lo hago por<br \/>\nlo de las declaraciones del otro d\u00eda. D<b>ec\u00edas que Goya vivi\u00f3 la guerra y que Picasso no<\/b>, y que eso se nota, en tu opini\u00f3n. Seg\u00fan lo planteaba la noticia, parec\u00eda que impl\u00edcitamente se deb\u00eda <b>entender que Goya era mejor que Picasso, al menos en cuanto al tratamiento del tema b\u00e9lico en la pintura<\/b>. Me pregunto si hay que vivir algo tan extremo como la guerra para poder pintarla o escribirla, <b>si a Baroja se le nota que no sali\u00f3 a la mar jam\u00e1s en su vida cuando hablaba de marinos<\/b><br \/>\n(a lo mejor s\u00ed, t\u00fa me contar\u00e1s). Parece, no obstante, que la condici\u00f3n<br \/>\ndel creador implica un cierto grado de instrusismo, en el sentido de<br \/>\nque \u00e9l es capaz de hablar de aquello que a lo mejor no ha experimentado<br \/>\ny s\u00f3lo lo ha imaginado. <br \/><IMG src=\"\/divergencias\/files\/GF02DVP1.jpg\" align=\"left\" hspace=\"10\" vspace=\"10\"><\/p>\n<p>&nbsp;&nbsp;&nbsp; Dec\u00edas que <b>el &#8216;Guernica&#8217; &#8220;no es un cuadro de guerra&#8221;<\/b>.<br \/>\nEstamos de acuerdo. Yo creo que es un cuadro sobre las consecuencias de<br \/>\nla guerra, ya sabes, aquello del paisaje desp\u00faes de la batalla. En<br \/>\ndefintiva, el horror, el dolor de las mujeres, los ni\u00f1os como v\u00edctimas,<br \/>\nla estupidez de los hombres. Y no digo esto por correcci\u00f3n pol\u00edtica.<br \/>\nCreo sinceramente que es as\u00ed. <br \/>\n&nbsp;&nbsp;&nbsp; Picasso., en efecto, no vivi\u00f3 la guerra. Es m\u00e1s, <b>cuando Juan Larrea le sugiri\u00f3 <\/b>que<br \/>\nel bombardeo de Guernica pod\u00eda ser el tema que estaba buscando para su<br \/>\ncuadro de pabell\u00f3n espa\u00f1ol en la Expo de Paris, 1937, el pintor le<br \/>\npregunt\u00f3: \u00bf<b>C\u00f3mo es un bombardeo<\/b>? Sin embargo, \u00e9l conoc\u00eda bien<br \/>\ntodo lo que estaba pasando en Espa\u00f1a y ten\u00eda en Par\u00eds un observatorio<br \/>\nmagn\u00edfico para apercibirse de lo que pod\u00eda pasar en Europa (el<br \/>\nhistoriador Gus Van Hensbergen lo cuenta bastante bien Guernica.<br \/>\nHistoria de un icono del siglo XX, Editorial Debate). <\/p>\n<p><IMG src=\"\/divergencias\/files\/GF05QTU1.jpg\" align=\"left\" hspace=\"10\" vspace=\"10\"><br \/>\n&nbsp;&nbsp;&nbsp; En cualquier caso no parece que haya que elegir entre Goya o Picasso. <b>El Reina Sof\u00eda quiere poner el Guernica al lado de Los fusilamientos del 3 de mayo<\/b>. El malague\u00f1o sab\u00eda lo que se tra\u00eda entre manos.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Querido Arturo, Como nos hemos tratado en varias ocasiones me permito mandarte este breve carta, ya que adem\u00e1s intuyo que aprecias m\u00e1s la discusi\u00f3n civilizada que no la simple y a veces traidora adulaci\u00f3n. Lo hago por lo de las declaraciones del otro d\u00eda. Dec\u00edas que Goya vivi\u00f3 la guerra y que Picasso no, y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-53","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/53\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=53"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}