{"id":5141,"date":"2022-03-29T10:00:15","date_gmt":"2022-03-29T08:00:15","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/divergencias\/?p=5141"},"modified":"2022-03-24T13:36:07","modified_gmt":"2022-03-24T11:36:07","slug":"un-libro-cada-semana-la-muerte-contada-por-un-sapiens-a-un-neandertal-de-juan-jose-millas-y-juan-luis-arsuaga","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2022\/03\/29\/un-libro-cada-semana-la-muerte-contada-por-un-sapiens-a-un-neandertal-de-juan-jose-millas-y-juan-luis-arsuaga\/","title":{"rendered":"Un libro cada semana: &#8216;La muerte contada por un sapiens a un neandertal&#8217; de Juan Jos\u00e9 Mill\u00e1s y Juan Luis Arsuaga"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2022\/03\/sapiens.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-5142\" src=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2022\/03\/sapiens-190x300.jpg\" alt=\"\" width=\"190\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2022\/03\/sapiens-190x300.jpg 190w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2022\/03\/sapiens.jpg 552w\" sizes=\"(max-width: 190px) 100vw, 190px\" \/><\/a><em>La vida contada por un sapiens a un neandertal<\/em> fue uno de los libros que nos alegraron la existencia en un tiempo en el que est\u00e1bamos asustados por la pandemia y lo que pod\u00eda suceder. No s\u00e9 si alguien fue capaz de prever el \u00e9xito que iba a tener ese di\u00e1logo entre un cient\u00edfico y un novelista sobre cuestiones relevantes que a todos nos afectan y sobre las que no siempre nos detenemos demasiado. Lo tuvo, y ahora es m\u00e1s sencillo vaticinar que esta segunda entrega lo tendr\u00e1 igualmente.<\/p>\n<p>Este libro es, por tanto, una continuaci\u00f3n de aquel aunque se puede leer de forma independiente. De nuevo Mill\u00e1s y Arsuaga se van a algunos escenarios por lo menos curiosos y empiezan a hablar. De la muerte pero m\u00e1s a\u00fan de la vida, y mucho sobre la vejez. Sobre c\u00f3mo la ciencia ha alargado la existencia pero eso ha creado problemas que antes no exist\u00edan, y m\u00e1s que va a generar en el futuro, a medida que la esperanza de vida se alargue, incluso por encima de los cien a\u00f1os en un futuro no muy lejano.<\/p>\n<p>Mill\u00e1s y Arsuaga lo cuentan con un gran despliegue de sentido del humor (negro, a veces), lo que hace llevaderos temas que de otra manera pod\u00edan conducir a la depresi\u00f3n o el pesimismo. Nada de eso sucede. Su libro, aunque gire en torno a la muerte, es una celebraci\u00f3n de la vida. Y de eso se trata.<\/p>\n<p>&nbsp;<\/p>\n<p><em>(Publicado en elcorreo.com)<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La vida contada por un sapiens a un neandertal fue uno de los libros que nos alegraron la existencia en un tiempo en el que est\u00e1bamos asustados por la pandemia y lo que pod\u00eda suceder. No s\u00e9 si alguien fue capaz de prever el \u00e9xito que iba a tener ese di\u00e1logo entre un cient\u00edfico y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[3204,1674,2493,3203],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/5141"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=5141"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/5141\/revisions"}],"predecessor-version":[{"id":5144,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/5141\/revisions\/5144"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=5141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=5141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=5141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}