{"id":50,"date":"2006-01-17T16:45:48","date_gmt":"2006-01-17T16:45:48","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=49"},"modified":"2006-01-17T16:45:48","modified_gmt":"2006-01-17T16:45:48","slug":"las-mujeres-corto-maltes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/01\/17\/las-mujeres-corto-maltes\/","title":{"rendered":"Las mujeres de Corto Malt\u00e9s"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/tabaco_01.jpg\" height=\"205\" width=\"211\"><\/p>\n<p>En una taberna de Tarifa me ense\u00f1aron hace unos a\u00f1os una gastada<br \/>\npitillera de plata con el nombre de \u00abVenexiana Stevenson\u00bb grabado en el<br \/>\ninterior y un orificio de bala cerca del cierre. El due\u00f1o de esta<br \/>\nreliquia me asegur\u00f3 que a su abuelo se la hab\u00eda regalado, antes de la<br \/>\nGuerra Civil, una italiana que se present\u00f3 en el pueblo preguntando por<br \/>\nel hijo de una gitana de Gibraltar y un marinero de Cornualles. Yo<br \/>\nquise comprar la pitillera pero su propietario -que sin duda ignoraba<br \/>\nsu valor- me asegur\u00f3 que no pod\u00eda venderla porque era un regalo \u00abde una<br \/>\nse\u00f1ora que miraba como si tuviese la muerte entre las pesta\u00f1as\u00bb.<br \/>\nSupongo que si el hostelero sigue en Tarifa todav\u00eda seguir\u00e1 ense\u00f1ando<br \/>\nesa extra\u00f1a pitillera con el siniestro agujero.<\/p>\n<p><A href=\"http:\/\/www.norma-ed.es\">Norma Editorial<\/a> ya ha publicado en castellano &#8216;Las Mujeres de <A href=\"http:\/\/dreamers.com\/corto\">Corto Malt\u00e9s&#8217;<\/a>,<br \/>\nun libro en el que aparece, entre otras cosas, un informe realizado por<br \/>\nlos expertos de la sociedad de criminolog\u00eda de Lausana sobre Venexiana<br \/>\nStevenson. Fue una de las m\u00e1s despiadadas enemigas del marinero y creo<br \/>\nque intent\u00f3 matarle en un par de ocasiones porque, en el fondo, estaba<br \/>\nenamorada de \u00e9l. \u00a1Qui\u00e9n sabe qu\u00e9 sentimientos le impulsaban cuando<br \/>\nvolvi\u00f3 a Tarifa en busca de Corto! En el libro, adem\u00e1s, hay unas<br \/>\ncuantas acuarelas de las amigas del marino pintadas por Hugo Pratt.<br \/>\nEntre ellas, ese inquietante retrato de Esmeralda con su tatuaje que<br \/>\nahora pasamos a reproducir. El se\u00f1or Pratt tuvo que tener mucha sangre<br \/>\nfr\u00eda para que no le temblase la mano mientras ella posaba. <\/p>\n<p><IMG src=\"\/divergencias\/files\/esmerald.jpg\" height=\"238\" width=\"237\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En una taberna de Tarifa me ense\u00f1aron hace unos a\u00f1os una gastada pitillera de plata con el nombre de \u00abVenexiana Stevenson\u00bb grabado en el interior y un orificio de bala cerca del cierre. El due\u00f1o de esta reliquia me asegur\u00f3 que a su abuelo se la hab\u00eda regalado, antes de la Guerra Civil, una italiana [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-50","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}