{"id":3612,"date":"2019-02-07T12:00:58","date_gmt":"2019-02-07T10:00:58","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/divergencias\/?p=3612"},"modified":"2019-02-07T18:07:25","modified_gmt":"2019-02-07T16:07:25","slug":"ningun-fin-de-semana-sin-musica-sonata-para-piano-no-12-k-332-de-mozart","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2019\/02\/07\/ningun-fin-de-semana-sin-musica-sonata-para-piano-no-12-k-332-de-mozart\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: Sonata para piano N\u00ba 12 K. 332 de Mozart"},"content":{"rendered":"<p>En esta ocasi\u00f3n, la propuesta musical es un homenaje. Porque <strong>esta tarde dar\u00e1 un recital en Bilbao Maria Joao Pires<\/strong> y es muy probable que sea la \u00faltima oportunidad para escucharla por aqu\u00ed. Est\u00e1 ya en sus conciertos de despedida y ser\u00eda verdaderamente extra\u00f1o que regresara. As\u00ed que estamos ante un concierto que tiene mucho de especial, tambi\u00e9n por el programa que trae, compuesto justo por tres de los m\u00fasicos que m\u00e1s ama, y que m\u00e1s veces ha interpretado: Mozart, Beethoven y Chopin. Lo cuenta en una entrevista que publiqu\u00e9 la semana pasada en <strong>El Correo<\/strong>, y que quiz\u00e1 ustedes han tenido ocasi\u00f3n de leer.<\/p>\n<p>La obra que he seleccionado forma parte del programa de este concierto de hoy. Se trata de la <em>Sonata para piano N\u00ba 12 K. 332<\/em>, que forma parte de un grupo de tres, en el que tambi\u00e9n est\u00e1 la que incluye el famoso movimiento <em>Alla turca<\/em>. Les dejo con Mozart, siempre interesante, y con este v\u00eddeo de Pires, hace un buen pu\u00f1ado de a\u00f1os. Disfruten.<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YRcy6J9NVbo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n, la propuesta musical es un homenaje. Porque esta tarde dar\u00e1 un recital en Bilbao Maria Joao Pires y es muy probable que sea la \u00faltima oportunidad para escucharla por aqu\u00ed. Est\u00e1 ya en sus conciertos de despedida y ser\u00eda verdaderamente extra\u00f1o que regresara. As\u00ed que estamos ante un concierto que tiene mucho [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[2799],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3612"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=3612"}],"version-history":[{"count":4,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3612\/revisions"}],"predecessor-version":[{"id":3626,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3612\/revisions\/3626"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=3612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=3612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=3612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}