{"id":3515,"date":"2018-11-22T12:00:27","date_gmt":"2018-11-22T10:00:27","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/divergencias\/?p=3515"},"modified":"2018-11-16T21:18:48","modified_gmt":"2018-11-16T19:18:48","slug":"ningun-fin-de-semana-sin-musica-concierto-para-flauta-arpa-y-orquesta-de-mozart","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2018\/11\/22\/ningun-fin-de-semana-sin-musica-concierto-para-flauta-arpa-y-orquesta-de-mozart\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: Concierto para flauta, arpa y orquesta de Mozart"},"content":{"rendered":"<p>A la edad de 22 a\u00f1os, durante un viaje, <strong>Mozart compuso su Concierto para flauta, arpa y orquesta<\/strong>. Era un encargo de un duque franc\u00e9s, int\u00e9rprete de flauta que quer\u00eda tocarlo con su hija, que a su vez se ocupaba de la parte del arpa. Seg\u00fan parece, el duque nunca pag\u00f3 a Mozart por la obra entregada. En 1778, a\u00f1o de la composici\u00f3n de la partitura, el compositor salzburgu\u00e9s acababa de terminar su Sinfon\u00eda N\u00ba 31 y estaba enfrascado en la composici\u00f3n de un elevado n\u00famero de sonatas para piano y para viol\u00edn y piano.<\/p>\n<p>Una vez, un violonchelista (creo que fue Mischa Maisky) me dijo que nunca perdonar\u00eda a Mozart no haber escrito ning\u00fan concierto para su instrumento. \u00c9l, dec\u00eda, que hizo piezas para solista de trompa, oboe, fagot, arpa y hasta arm\u00f3nica de cristal&#8230; Hoy les propongo una de esas partituras que tienen combinaciones instrumentales verdaderamente inusuales. Aqu\u00ed esta <strong>Mozart en estado puro<\/strong>. El Mozart <strong>\u00e1gil, et\u00e9reo, alegre y r\u00edtmico, y tambi\u00e9n el dulce, hasta un poco melanc\u00f3lico<\/strong> pese a que con 22 a\u00f1os (ni siquiera a los 22 de entonces, tan distintos a los de ahora) no parece existir demasiado motivo para la melancol\u00eda.<\/p>\n<p>La pieza est\u00e1 <strong>entre las m\u00e1s c\u00e9lebres de su autor<\/strong>, aunque seguramente no en el top-10. Les dejo el segundo movimiento, en la interpretaci\u00f3n de una joven orquesta, con una solista de flauta tambi\u00e9n muy joven y una arpista que es una ni\u00f1a. Y no se pierdan c\u00f3mo toca. Van a disfrutar, seguro.<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/00iO7FXWhx8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A la edad de 22 a\u00f1os, durante un viaje, Mozart compuso su Concierto para flauta, arpa y orquesta. Era un encargo de un duque franc\u00e9s, int\u00e9rprete de flauta que quer\u00eda tocarlo con su hija, que a su vez se ocupaba de la parte del arpa. Seg\u00fan parece, el duque nunca pag\u00f3 a Mozart por la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[2642,1670],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3515"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=3515"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3515\/revisions"}],"predecessor-version":[{"id":3518,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3515\/revisions\/3518"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=3515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=3515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=3515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}