{"id":3487,"date":"2018-11-01T12:00:44","date_gmt":"2018-11-01T10:00:44","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/divergencias\/?p=3487"},"modified":"2018-10-30T22:05:11","modified_gmt":"2018-10-30T20:05:11","slug":"ningun-fin-de-semana-sin-musica-danza-macabra-de-saint-saens-2","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2018\/11\/01\/ningun-fin-de-semana-sin-musica-danza-macabra-de-saint-saens-2\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: &#8216;Danza macabra&#8217; de Saint-Sa\u00ebns"},"content":{"rendered":"<p>Puede que les parezca una humorada, pero a veces hay que desdramatizar un poco. Y como hoy es la festividad de Todos los Santos, he pensado que <strong>esta pieza breve<\/strong> de <a href=\"https:\/\/www.musicologie.org\/Biographies\/saint_saens_c.html\" rel=\"external nofollow\">Camille Saint-Sa\u00ebns<\/a>, la <em>Danza Macabra<\/em>, pod\u00eda servir para ello.<\/p>\n<p>La m\u00fasica de Saint-Sa\u00ebns es un ejemplo de excelente acabado aunque\u00a0haya sido y a\u00fan sea un compositor poco apreciado por quienes se han mantenido fieles a las vanguardias. Ya en su tiempo, fue\u00a0<strong>considerado conservador tanto en su obra como en sus planteamientos pedag\u00f3gicos<\/strong>, lo que no le impidi\u00f3 ser un gran promotor de la m\u00fasica nueva que estaba haciendo la generaci\u00f3n posterior a la suya. Debido a ello, su influencia en la\u00a0cultura\u00a0francesa de las \u00faltimas d\u00e9cadas del siglo XIX y las primeras del XX fue enorme. <strong>Su cat\u00e1logo es muy extenso y abarca todos los g\u00e9neros<\/strong>, aunque fuera de Francia se interpreten de manera habitual poco m\u00e1s de una decena de obras:\u00a0la Sinfon\u00eda N\u00ba 3\u00a0y algunos conciertos para piano y viol\u00edn, unas pocas piezas de c\u00e1mara, la \u00f3pera <em>Sans\u00f3n y Dalila<\/em> y <em>El carnaval de los animales<\/em>, adem\u00e1s de la que hoy les propongo. Disfruten.<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/71fZhMXlGT4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Puede que les parezca una humorada, pero a veces hay que desdramatizar un poco. Y como hoy es la festividad de Todos los Santos, he pensado que esta pieza breve de Camille Saint-Sa\u00ebns, la Danza Macabra, pod\u00eda servir para ello. La m\u00fasica de Saint-Sa\u00ebns es un ejemplo de excelente acabado aunque\u00a0haya sido y a\u00fan sea [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[2413],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3487"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=3487"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3487\/revisions"}],"predecessor-version":[{"id":3489,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3487\/revisions\/3489"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=3487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=3487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=3487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}