{"id":3474,"date":"2018-10-23T10:00:48","date_gmt":"2018-10-23T08:00:48","guid":{"rendered":"https:\/\/blogs.elcorreo.com\/divergencias\/?p=3474"},"modified":"2018-10-19T19:12:54","modified_gmt":"2018-10-19T17:12:54","slug":"un-libro-cada-semana-todos-mienten-de-mindy-mejia","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2018\/10\/23\/un-libro-cada-semana-todos-mienten-de-mindy-mejia\/","title":{"rendered":"Un libro cada semana: &#8216;Todos mienten&#8217; de Mindy Mejia"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-3476\" src=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten-184x300.jpg\" alt=\"todos-mienten\" width=\"184\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten-184x300.jpg 184w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten-768x1253.jpg 768w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten-627x1024.jpg 627w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/10\/todos-mienten.jpg 2000w\" sizes=\"(max-width: 184px) 100vw, 184px\" \/><\/a>Con frecuencia, en las novelas policiales lo m\u00e1s novedoso no est\u00e1 en las tramas, sino en su desarrollo. El asesinato de una joven con vocaci\u00f3n de actriz tras haber hecho <em>Macbeth<\/em> en una funci\u00f3n escolar y el hecho de que los principales sospechosos del crimen sean su novio y el profesor con el que manten\u00eda una relaci\u00f3n no es demasiado original. Y esa es la trama de <em>Todos mienten<\/em>, de Mindy Mejia.<\/p>\n<p>Tampoco lo es que la joven fuese una estupenda actriz fuera de las tablas, una manipuladora de gran nivel. Y ni siquiera es demasiado inusual que <strong>la novela est\u00e9 narrada en primera persona por tres personajes distintos<\/strong>: la joven, su profesor y el sheriff de la localidad, que debe investigar lo sucedido.<\/p>\n<p>Sin embargo, Mejia consigue atraer al lector con <strong>un relato \u00e1gil, en el que nada sobra<\/strong> y en el que lector es conducido hasta un final que, sin llegar al nivel de sorpresa habitual en los textos de <a href=\"https:\/\/www.elcorreo.com\/bizkaia\/culturas\/libros\/201411\/01\/vestido-novia-pierre-lemaitre-20141028195214.html\" rel=\"external nofollow\">Lemaitre<\/a>, tiene un par de quiebros que resultan atractivos.<\/p>\n<p>Por supuesto, como sucede en tantas novelas de hoy, <em>Todos mienten<\/em> se prestar\u00eda, sin demasiados cambios, a un tratamiento cinematogr\u00e1fico o televisivo. Y as\u00ed ha sucedido tambi\u00e9n con las referencias que la autora ha manejado \u2013y que los editores no obvian en la promoci\u00f3n\u2013 sin duda alguna para su relato.<\/p>\n<p><em>(Publicado en elcorreo.com)<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Con frecuencia, en las novelas policiales lo m\u00e1s novedoso no est\u00e1 en las tramas, sino en su desarrollo. El asesinato de una joven con vocaci\u00f3n de actriz tras haber hecho Macbeth en una funci\u00f3n escolar y el hecho de que los principales sospechosos del crimen sean su novio y el profesor con el que manten\u00eda [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[2770,2769,2368,2768],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3474"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=3474"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3474\/revisions"}],"predecessor-version":[{"id":3477,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3474\/revisions\/3477"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=3474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=3474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=3474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}