{"id":3357,"date":"2018-07-31T10:00:34","date_gmt":"2018-07-31T08:00:34","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=3357"},"modified":"2018-07-04T20:34:57","modified_gmt":"2018-07-04T18:34:57","slug":"un-libro-cada-semana-lejos-del-corazon-de-lorenzo-silva","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2018\/07\/31\/un-libro-cada-semana-lejos-del-corazon-de-lorenzo-silva\/","title":{"rendered":"Un libro cada semana: &#8216;Lejos del coraz\u00f3n&#8217; de Lorenzo Silva"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-3358\" src=\"\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n-175x300.jpg\" alt=\"lejos-del-corazon\" width=\"175\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n-175x300.jpg 175w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n-768x1318.jpg 768w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n-597x1024.jpg 597w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2018\/07\/lejos-del-coraz\u00f3n.jpg 2000w\" sizes=\"(max-width: 175px) 100vw, 175px\" \/><\/a>La serie de Bevilacqua y Chamorro cumple veinte a\u00f1os. Eso permite asegurar que<strong> la moda de la novela negra en Espa\u00f1a no es cosa reciente<\/strong>, como a veces se apunta a la ligera. Silva, Gim\u00e9nez Bartlett y algunos otros llevan d\u00e9cadas escribiendo, por no hablar de las primeras entregas de Pepe Carvalho o, a\u00fan m\u00e1s atr\u00e1s, las viejas novelas de Francisco Garc\u00eda Pav\u00f3n, que public\u00f3 las historias de Plinio, aquel peculiar jefe de la polic\u00eda municipal de Tomelloso, desde los a\u00f1os cincuenta.<\/p>\n<p>En <em>Lejos del coraz\u00f3n<\/em>, Silva desplaza a sus dos guardias civiles al Campo de Gibraltar para que<strong> investiguen la desaparici\u00f3n del joven due\u00f1o de una exitosa empresa de inform\u00e1tica que ha sido secuestrado.<\/strong> Por los datos disponibles, el autor ha sido alguien que conoc\u00eda muy bien a la v\u00edctima, hasta el punto de pedir como rescate una elevada cantidad de dinero que justamente esos d\u00edas ten\u00eda en su casa el secuestrado.<\/p>\n<p>Bevilacqua y Chamorro descubren r\u00e1pidamente que <strong>el joven se hab\u00eda mezclado con una red de traficantes de drogas a cuenta del blanqueo de dinero y el manejo de ingentes cantidades de euros mediante criptomonedas.<\/strong> Ello le sirve a Silva para adentrarse en el peligroso entorno de los negocios en la zona, con algunas impagables escenas en las que los guardias civiles que van a detener a peligrosos delincuentes son atacados por los vecinos del barrio.<\/p>\n<p>La novela narra tambi\u00e9n el reencuentro de viejos amigos y se detiene en <strong>la soledad que, cada vez de manera m\u00e1s notable, va arrinconando a sus dos protagonistas<\/strong>. El tiempo, que pasa para todos.<\/p>\n<p>&nbsp;<\/p>\n<p><em>(Publicado en elcorreo.com)<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; La serie de Bevilacqua y Chamorro cumple veinte a\u00f1os. Eso permite asegurar que la moda de la novela negra en Espa\u00f1a no es cosa reciente, como a veces se apunta a la ligera. Silva, Gim\u00e9nez Bartlett y algunos otros llevan d\u00e9cadas escribiendo, por no hablar de las primeras entregas de Pepe Carvalho o, a\u00fan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[2739,2738,2740],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3357"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=3357"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3357\/revisions"}],"predecessor-version":[{"id":3359,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/3357\/revisions\/3359"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=3357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=3357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=3357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}