{"id":2937,"date":"2017-10-05T12:00:13","date_gmt":"2017-10-05T10:00:13","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=2937"},"modified":"2017-10-02T21:08:24","modified_gmt":"2017-10-02T19:08:24","slug":"ningun-fin-de-semana-sin-musica-concierto-para-violonchelo-y-orquesta-de-lalo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2017\/10\/05\/ningun-fin-de-semana-sin-musica-concierto-para-violonchelo-y-orquesta-de-lalo\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: Concierto para violonchelo y orquesta de Lalo"},"content":{"rendered":"<p>Edouard <a href=\"http:\/\/www.hagaselamusica.com\/ficha-compositores\/romanticismo\/lalo-douard\/\" rel=\"external nofollow\">Lalo<\/a> est\u00e1 situado cronol\u00f3gicamente entre Berlioz y Saint-Sa\u00ebns, es decir, en la mitad de la gran corriente de la m\u00fasica francesa previa al impresionismo. <strong>No se sabe con certeza si ten\u00eda origen espa\u00f1ol<\/strong>, aunque <strong>es seguro que nunca visit\u00f3 Espa\u00f1a<\/strong>, lo que no obsta para que manifestara un<strong> gran inter\u00e9s por el folclore hispano<\/strong>, que entonces era visto en Europa tan ex\u00f3tico como el oriental. Tambi\u00e9n mantuvo una entra\u00f1able amistad con Pablo Sarasate, para quien escribi\u00f3 su obra m\u00e1s c\u00e9lebre: la <em>Sinfon\u00eda espa\u00f1ola<\/em>, un verdadero concierto para viol\u00edn pese a su t\u00edtulo.<\/p>\n<p>Admirador de Wagner, Lalo ten\u00eda un gran dominio de la orquesta e imprime a <strong>su m\u00fasica una fuerza y un dramatismo notables.<\/strong> De su cat\u00e1logo es muy poco lo que se interpreta de manera habitual, al menos fuera de Francia.\u00a0De sus \u00f3peras no hay noticia en nuestros escenarios, y de sus\u00a0conciertos\u00a0instrumentales es m\u00e1s que probable que muchos buenos aficionados no conozcan m\u00e1s que uno, justamente el que hoy les propongo. El Concierto para viol\u00edn -estrenado por Sarasate- se interpreta muy poco, el denominado <em>ruso<\/em> pr\u00e1cticamente nada y el escrito para piano es un absoluto desconocido del que apenas si hay grabaciones. <strong>Solo este concierto para violonchelo figura en el repertorio<\/strong>, aunque tampoco sea el favorito entre los solistas. No obstante, ver\u00e1n que es una pieza que tiene su valor. Se lo dejo en la versi\u00f3n del<strong> violonchelista venezolano William Molina Cestari<\/strong>, que lo interpreta <strong>bajo la direcci\u00f3n de un jovenc\u00edsimo Gustavo Dudamel<\/strong>, en una m\u00edtica sala de Caracas: la Teresa Carre\u00f1o. Disfruten.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wijnBhSNTf8\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Edouard Lalo est\u00e1 situado cronol\u00f3gicamente entre Berlioz y Saint-Sa\u00ebns, es decir, en la mitad de la gran corriente de la m\u00fasica francesa previa al impresionismo. No se sabe con certeza si ten\u00eda origen espa\u00f1ol, aunque es seguro que nunca visit\u00f3 Espa\u00f1a, lo que no obsta para que manifestara un gran inter\u00e9s por el folclore hispano, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[423],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2937"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=2937"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2937\/revisions"}],"predecessor-version":[{"id":2940,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2937\/revisions\/2940"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=2937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=2937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=2937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}