{"id":2778,"date":"2017-03-27T18:18:20","date_gmt":"2017-03-27T16:18:20","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=2778"},"modified":"2017-03-27T18:18:20","modified_gmt":"2017-03-27T16:18:20","slug":"un-libro-cada-semana-a-cielo-abierto-de-antonio-iturbe","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2017\/03\/27\/un-libro-cada-semana-a-cielo-abierto-de-antonio-iturbe\/","title":{"rendered":"Un libro cada semana: &#039;A cielo abierto&#039; de Antonio Iturbe"},"content":{"rendered":"<p><a href=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-2779\" title=\"cielo abierto\" src=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto.jpg\" alt=\"\" width=\"175\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto.jpg 2000w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto-175x300.jpg 175w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto-768x1316.jpg 768w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2017\/03\/cielo-abierto-598x1024.jpg 598w\" sizes=\"(max-width: 175px) 100vw, 175px\" \/><\/a>Antonio Iturbe ha ganado el premio Biblioteca Breve con <em>A cielo abierto<\/em>, una novela en la que el lector encuentra <strong>aventura, amor, escenarios ex\u00f3ticos, pol\u00edtica, humor y drama<\/strong>.<strong> Aventura<\/strong> porque los protagonistas de la misma son el piloto y novelista <a href=\"http:\/\/www.biografiasyvidas.com\/biografia\/s\/saint__exupery.htm\" target=\"_blank\" rel=\"external nofollow\">Antoine de Saint-Exup\u00e9ry<\/a> y dos de sus amigos, embarcados todos ellos en <strong>una compa\u00f1\u00eda de aviaci\u00f3n postal en los a\u00f1os en que eso no era un trabajo sino un empe\u00f1o de alto riesgo<\/strong> con el que solo personas de una pasta muy especial se atrev\u00edan. <strong>Amor<\/strong> porque cada uno de ellos lo vive a su manera. Jean Mermoz es un mujeriego empedernido que no quiere compromiso sino episodios de una noche. Henri Guillaumet, el m\u00e1s prudente y preciso de los tres, busca una vida m\u00e1s convencional, con una compa\u00f1era que espera su regreso y que lo apoya incondicionalmente. Saint-Exup\u00e9ry, en fin, vivir\u00e1 siempre obsesionado por la primera mujer a la que am\u00f3 de verdad y que lo rechaz\u00f3 por razones que nunca logr\u00f3 explicarse.<\/p>\n<p>Hay<strong> escenarios ex\u00f3ticos<\/strong> que van de los Andes al desierto del Sahara. Hay <strong>pol\u00edtica<\/strong> porque la acci\u00f3n transcurre en un momento hist\u00f3rico en el que los totalitarismos se adue\u00f1an de Europa y Francia tiembla ante la amenaza alemana. El <strong>humor<\/strong> est\u00e1 en las locuras de los pilotos, siempre viviendo al l\u00edmite por su conciencia de que cada vez que se suben a sus fr\u00e1giles aparatos puede ser la \u00faltima. Y<strong> drama<\/strong> porque el final de los tres amigos es conocido. Iturbe se detiene sobre todo en los \u00faltimos meses de Saint-Exup\u00e9ry y logra <strong>una escena conmovedora<\/strong>, cuando el ya c\u00e9lebre escritor, de viaje en Nueva York, se tropieza por la calle con un muchacho que se gana unos centavos vendiendo cucuruchos de galleta. Ser\u00e1 \u00e9l quien inspire el personaje de <em>El principito<\/em>.<\/p>\n<p>Iturbe ha conseguido una novela que, pese a su extensi\u00f3n, se lee con gran facilidad por la tersura del estilo y porque en ella nada sobra.<\/p>\n<p><em>(Publicado en elcorreo.com)<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Antonio Iturbe ha ganado el premio Biblioteca Breve con A cielo abierto, una novela en la que el lector encuentra aventura, amor, escenarios ex\u00f3ticos, pol\u00edtica, humor y drama. Aventura porque los protagonistas de la misma son el piloto y novelista Antoine de Saint-Exup\u00e9ry y dos de sus amigos, embarcados todos ellos en una compa\u00f1\u00eda de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[2594,2595,1978],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2778"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=2778"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2778\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=2778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=2778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=2778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}