{"id":274,"date":"2007-08-16T19:11:35","date_gmt":"2007-08-16T19:11:35","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=274"},"modified":"2007-08-16T19:11:35","modified_gmt":"2007-08-16T19:11:35","slug":"fraudes-culturales","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2007\/08\/16\/fraudes-culturales\/","title":{"rendered":"Fraudes culturales"},"content":{"rendered":"<p><IMG alt=\"uffizi460_01.jpg\" src=\"\/divergencias\/files\/uffizi460_01.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"300\"><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Escribo este comentario reci\u00e9n llegado al trabajo y con una cierta dosis de enfado. Pero no me resisto a hacer este post porque <b>seguro que a ustedes les ha pasado algo parecido en alguna ocasi\u00f3n. <\/b><\/p>\n<p>Uno va por ah\u00ed, de turismo cultural, y <b>se dispone a entrar&nbsp; en ese museo en el que est\u00e1 ese cuadro<\/b> que le tiene hechizado desde que lo vio en un libro de bachillerato, en <b>esa iglesia que tiene un retablo que es la cumbre del barroco europeo<\/b>, o en <b>ese palacio en el que se encuentra la escultura<\/b> que toda la vida ha querido ver en tres dimensiones. <b>Espera la correspondiente cola<\/b> (a veces muchos minutos y hasta horas), <b>pasa por mil controles de seguridad<\/b> (arcos magn\u00e9ticos, esc\u00e1neres), <b>paga una entrada no precisamente barata<\/b> y cuando ya est\u00e1 dentro <b>comprueba que el cuadro ha sido cedido<\/b> para una exposici\u00f3n temporal, <b>el retablo<\/b> est\u00e1 cubierto por una enorme lona porque <b>lo est\u00e1n restaurando<\/b> y <b>la estatua acaban de trasladarla<\/b> a otro museo pr\u00f3ximo para enriquecer su nueva colecci\u00f3n y en su lugar han colocado algo de categor\u00eda bastante inferior. <\/p>\n<p>\u00bfSe informa de todo ello con claridad en la puerta de la iglesia, el museo o el palacio? \u00bfSe reduce el precio de la entrada por ello? Ya pueden adivinar que la respuesta es NO. <b>Esto es una verdadera plaga en todo el mundo<\/b> (un apunte: el Guggenheim Bilbao es la excepci\u00f3n a&nbsp; la norma) y los responsables de esas instituciones muestran un ol\u00edmpico desprecio hacia los visitantes-turistas a quienes tratan como manadas ignorantes a las que se puede timar impunemente. Lo dicho, un fraude. Seguro que ustedes conocen unos cuantos casos.<\/p>\n<p><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Escribo este comentario reci\u00e9n llegado al trabajo y con una cierta dosis de enfado. Pero no me resisto a hacer este post porque seguro que a ustedes les ha pasado algo parecido en alguna ocasi\u00f3n. Uno va por ah\u00ed, de turismo cultural, y se dispone a entrar&nbsp; en ese museo en el que est\u00e1 ese [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-274","post","type-post","status-publish","format-standard","hentry","category-museos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=274"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/274\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}