{"id":266,"date":"2007-07-10T18:47:39","date_gmt":"2007-07-10T18:47:39","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=266"},"modified":"2007-07-10T18:47:39","modified_gmt":"2007-07-10T18:47:39","slug":"superventas-divergentes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2007\/07\/10\/superventas-divergentes\/","title":{"rendered":"Superventas divergentes"},"content":{"rendered":"<p><IMG alt=\"Mozart_01.gif\" src=\"\/divergencias\/files\/Mozart_01.gif\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"300\"><\/p>\n<p><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Hace alg\u00fan tiempo, los compa\u00f1eros <A target=\"_blank\" href=\"http:\/\/www.blogs.elcorreo.com\/evadidos\">evadidos<\/a> hicieron una clasificaci\u00f3n con sus post m\u00e1s comentados. Ha llegado el momento de que les imitemos. Ustedes, nuestros lectores, nos han honrado en diez ocasiones con 20 o m\u00e1s comentarios. \u00bfQuieren saber cu\u00e1les han sido los temas que m\u00e1s apuntes han suscitado? Ah\u00ed van:<\/p>\n<p><b>La literatura destaca entre los temas m\u00e1s comentados<\/b>: el post titulado <i>Describir el alma femenina<\/i> ha generado 20 comentarios. La quiniela sobre el Nobel de 2005<i> <\/i>(<i>El Nobel, a punto<\/i>, el post con el que se abri\u00f3 este blog), con 22 apuntes, y dos notas sobre galardones&nbsp; (<i>Qu\u00e9 pasa con los premios literarios<\/i>) y plagios (<i>Bucay, cazado<\/i>), con 25 y 21 comentarios, completan el apartado de literatura. Aunque podr\u00edamos considerar que otro apunte sobre el periodismo como actividad y visi\u00f3n de la realidad (<i>Esos viejos periodistas<\/i>, con 25 comentarios) tambi\u00e9n entra en este cap\u00edtulo.<\/p>\n<p><b>La pol\u00e9mica de las caricaturas<\/b> de Mahoma dio pie a un comentario (<i>Religi\u00f3n y libertad creadora<\/i>) que lleva 25 apuntes. <i>Pasen y vean, es arte (2\u00aa parte)<\/i>, sobre el tema de las fotograf\u00edas consideradas blasfemas por la Iglesia, acumul\u00f3 otros 25 comentarios. <i>Un regalo para Magonia<\/i> lleva otros 20. <\/p>\n<p><b>Los dos post con m\u00e1s comentarios tratan de m\u00fasica<\/b> (\u00bfqui\u00e9n dice que la m\u00fasica no da lectores?): <i>Mozart y Arriaga: la cultura como negocio<\/i>, a prop\u00f3sito de ambas efem\u00e9rides, lleva 27 comentarios. <b>And the winner is&#8230;<\/b> <i>Va de genios<\/i>, un post que planteaba si Mozart es o no el mayor genio de la historia de la m\u00fasica. A d\u00eda de hoy lleva 79 comentarios. <\/p>\n<p>Los tienen todos en este blog, por si quieren sumar alg\u00fan comentario nuevo a estos post superventas.<\/p>\n<p><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace alg\u00fan tiempo, los compa\u00f1eros evadidos hicieron una clasificaci\u00f3n con sus post m\u00e1s comentados. Ha llegado el momento de que les imitemos. Ustedes, nuestros lectores, nos han honrado en diez ocasiones con 20 o m\u00e1s comentarios. \u00bfQuieren saber cu\u00e1les han sido los temas que m\u00e1s apuntes han suscitado? Ah\u00ed van: La literatura destaca entre los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-266","post","type-post","status-publish","format-standard","hentry","category-varios"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}