{"id":263,"date":"2007-07-04T19:48:35","date_gmt":"2007-07-04T19:48:35","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=263"},"modified":"2007-07-04T19:48:35","modified_gmt":"2007-07-04T19:48:35","slug":"padma-personaje-literario","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2007\/07\/04\/padma-personaje-literario\/","title":{"rendered":"Padma, personaje literario"},"content":{"rendered":"<p><IMG alt=\"padma_lakshmi102_01.jpg\" src=\"\/divergencias\/files\/padma_lakshmi102_01.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"250\"><\/p>\n<p><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Esto va de cotilleo cultural. El escritor<A target=\"_blank\" href=\"http:\/\/es.wikipedia.org\/wiki\/Salman_Rushdie\"> Salman Rushdie<\/a> y su esposa, la modelo y actriz <A target=\"_blank\" href=\"http:\/\/cine.linkara.com\/actor\/padma-lakshmi-2a36.html\">Padma Lakshmi<\/a>, van a <A target=\"_blank\" href=\"http:\/\/www.perfil.com\/contenidos\/2007\/07\/02\/noticia_0042.html\">divorciarse<\/a>, o lo han hecho ya. No s\u00e9 si ustedes saben que Padma se convirti\u00f3 en personaje literario en <A target=\"_blank\" href=\"http:\/\/www.opiofuturo.com\/pizotesolo\/furia.htm\"><i>Furia<\/i><\/a>, la pen\u00faltima novela del autor indio. All\u00ed <b>era una mujer de tal belleza que causaba aut\u00e9nticos estragos<\/b> a su paso. Concretamente, en una ocasi\u00f3n en la que va caminando junto a <A target=\"_blank\" href=\"http:\/\/es.wikipedia.org\/wiki\/Central_Park\">Central Park<\/a> varios coches chocan porque sus conductores se quedan mir\u00e1ndola&#8230;<\/p>\n<p>Entrevist\u00e9 a Rushdie cuando present\u00f3 el libro en Espa\u00f1a, y reconoci\u00f3 algunas <i>casualidades<\/i> entre el protagonista y \u00e9l mismo. Terminada la conversaci\u00f3n formal, confes\u00f3 que <b>esa escena del choque de coches era real<\/b>: lo hab\u00eda provocado Padma un d\u00eda que sali\u00f3 a pasear. Un aut\u00e9ntico personaje literario.<br \/><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Esto va de cotilleo cultural. El escritor Salman Rushdie y su esposa, la modelo y actriz Padma Lakshmi, van a divorciarse, o lo han hecho ya. No s\u00e9 si ustedes saben que Padma se convirti\u00f3 en personaje literario en Furia, la pen\u00faltima novela del autor indio. All\u00ed era una mujer de tal belleza que causaba [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-263","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}