{"id":2619,"date":"2016-07-29T12:00:51","date_gmt":"2016-07-29T10:00:51","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=2619"},"modified":"2016-07-29T12:00:51","modified_gmt":"2016-07-29T10:00:51","slug":"ningun-fin-de-semana-sin-musica-pavana-de-faure","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2016\/07\/29\/ningun-fin-de-semana-sin-musica-pavana-de-faure\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: &#039;Pavana&#039; de Faur\u00e9"},"content":{"rendered":"<p>La <strong>pavana<\/strong> es una <strong>danza espa\u00f1ola lenta y ceremonial<\/strong> que se bailaba en la corte durante el siglo XVI. Faur\u00e9 compuso en 1887 esta pieza inspir\u00e1ndose en esa danza. Se trata de <strong>una obra de extrema elegancia<\/strong> en todos sus aspectos y resulta muy representativa de este compositor franc\u00e9s que sirve de puente entre el Romanticismo y el Impresionismo. La partitura es muy popular y ha tenido una gran influencia: <strong>Ravel<\/strong>, siendo alumno de Faur\u00e9, escribi\u00f3 tambi\u00e9n otra pieza que bebe de la misma fuente y que igualmente consigui\u00f3 una merecida fama. Se trata de la <em>Pavana para una infanta difunta<\/em>. Y hasta Debussy echa mano de la tradici\u00f3n para una de las partes de la <em>Suite Bergamasque<\/em>.<\/p>\n<p>Faur\u00e9 la escribi\u00f3 inicialmente para una peque\u00f1a orquesta pero <strong>luego le a\u00f1adi\u00f3 un coro<\/strong> y hasta existe una versi\u00f3n coreografiada. A partir de ah\u00ed, la partitura ha sido objeto de numerosas adaptaciones, incluida alguna versi\u00f3n que bordea el pop. Disfruten de esta <em>Pavana<\/em>. Aunque sea sin bailar.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/mpgyTl8yqbw?rel=0\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La pavana es una danza espa\u00f1ola lenta y ceremonial que se bailaba en la corte durante el siglo XVI. Faur\u00e9 compuso en 1887 esta pieza inspir\u00e1ndose en esa danza. Se trata de una obra de extrema elegancia en todos sus aspectos y resulta muy representativa de este compositor franc\u00e9s que sirve de puente entre el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[602,611,893,2072],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2619"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}