{"id":2532,"date":"2016-04-01T12:00:32","date_gmt":"2016-04-01T10:00:32","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=2532"},"modified":"2016-04-01T12:00:32","modified_gmt":"2016-04-01T10:00:32","slug":"ningun-fin-de-semana-sin-musica-les-djinns-de-cesar-franck","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2016\/04\/01\/ningun-fin-de-semana-sin-musica-les-djinns-de-cesar-franck\/","title":{"rendered":"Ning\u00fan fin de semana sin m\u00fasica: &#039;Les Djinns&#039; de C\u00e9sar Franck"},"content":{"rendered":"<p>La semana pasada pens\u00e9 proponerles alguna <strong>obra de un compositor belga<\/strong>, a modo de homenaje por los atentados de Bruselas. Pero al final prefer\u00eda ce\u00f1irme a la fecha de Semana Santa y dejar para este viernes la propuesta. As\u00ed que aqu\u00ed tienen una pieza de <a href=\"http:\/\/recursos.march.es\/culturales\/documentos\/conciertos\/cc716.pdf\" target=\"_blank\" rel=\"external nofollow\">C\u00e9sar Franck<\/a>, que aunque adquiri\u00f3 la nacionalidad francesa -en principio fue para poder acceder al Conservatorio de Par\u00eds pero luego pas\u00f3 el resto de su vida en esa capital- <strong>hab\u00eda nacido en Lieja<\/strong> y all\u00ed vivi\u00f3 hasta los 13 a\u00f1os.<\/p>\n<p>Franck fue durante los treinta \u00faltimos a\u00f1os de vida <strong>organista<\/strong> en la <a href=\"http:\/\/www.sainte-clotilde.com\/v2\/\" target=\"_blank\" rel=\"external nofollow\">bas\u00edlica de Santa Clotilde<\/a>, un soberbio edificio neog\u00f3tico que se levanta entre los museos d&#8217;Orsay y Rodin. Muchas de sus obras est\u00e1n escritas para ese instrumento pero en su enorme cat\u00e1logo -poco conocido por aqu\u00ed con la excepci\u00f3n de unos pocos t\u00edtulos- hay tambi\u00e9n una serie interesante de piezas orquestales. Una de ellas es este poema sinf\u00f3nico con piano solista sobre una obra de Victor Hugo, compuesto en 1884, seis a\u00f1os antes de su muerte. Se trata de <em>Les Djinns<\/em>. Una obra de car\u00e1cter, en la que el pianista debe hacer frente a no pocas dificultades t\u00e9cnicas.<\/p>\n<p>Aqu\u00ed se la dejo en la versi\u00f3n del gran Sviatoslav Ritcher, con la Joven Orquesta Sinf\u00f3nica de Mosc\u00fa dirigida por Kirill Kondrahin. El sonido no es muy bueno, pero la interpretaci\u00f3n es fant\u00e1stica. Disfruten.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/YV0tmB17EI8?rel=0\" frameborder=\"0\" width=\"640\" height=\"360\"><\/iframe><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La semana pasada pens\u00e9 proponerles alguna obra de un compositor belga, a modo de homenaje por los atentados de Bruselas. Pero al final prefer\u00eda ce\u00f1irme a la fecha de Semana Santa y dejar para este viernes la propuesta. As\u00ed que aqu\u00ed tienen una pieza de C\u00e9sar Franck, que aunque adquiri\u00f3 la nacionalidad francesa -en principio [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,8],"tags":[255,1854],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2532"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=2532"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2532\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=2532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=2532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=2532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}