{"id":2517,"date":"2016-03-14T10:00:52","date_gmt":"2016-03-14T08:00:52","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=2517"},"modified":"2016-03-14T10:00:52","modified_gmt":"2016-03-14T08:00:52","slug":"un-libro-cada-semana-cicatriz-de-juan-gomez-jurado","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2016\/03\/14\/un-libro-cada-semana-cicatriz-de-juan-gomez-jurado\/","title":{"rendered":"Un libro cada semana: &#039;Cicatriz&#039; de Juan G\u00f3mez-Jurado"},"content":{"rendered":"<p><a href=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2016\/03\/cicatriz.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-2518\" title=\"cicatriz\" src=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2016\/03\/cicatriz.jpg\" alt=\"\" width=\"194\" height=\"300\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2016\/03\/cicatriz.jpg 272w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2016\/03\/cicatriz-194x300.jpg 194w\" sizes=\"(max-width: 194px) 100vw, 194px\" \/><\/a>En los comienzos de su carrera literaria \u2013y eso es decir anteayer, pues tiene solo 38 a\u00f1os\u2013, Juan G\u00f3mez-Jurado public\u00f3 algunas <strong>novelas ambientadas en el entorno del Vaticano<\/strong>. <em>Esp\u00eda de Dios<\/em> jugaba con el asesinato de dos cardenales justo cuando arrancaba el c\u00f3nclave para la elecci\u00f3n del sucesor de Juan Pablo II y <em>Contrato con Dios<\/em> trataba acerca de la b\u00fasqueda del Arca de la Alianza, de nuevo con agentes del Vaticano de por medio. Luego, el autor dio un giro hacia una novela de corte m\u00e1s bien hist\u00f3rico, con <em>El emblema del traidor<\/em>, que se situaba en la agitada Europa central de los a\u00f1os treinta, y <em>La leyenda del ladr\u00f3n<\/em>, relato de la peripecia vital de un p\u00edcaro en la Sevilla del siglo XVI. Un <strong>denominador com\u00fan<\/strong> en lo argumental un\u00eda esas cuatro novelas: la <strong>aventura<\/strong>. Y otro <strong>estil\u00edstico<\/strong>: la <strong>eficacia<\/strong> de una narraci\u00f3n muy visual que discurre a gran velocidad.<\/p>\n<p>En <em>El paciente<\/em>, publicada en 2014, G\u00f3mez-Jurado se fue a EE UU para contar una historia de alto riesgo: el presidente ha de ser operado del coraz\u00f3n y el cirujano que va a hacerlo se encuentra con que secuestran a su hija y el precio por recuperarla con vida es que el inquilino de la Casa Blanca muera durante la intervenci\u00f3n. En <em>Cicatriz<\/em>, G\u00f3mez-Jurado sigue en EE UU. Ahora, <strong>un joven inform\u00e1tico<\/strong> ya en la treintena est\u00e1 a punto de hacerse millonario pero debe perfeccionar un sistema de reconocimiento de im\u00e1genes mediante una aplicaci\u00f3n. Una multinacional le ha ofrecido la operaci\u00f3n que lo har\u00e1 inmensamente rico pero las condiciones hasta ese momento son de una dureza singular. En plena carrera contra el reloj, el protagonista, que tiene una notable incapacidad para relacionarse con la gente \u2013sobre todo con mujeres de su edad\u2013 conoce a trav\u00e9s de una web que selecciona a j\u00f3venes del Este de Europa con aspiraciones de situarse en Occidente a <strong>una chica ucraniana que tiene una leve cicatriz en la cara<\/strong>. El inform\u00e1tico se enamora de ella, que se va a vivir a Chicago con planes de boda para ambos.<\/p>\n<p>El problema es que la chica tiene <strong>un pasado oscuro en el que el inform\u00e1tico se ve implicado<\/strong>. Y no se puede contar m\u00e1s para no desvelar aspectos de la trama que el lector debe ir conociendo. G\u00f3mez-Jurado construye otra novela en la que a partir de estereotipos de personajes y situaciones que ya han sido tratados en la literatura y el cine \u2013un hermano del protagonista tiene s\u00edndrome Down, una circunstancia tambi\u00e9n presente en la serie <em><a href=\"http:\/\/www.antena3.com\/series\/sin-identidad\/\" target=\"_blank\" rel=\"external nofollow\">Sin identidad<\/a><\/em>, por citar solo un ejemplo\u2013 consigue<strong> enganchar por el v\u00e9rtigo de su narraci\u00f3n<\/strong>. Con un ritmo muy cinematogr\u00e1fico, que va <em>in crescendo<\/em> hasta la apoteosis final, el autor crea una trama que envuelve al lector y lo obliga a seguir leyendo. G\u00f3mez-Jurado demuestra que puede ser tan <em>americano<\/em> como el m\u00e1s estadounidense de los escritores de <em>best sellers<\/em>. Sus libros esperan una versi\u00f3n cinematogr\u00e1fica que a buen seguro van a tener.<\/p>\n<p><em>\u00a0(Publicado en elcorreo.com)<\/em><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En los comienzos de su carrera literaria \u2013y eso es decir anteayer, pues tiene solo 38 a\u00f1os\u2013, Juan G\u00f3mez-Jurado public\u00f3 algunas novelas ambientadas en el entorno del Vaticano. Esp\u00eda de Dios jugaba con el asesinato de dos cardenales justo cuando arrancaba el c\u00f3nclave para la elecci\u00f3n del sucesor de Juan Pablo II y Contrato con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15830,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[41,735,2491],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2517"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/15830"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=2517"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/2517\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=2517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=2517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=2517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}