{"id":246,"date":"2007-05-25T13:20:16","date_gmt":"2007-05-25T13:20:16","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=246"},"modified":"2007-05-25T13:20:16","modified_gmt":"2007-05-25T13:20:16","slug":"veinte-libros","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2007\/05\/25\/veinte-libros\/","title":{"rendered":"Veinte libros"},"content":{"rendered":"<p><IMG alt=\"libros_05.jpg\" src=\"\/divergencias\/files\/libros_05.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"300\"><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\">Quiz\u00e1 algunos de los lectores de este blog sepan que desde hace un par de meses Nieves Fontova (coordinadora de <i>Territorios<\/i>, el suplemento cultural de <A target=\"_blank\" href=\"http:\/\/www.elcorreo.com\">El Correo<\/a>) y el abajo firmante <b>recomendamos semanalmente un par de libros<\/b> a los oyentes de <i>Protagonistas Bizkaia<\/i>, <b>el programa que dirige Almudena Cacho<\/b> en Punto Radio Bilbao (103.7 FM). Cada jueves, a eso de las 12.35, comentamos un libro de reciente publicaci\u00f3n y un cl\u00e1sico (que a veces tiene s\u00f3lo 20 a\u00f1os). S\u00f3lo una vez nos hemos saltado la norma: fue cuando Almudena hizo el programa en Gernika para recordar el bombardeo de la villa foral.<\/p>\n<p>Pues bien, ya van 20 libros y creo que es el momento de recapitular y pedir opini\u00f3n a nuestros lectores. \u00bfQu\u00e9 les parece nuestra elecci\u00f3n? <\/p>\n<p>Estos han sido hasta ahora los libros recomendados:<\/p>\n<p>15-3-07 <i>Eleg\u00eda<\/i>, de Philip Roth<br \/><i>El amor en los tiempos del c\u00f3lera<\/i>, de Gabriel Garc\u00eda M\u00e1rquez<\/p>\n<p>22-3-07 <i>Mi vida, mi libertad<\/i>, de Ayaan Hirsi Ali<br \/><i>Madame Bovary<\/i>, de Gustave Flaubert<\/p>\n<p>29-3-07 <i>Arthur and George<\/i>, de Julian Barnes<br \/><i>El guardi\u00e1n entre el centeno<\/i>, de J. Salinger<\/p>\n<p>12-4-07 <i>Dos vidas<\/i>, de Vikram Seth<br \/><i>Los versos del Capit\u00e1n<\/i>, de Pablo Neruda<\/p>\n<p>19-4-07 <i>Humor pr\u00f3digo<\/i>, de Pedro Zarraluki<br \/><i>El viejo y el mar<\/i>, de Ernest Hemignway<\/p>\n<p>26-4-07 <i>La Rep\u00fablica y la Guerra Civil<\/i>, de Gabriel Jackson<br \/><i>El otro \u00e1rbol de Guernica<\/i>, de Luis de Castresana<\/p>\n<p>3-5-07 <i>S\u00f3niechka<\/i>, de Ludmila Ulitskaya<br \/><i>Bartleby, el escribiente<\/i>, de Herman Melville<\/p>\n<p>10-5-07 <i>Las l\u00e1grimas de Eur\u00eddice<\/i>, de Fernando Garc\u00eda Pa\u00f1eda<br \/><i>La metamorfosis<\/i>, de Franz Kafka<\/p>\n<p>17-05-07 <i>La hermana<\/i>, de Sandor M\u00e1rai<br \/><i>El aleph<\/i>, de Jorge Luis Borges<\/p>\n<p>24-05-07 <i>Mira si yo te querr\u00e9<\/i>, de Luis Leante<br \/><i>\u00daltimas tardes con Teresa<\/i>, de Juan Mars\u00e9<\/p>\n<p>Y bien, \u00bfqu\u00e9 opinan?<\/p>\n<p><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1 algunos de los lectores de este blog sepan que desde hace un par de meses Nieves Fontova (coordinadora de Territorios, el suplemento cultural de El Correo) y el abajo firmante recomendamos semanalmente un par de libros a los oyentes de Protagonistas Bizkaia, el programa que dirige Almudena Cacho en Punto Radio Bilbao (103.7 FM). [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-246","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=246"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/246\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}