{"id":237,"date":"2007-05-10T12:50:18","date_gmt":"2007-05-10T12:50:18","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=237"},"modified":"2007-05-10T12:50:18","modified_gmt":"2007-05-10T12:50:18","slug":"enzensberger-y-perdedores","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2007\/05\/10\/enzensberger-y-perdedores\/","title":{"rendered":"Enzensberger y los perdedores"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/GF0461N1.jpg\"><\/p>\n<p>\u00bfCu\u00e1l es el v\u00ednculo entre el estudiante asesino de Virginia y los<br \/>\nterroristas suicidas de Casablanca? Seg\u00fan Hans Magnus Enzensberger,<br \/>\npremio Pr\u00edncipe de Asturias en 2002, todos ellos son &#8216;perdedores<br \/>\nradicales&#8217;, gente a la que acecha el fracaso, que tiene un elevado<br \/>\nconcepto de s\u00ed mismo y busca chivos expiatorios para vengarse de la<br \/>\ninfinita injusticia del mundo. <br \/>\n&#8216;El perdedor radical&#8217; (Anagrama) de Enzensberger piensa que los dem\u00e1s<br \/>\nse la tienen jurada y quieren hacerle la vida imposible. Se siente<br \/>\nofendido, humillado y rebajado por sus compa\u00f1eros, por sus jefes, por<br \/>\nsu mujer (todav\u00eda no se han dado &#8216;serial killers&#8217; ni bombas humanas de<br \/>\nsexo femenino), por los vecinos, los inmigrantes y las multinacionales.<br \/>\nGeneralmente tambi\u00e9n le gusta el &#8216;show business&#8217;, como muestra el v\u00eddeo<br \/>\npeliculero que mand\u00f3 el estudiante de Virginia a una cadena de<br \/>\ntelevisi\u00f3n.<br \/>\nEnzensberger se pregunta qu\u00e9 sucede cuando el perdedor radical supera<br \/>\nsu aislamiento y \u00abencuentra una patria de perdedores con cuya<br \/>\ncomprensi\u00f3n e incluso reconocimiento pueda contar\u00bb. Amparado por el<br \/>\nsectarismo de su grupo ideol\u00f3gico o religioso, el tipo en cuesti\u00f3n ya<br \/>\nest\u00e1 maduro para morir por el para\u00edso llev\u00e1ndose a quien haga falta por<br \/>\ndelante. El escritor argumenta, con una fina combinaci\u00f3n de datos e<br \/>\nhistoria, que los pa\u00edses \u00e1rabes se han quedado atr\u00e1s en ideas,<br \/>\ntecnolog\u00eda y nivel de vida. Se sienten humillados por Occidente&nbsp; y<br \/>\nquieren hacerlo desaperecer. Enzensberger lo borda en 67 p\u00e1ginas.<\/p>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1l es el v\u00ednculo entre el estudiante asesino de Virginia y los terroristas suicidas de Casablanca? Seg\u00fan Hans Magnus Enzensberger, premio Pr\u00edncipe de Asturias en 2002, todos ellos son &#8216;perdedores radicales&#8217;, gente a la que acecha el fracaso, que tiene un elevado concepto de s\u00ed mismo y busca chivos expiatorios para vengarse de la infinita [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-237","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=237"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/237\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}