{"id":1674,"date":"2013-05-13T16:10:33","date_gmt":"2013-05-13T14:10:33","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=1674"},"modified":"2013-05-13T16:10:33","modified_gmt":"2013-05-13T14:10:33","slug":"un-libro-cada-semana-el-gran-gatsby-de-f-scott-fitzgerald","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2013\/05\/13\/un-libro-cada-semana-el-gran-gatsby-de-f-scott-fitzgerald\/","title":{"rendered":"Un libro cada semana: &#039;El gran Gatsby&#039; de F. Scott Fitzgerald"},"content":{"rendered":"<p><a href=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2013\/05\/el-gran-gatsby-.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1675\" title=\"el-gran-gatsby-\" src=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2013\/05\/el-gran-gatsby-.jpg\" alt=\"\" width=\"180\" height=\"300\" \/><\/a>Llega al cine la quinta versi\u00f3n cinematogr\u00e1fica de <em>El gran Gatsby<\/em> (me temo que nadie encarnar\u00e1 nunca al personaje como Robert Redford), <strong>una de las grandes novelas de la literatura estdounidense del siglo pasado<\/strong>, por no decir directamente de la literatura universal.<\/p>\n<p>Hasta la publicaci\u00f3n de <em>Hermosos y malditos<\/em> \u2013otro t\u00edtulo inolvidable\u2013, Scott Fitzgerald era un formidable escritor de cuentos que se cotizaba muy alto en las revistas de post\u00edn de la \u00e9poca. Suyo es <em>El curioso caso de Benjamin Button<\/em>, un relato magn\u00edfico y original que luego tendr\u00e1 una vuelta de tuerca en otra pieza maestra, <em>El viaje a la semilla<\/em> de Alejo Carpentier.<\/p>\n<p><strong>Francis Scott Fitzgerald protagoniz\u00f3, en su propia vida, muchos de los episodios que cuenta en sus novelas<\/strong>. Asisti\u00f3 a las fiestas interminables de aquellos locos a\u00f1os veinte, conoci\u00f3 a titulares de grandes fortunas construidas sobre el contrabando y apoyadas por el crimen organizado, cedi\u00f3 a casi todas las tentaciones, subi\u00f3 a lo m\u00e1s alto y termin\u00f3 descendiendo al infierno.<\/p>\n<p><em>El gran Gatsby<\/em>, publicada en 1925, refleja <strong>ese mundo enloquecido de noches rebosantes de alcohol (no solo), con pol\u00edticos corruptos, millonarios con secretos inconfesables, matrimonios rotos y amores desenfrenados<\/strong>. Fue all\u00ed cuando empez\u00f3 el culto a la eterna juventud, quiz\u00e1 la \u00faltima herencia de esa \u00e9poca que tanto juego literario y cinematogr\u00e1fico ha dado. Los felices a\u00f1os veinte que ocultaban tantas cosas y que a tantos llevaron al desastre. Entre ellos, el propio Scott Fitzgerald y su esposa Zelda, sumida en la locura. Su tortuosa experiencia en varios centros psiqui\u00e1tricos sirvi\u00f3 al novelista para escribir otra gran obra: <em>Suave es la noche<\/em>.<\/p>\n<p>No s\u00e9 si el filme de Baz Luhrmann ser\u00e1 bueno. La novela es excelente.<\/p>\n<p><em>(Publicado en elcorreo.com)<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Llega al cine la quinta versi\u00f3n cinematogr\u00e1fica de El gran Gatsby (me temo que nadie encarnar\u00e1 nunca al personaje como Robert Redford), una de las grandes novelas de la literatura estdounidense del siglo pasado, por no decir directamente de la literatura universal. Hasta la publicaci\u00f3n de Hermosos y malditos \u2013otro t\u00edtulo inolvidable\u2013, Scott Fitzgerald era [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,10],"tags":[243,957,1118,2146,2333],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1674"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=1674"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1674\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=1674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=1674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=1674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}