{"id":1327,"date":"2012-04-26T18:50:06","date_gmt":"2012-04-26T17:50:06","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=1327"},"modified":"2012-04-26T18:50:06","modified_gmt":"2012-04-26T17:50:06","slug":"una-entrada-para-anne-germain-12-entradas-de-cine-5-conciertos-o-4-libros","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2012\/04\/26\/una-entrada-para-anne-germain-12-entradas-de-cine-5-conciertos-o-4-libros\/","title":{"rendered":"Una entrada para Anne Germain = 12 entradas de cine, 5 conciertos o 4 libros"},"content":{"rendered":"<p>Estos d\u00edas ha estado actuando en Bilbao <strong>Anne Germain<\/strong>, una se\u00f1ora que en <a href=\"http:\/\/www.annegermain.co.uk\/\" target=\"_blank\" rel=\"external nofollow\">su p\u00e1gina web<\/a> se presenta como <em>spiritual medium and reiki master<\/em>. Les reconozco que no s\u00e9 muy bien qu\u00e9 es ninguna de esas cosas, pero deben de ser especialidades profesionales muy notables porque <strong>la entrada al espect\u00e1culo (tampoco s\u00e9 c\u00f3mo llamarlo) costaba 80 euros<\/strong>. Han le\u00eddo bien: ochenta euros. Hay gente a la que le gusta a\u00fan hablar en pesetas as\u00ed que les pongo\u00a0 la equivalencia: 13.300 pesetas.<\/p>\n<p>No voy a juzgar lo que hace esta se\u00f1ora. Mi amigo y colega <a href=\"http:\/\/blogs.elcorreo.com\/magonia\/\" target=\"_blank\">Luis Alfonso G\u00e1mez<\/a> ya ha hablado muchas veces de estas cosas con autoridad. Les confieso, eso s\u00ed, mi escepticismo ante los videntes.<\/p>\n<p>Solo voy a plantearles un juego. <strong>\u00bfSaben ustedes cu\u00e1ntas entradas de cine se compran con 80 euros? \u00bfCu\u00e1ntos libros? \u00bfCu\u00e1ntos discos y deuved\u00e9s? \u00bfSab\u00edan que con ese dinero se saca una entrada para la \u00f3pera? \u00bfO varias entradas para conciertos, sesiones de teatro y ballet?<\/strong> Y ahora si quieren hablamos de lo que cuesta todo eso en t\u00e9rminos de creatividad y talento. <strong>Las horas de trabajo de alguien que ha de\u00a0 inventar una historia<\/strong> y darle forma; el personal necesario (orquesta, coros, solistas, director, producci\u00f3n, etc) para <strong>poner en pie una \u00f3pera<\/strong>; los m\u00fasicos muy formados, con mucho talento y muchos a\u00f1os de estudio a sus espaldas, que hacen falta para <strong>interpretar un concierto de Beethoven o una sinfon\u00eda de Brahms<\/strong>; los actores, guionistas, t\u00e9cnicos que son precisos para <strong>filmar una pel\u00edcula<\/strong>.<\/p>\n<p>Y todo es m\u00e1s barato para el espectador que asistir a una sesi\u00f3n de Anne Germain. Por favor, <strong>a partir de ahora que nadie me diga que la cultura es cara.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estos d\u00edas ha estado actuando en Bilbao Anne Germain, una se\u00f1ora que en su p\u00e1gina web se presenta como spiritual medium and reiki master. Les reconozco que no s\u00e9 muy bien qu\u00e9 es ninguna de esas cosas, pero deben de ser especialidades profesionales muy notables porque la entrada al espect\u00e1culo (tampoco s\u00e9 c\u00f3mo llamarlo) costaba [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,11],"tags":[1970,2521],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1327"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}