{"id":125,"date":"2006-06-20T15:58:56","date_gmt":"2006-06-20T15:58:56","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=124"},"modified":"2006-06-20T15:58:56","modified_gmt":"2006-06-20T15:58:56","slug":"135-millones","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/06\/20\/135-millones\/","title":{"rendered":"135 millones"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/klim.jpg\" height=\"253\" width=\"280\"><\/p>\n<p>Contemple la imagen superior. Desc\u00e1rgela en su pantalla. Impr\u00edmala.<br \/>\nAmpl\u00edela y cu\u00e9lguela en su sal\u00f3n. Conseguir\u00e1 decorar su casa con algo<br \/>\nque <A href=\"http:\/\/www.elcorreo.com\/vizcaya\/edicion\/\/prensa\/noticias\/Gente\/200606\/20\/VIZ-GEN-032.html\">cuesta 135&nbsp; millones de d\u00f3lares<\/a>. Y casi gratis.<\/p>\n<p>\u00bfVale tanto un cuadro? La idea es confusa. Una forma de entender algo<br \/>\ntan material como los 135 millones de d\u00f3lares es realizar un<br \/>\nacercamiento espiritual al trabajo del artista y a la importancia de la<br \/>\npincelada, a ese intangible que supone la obra \u00fanica. \u00a1El propio Kimt,<br \/>\ncon su propia mano, pint\u00f3 la sonrisa que ahora vemos! \u00bfY? <\/p>\n<p>Desde el punto de vista del placer art\u00edstico no existe diferencia entre<br \/>\nla copia y lo aut\u00e9ntico. Si alguien tiene una reproducci\u00f3n de Las<br \/>\nMeninas en su casa, \u00bfdejan por ello de ser una obra cumbre de la<br \/>\npintura? La diferencia se esconde en un \u00e1mbito muy sutil.<\/p>\n<p>Pero hay otra forma de entender los 135 millones. Se llama<br \/>\nespeculaci\u00f3n. Se pagan 135 millones de d\u00f3lares por Klimt como se pagan<br \/>\npor una parcela urbanizable en Marbella, por una empresa boyante de<br \/>\nSuecia o por un edificio en ruinas en Nueva York. O se tiene un Mir\u00f3 en<br \/>\nel lavabo para blanquear dinero.<\/p>\n<p>A veces las noticias de Arte deber\u00edan ir en las p\u00e1ginas de Econom\u00eda.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Contemple la imagen superior. Desc\u00e1rgela en su pantalla. Impr\u00edmala. Ampl\u00edela y cu\u00e9lguela en su sal\u00f3n. Conseguir\u00e1 decorar su casa con algo que cuesta 135&nbsp; millones de d\u00f3lares. Y casi gratis. \u00bfVale tanto un cuadro? La idea es confusa. Una forma de entender algo tan material como los 135 millones de d\u00f3lares es realizar un acercamiento [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-125","post","type-post","status-publish","format-standard","hentry","category-artes-plasticas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/125\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}