{"id":1222,"date":"2011-12-27T19:12:59","date_gmt":"2011-12-27T18:12:59","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=1222"},"modified":"2011-12-27T19:12:59","modified_gmt":"2011-12-27T18:12:59","slug":"puede-un-ministro-decir-que-no-combatira-la-pirateria","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2011\/12\/27\/puede-un-ministro-decir-que-no-combatira-la-pirateria\/","title":{"rendered":"\u00bfPuede un ministro decir que no combatir\u00e1 la pirater\u00eda?"},"content":{"rendered":"<p><a href=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2011\/12\/pirateria.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1223\" title=\"pirateria\" src=\"\/divergencias\/wp-content\/uploads\/sites\/3\/2011\/12\/pirateria.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2011\/12\/pirateria.jpg 450w, https:\/\/blogs.elcorreo.com\/divergencias\/wp-content\/uploads\/sites\/3\/2011\/12\/pirateria-300x201.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Escrib\u00eda hace poco sobre la ligereza insoportable de los comentarios en Twitter por parte de todos aquellos que pretenden ser los primeros en opinar, o los constructores de las frases breves m\u00e1s brillantes. Y seguimos. <strong>Las redes sociales est\u00e1n que arden<\/strong> porque el nuevo ministro de Educaci\u00f3n,\u00a0Cultura y Deporte, Jos\u00e9 Ignacio Wert, ha anunciado que <a href=\"http:\/\/www.elcorreo.com\/vizcaya\/v\/20111227\/cultura\/wert-promete-mano-hierro-20111227.html\" target=\"_blank\" rel=\"external nofollow\">combatir\u00e1<\/a> la pirater\u00eda.<\/p>\n<p>Pues no lo entiendo. <strong>\u00bfQu\u00e9 esperaban? \u00bfQue un ministro de un gobierno occidental dijera que la fomentar\u00e1? Puestos a ello, un ministro de Hacienda podr\u00eda recomendar atracar bancos, uno de Industria copiar patentes y, en aquellos pa\u00edses donde a\u00fan existe la mili obligatoria, uno de Defensa mostrarse partidario de la insumisi\u00f3n<\/strong>.<\/p>\n<p>Me temo que algunos no saben exactamente de qu\u00e9 van las sociedades occidentales. Pero hay m\u00e1s: <strong>\u00bfes posible \u00e9ticamente defender la pirater\u00eda?<\/strong> Llevo un tiempo en el que no dejo de leer cosas extra\u00f1as. Enrique Dans,\u00a0conocido entre otras cosas por su enorme presencia en la red dedicaba hace unos d\u00edas un <a href=\"http:\/\/www.enriquedans.com\/2011\/12\/sobre-lucia-sus-libros-y-el-camino-equivocado.html\" target=\"_blank\" rel=\"external nofollow\">post<\/a> a Luc\u00eda Etxebarria a prop\u00f3sito de su anuncio de que dejar\u00e1 de escribir porque la pirater\u00eda est\u00e1 da\u00f1ando mucho sus ventas. Ven\u00eda a decirle que todo depende de lo que quiera: dar rienda a su creatividad o vivir de ella. Bastantes de los dem\u00e1s argumentos de su art\u00edculo me sonaban bien, pero <strong>eso de\u00a0plantear a un escritor si pretende vivir de ello y quiere cobrar los derechos de autor que le pertenezcan me parece absurdo<\/strong>. Claro que quiere vivir de ello. Dans, por cierto, no dec\u00eda nada respecto de s\u00ed mismo: la entidad acad\u00e9mica en la que imparte clase tambi\u00e9n podr\u00eda decirle que si lo que quiere es crear escuela podr\u00eda trabajar gratis. Y as\u00ed en todos los empleos. <strong>Habr\u00edamos creado un modelo econ\u00f3mico distinto, pero me parece que quienes critican que se persiga la pirater\u00eda no lo pretenden<\/strong>. Al menos, no lo pretender\u00edan si les afectara tambi\u00e9n a ellos.<\/p>\n<p><strong>Un ministro debe combatir la pirater\u00eda, claro que s\u00ed. Otra cosa es que perseguirla no suponga limitar los derechos de los consumidores<\/strong>. Debe ser posible conjugar ambas actuaciones: defender a los creadores y a los ciudadanos en general. Hay pa\u00edses que lo han conseguido. Podr\u00edamos copiar lo que han hecho. Es m\u00e1s inteligente que innovar y hacer una chapuza.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Escrib\u00eda hace poco sobre la ligereza insoportable de los comentarios en Twitter por parte de todos aquellos que pretenden ser los primeros en opinar, o los constructores de las frases breves m\u00e1s brillantes. Y seguimos. Las redes sociales est\u00e1n que arden porque el nuevo ministro de Educaci\u00f3n,\u00a0Cultura y Deporte, Jos\u00e9 Ignacio Wert, ha anunciado que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[589,629,1283,1934],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1222"}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}