{"id":114,"date":"2006-05-24T18:18:45","date_gmt":"2006-05-24T18:18:45","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=113"},"modified":"2006-05-24T18:18:45","modified_gmt":"2006-05-24T18:18:45","slug":"describir-alma-femenina","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/05\/24\/describir-alma-femenina\/","title":{"rendered":"Describir el alma femenina"},"content":{"rendered":"<p><IMG alt=\"GF07F741_01.jpg\" src=\"\/divergencias\/files\/GF07F741_01.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"150\"><IMG src=\"\/divergencias\/files\/GF01NMW1_01.jpg\" align=\"left\" border=\"3\" hspace=\"5\" vspace=\"5\" width=\"150\"><\/p>\n<div align=\"justify\"><font face=\"Arial\" size=\"2\"><br \/>\nHe o\u00eddo comentar a<br \/>\nalguna escritora que <b>un hombre tiene dificultades para entrar en el<br \/>\nalma de una mujer<\/b> y describir sus sentimientos. Es una opini\u00f3n y nada<br \/>\nm\u00e1s que eso, por supuesto. No creo que exista ning\u00fan estudio sobre la<br \/>\nmateria, o si existe no lo conozco.<\/p>\n<p>Viene esto a cuento por la \u00faltima novela de <A target=\"_blank\" href=\"http:\/\/www.mvargasllosa.com\/\">Mario Vargas Llosa<\/a>, <A target=\"_blank\" href=\"http:\/\/www.cervantesvirtual.com\/noticias\/noticias.jsp\"><i>Travesuras de la ni\u00f1a mala<\/i><\/a>.<br \/>\nHe tenido la suerte de leerla cuando el libro a\u00fan no estaba en las<br \/>\nlibrer\u00edas (alguna ventaja deb\u00eda tener ser periodista;&nbsp; <A target=\"_blank\" href=\"http:\/\/www.elcorreo.com\/vizcaya\/pg060524\/prensa\/noticias\/Cultura_VIZ\/200605\/24\/VIZ-CUL-003.html\">entrevistar<\/a><br \/>\na gente interesante es otra), y <b>el personaje femenino, que es una de<br \/>\nesas mujeres con la costumbre de causar muchos problemas a quienes se<br \/>\nenamoran de ellas, es realmente extraordinario. <br \/><\/b><br \/>\nMientras le\u00eda el libro pensaba en lo que o\u00ed a esa escritora de la que<br \/>\nhablaba, sin citarla, al comienzo del post. <b>\u00bfHay que ser mujer para<br \/>\nprofundizar de verdad en el alma femenina? <\/b>Desde luego no es lo<br \/>\nmismo que escribir sobre intr\u00e9pidos investigadores o tiburones de<br \/>\nempresa. Normalmente, el escritor no es ni ha sido nunca una cosa ni<br \/>\notra, pero es probable que haya conocido a gentes con esa ocupaci\u00f3n.<br \/>\nCreo, sin embargo, que cuando se habla de plasmar el interior, los<br \/>\nsentimientos, pasiones y temores de alguien, es m\u00e1s complejo. Y debe<br \/>\nde serlo para cualquier hombre que escribe sobre una mujer y para una<br \/>\nmujer que lo hace sobre un hombre. <b>Dif\u00edcil, pero no imposible<\/b>. Y si no,<br \/>\ncabr\u00eda recordar que <A target=\"_blank\" href=\"http:\/\/es.wikipedia.org\/wiki\/Madame_Bovary\">Emma Bovary<\/a> y <A target=\"_blank\" href=\"http:\/\/www.monografias.com\/trabajos10\/anak\/anak.shtml\">Anna Karenina<\/a> fueron creadas por<br \/>\nhombres. Y que <A target=\"_blank\" href=\"http:\/\/www.bibliotecasvirtuales.com\/biblioteca\/OtrosAutoresdelaLiteraturaUniversal\/EmilyBronte\/CumbresBorrascosas\/index.asp\">Heathcliff<\/a> y <A target=\"_blank\" href=\"http:\/\/www.ctv.es\/USERS\/borobar\/ageof.htm\">Newland Archer<\/a> son personajes imaginados<br \/>\npor mujeres.<\/p>\n<p><\/font><\/div>\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>He o\u00eddo comentar a alguna escritora que un hombre tiene dificultades para entrar en el alma de una mujer y describir sus sentimientos. Es una opini\u00f3n y nada m\u00e1s que eso, por supuesto. No creo que exista ning\u00fan estudio sobre la materia, o si existe no lo conozco. Viene esto a cuento por la \u00faltima [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-114","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/114\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}