{"id":110,"date":"2006-05-15T17:17:25","date_gmt":"2006-05-15T17:17:25","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=109"},"modified":"2006-05-15T17:17:25","modified_gmt":"2006-05-15T17:17:25","slug":"chavez-ravine","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/05\/15\/chavez-ravine\/","title":{"rendered":"Chavez Ravine"},"content":{"rendered":"<p><IMG src=\"\/divergencias\/files\/Chavez.jpg\" width=\"200\"><\/p>\n<p>Tal d\u00eda como hoy, el Gobierno espa\u00f1ol se dispone a enviar <A href=\"http:\/\/www.elcorreo.com\/vizcaya\/pg060515\/actualidad\/espana\/200605\/15\/inmigracion-ilegales-vicepresidenta-ministros.html\">aviones de guerra<\/a><br \/>\nal Atl\u00e1ntico para frentar la llegada de emigrantes a Canarias. Al mismo<br \/>\ntiempo, el presidente Bush va a proponer el despliegue de la Guardia<br \/>\nNacional en <A href=\"http:\/\/www.milenio.com\/mexico\/milenio\/nota.asp?id=82733\">la frontera con M\u00e9xico<\/a><br \/>\npara evitar el paso de &#8216;ilegales&#8217;. Al final, en todos los&nbsp; sitios<br \/>\nnos comportamos como nuevos ricos que no quieren que alguien estropee<br \/>\nsu bello jard\u00edn.<\/p>\n<p>Quer\u00eda aprovechar esta coincidencia para contar una peque\u00f1a historia.<br \/>\nEn los a\u00f1os 50, los emigrantes mexicanos de Los Angeles fundaron el<br \/>\nbarrio de <A href=\"http:\/\/caot.lacitycollege.edu\/112\/FinalChavezRavine\">Chavez Ravine<\/a>.<br \/>\nSu autogesti\u00f3n fue tan eficiente que aquel lugar fue llamado el Shangri<br \/>\nLa de los pobres. Entonces el alcalde de L.A les hizo una oferta que no<br \/>\npod\u00edan rechazar. Iba a derribar su barrio, construido con chabolas de<br \/>\nmadera, para levantarles una barriada social dise\u00f1ada por los mejores<br \/>\narquitectos. Era una trampa. Lo que buscaba era echarles del terreno de<br \/>\ncualquier forma porque hab\u00eda vendido todo el valle para&nbsp; edificar<br \/>\nel estadio de beisbol de los Dodgers. Los mexicanos fueron enga\u00f1ados y<br \/>\nlos pocos que se resistieron fueron apaleados y expulsados.<\/p>\n<p><IMG src=\"\/divergencias\/files\/coliseumfirst.jpg\" width=\"200\"><\/p>\n<p>\nEsta historia tiene m\u00fasica. El \u00faltimo disco de Ry Cooder se titula<br \/>\nChavez Ravine y cuenta la vida del barrio con rumbas, corridos, jazz,<br \/>\nbaladas y un rock and roll extra\u00f1o. Y utiliza el castellano, el ingl\u00e9s<br \/>\ny el spanglish. Es un disco bello y emocionante. Para la grabaci\u00f3n,<br \/>\nCooder recuper\u00f3 a m\u00fasicos tex mex que hab\u00edan actuado en Chavez Ravine,<br \/>\ncomo Lalo Guerrero o Flaco Jim\u00e9nez, y los mezcl\u00f3 con cantantes<br \/>\nhawaianos como Bla Pahinuhi; David Hidalgo, el l\u00edder de Los Lobos;<br \/>\npianistas como Jacky Terrason y, sobre todo, la magia de su guitarra.<br \/>\n(En mi opini\u00f3n, la mejor del mundo) Puro mestizaje.<\/p>\n<p>Hablar\u00e9 de un par de canciones. En &#8216;Don&#8217;t call me red&#8217;, Ry cuenta la<br \/>\nhistoria de Frank Wilkinson, el \u00fanico funcionario de L.A que ayud\u00f3 a<br \/>\nlos mexicanos y que por ello tuvo que declarar en el comit\u00e9 de<br \/>\nactividades antiamericanas. Es un tema en el que se mezcla un<br \/>\ncontrabajo alucinado y grabaciones anticomunistas de la \u00e9poca. Al<br \/>\nfinal, la voz de Wilkinson\/Cooder nos dice: \u00abdespu\u00e9s de todo, yo<br \/>\nsobreviv\u00ed a esos bastardos\u00bb, en referencia a los pol\u00edticos y los<br \/>\nmiembros del FBI. Es una novela de Ellroy resumida en cinco minutos de<br \/>\nm\u00fasica.<\/p>\n<p>Y tambi\u00e9n adoro &#8216;3rd Base, Dodger Stadium&#8217;, una balada sublime en la<br \/>\nque un viejo mexicano que trabaja de aparcacoches en un restaurante le<br \/>\npide a una estrella de beisbol que le atienda un segundito. Le quiere<br \/>\ncontar que d\u00f3nde el juega, en la tercera base, estuvo su casa, en<br \/>\nChavez Ravine.<\/p>\n<p><IMG src=\"\/divergencias\/files\/cr_dodgers.jpg\" width=\"200\"><\/p>\n<p>\nLo que m\u00e1s me gusta es que se trata de un homenaje a los habitantes de<br \/>\nChavez Ravine hecho desde Estados Unidos. Por alguien que se siente<br \/>\nobligado a contar que a los jardineros de su finca les dieron una<br \/>\npatada en el culo y los mandaron de vuelta a casa. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tal d\u00eda como hoy, el Gobierno espa\u00f1ol se dispone a enviar aviones de guerra al Atl\u00e1ntico para frentar la llegada de emigrantes a Canarias. Al mismo tiempo, el presidente Bush va a proponer el despliegue de la Guardia Nacional en la frontera con M\u00e9xico para evitar el paso de &#8216;ilegales&#8217;. Al final, en todos los&nbsp; [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-110","post","type-post","status-publish","format-standard","hentry","category-musica"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}