{"id":104,"date":"2006-04-29T18:23:47","date_gmt":"2006-04-29T18:23:47","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/divergencias\/?p=103"},"modified":"2006-04-29T18:23:47","modified_gmt":"2006-04-29T18:23:47","slug":"una-joya-desde-italia","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/divergencias\/2006\/04\/29\/una-joya-desde-italia\/","title":{"rendered":"Una joya desde Italia"},"content":{"rendered":"<p>I\u00f1igo Dom\u00ednguez me env\u00eda desde Italia una joya sin parang\u00f3n. Se titula, -en mi traducci\u00f3n del italiano-, <u>&#8216;<A href=\"http:\/\/www.lizardedizioni.com\/scheda.asp?id=382\">Armorica<\/a>. Itinerario m\u00e1gico de Corto Malt\u00e9s en Breta\u00f1a, el pa\u00eds del mar&#8217;<\/u>, y es un libro de viajes en el que acompa\u00f1amos a <A href=\"http:\/\/www.dreamers.com\/corto\/\">Corto<\/a><br \/>\npor la Breta\u00f1a francesa. I\u00f1igo sabe que mi devoci\u00f3n hacia el marinero<br \/>\nde Malta est\u00e1 m\u00e1s all\u00e1 de cualquier elemento racional y que un regalo<br \/>\nde este tipo me causa una emoci\u00f3n que no se puede explicar con<br \/>\npalabras. Dom\u00ednguez es un t\u00edo muy grande, con un talento y un coraz\u00f3n<br \/>\nque no le caben en el cuerpo. Me muero de ganas de ver <A href=\"http:\/\/servicios.elcorreo.com\/vizcaya\/pg060428\/prensa\/noticias\/Cultura_VIZ\/200604\/28\/VIZ-CUL-009.html\">su pel\u00edcula<\/a> aunque hasta entonces habr\u00e1 que contentarse con leer sus fenomenales cr\u00f3nicas italianas.<\/p>\n<p><IMG src=\"\/divergencias\/files\/armorica.jpg\" width=\"180\"><\/p>\n<p>Empiezo a hojear el libro con la misma ansiedad con la que Long John<br \/>\nSilver contempl\u00f3 por primera vez el mapa del tesoro. En las primeras<br \/>\np\u00e1ginas veo al mago Merl\u00edn, tal y como lo imaginaba Hugo Pratt, y al<br \/>\nlado, unas vi\u00f1etas del \u00e1lbum &#8216;Las C\u00e9lticas&#8217; en las que el tutor del Rey<br \/>\nArturo charla con una rana encantada. Se trata de una gu\u00eda&nbsp; en la<br \/>\nque el hilo conductor es Corto Malt\u00e9s, as\u00ed que tiene un cap\u00edtulo<br \/>\ndedicado a los faros de Breta\u00f1a -hablando de un marino, no hab\u00eda otro<br \/>\nremedio- y unas rutas fant\u00e1sticas por los monumentos megal\u00edticos de<br \/>\nCarnac. Intuyo que Corto pudo andar por all\u00ed al mismo tiempo que<br \/>\nayudaba a los militantes del IRA a luchar contra los ingleses y tambi\u00e9n<br \/>\ncolaboraba con Merl\u00edn para acabar con los esp\u00edas alemanes que<br \/>\npreparaban la invasi\u00f3n de Gran Breta\u00f1a.<\/p>\n<p><IMG src=\"\/divergencias\/files\/corto-pratt.jpg\" height=\"187\" width=\"283\"><\/p>\n<p>En el libro hay unas pistas para llegar a Saint Malo, nido de piratas y<br \/>\ncontrabandistas, y, entre las descripciones de d\u00f3lmenes encuentro&nbsp;<br \/>\nuno llamado &#8216;La Roca de las Hadas&#8217;. Lamento desconocer el italiano y,<br \/>\npor lo tanto, no poder leer la leyenda de &#8216;Nolwenn, la santa<br \/>\ndecapitata&#8217; o la historia del bosque de Huelgoat, donde parece que<br \/>\nanduvieron el Rey Arturo y Gargant\u00faa. <\/p>\n<p>Ser\u00eda feliz recorriendo esas tierras con la gu\u00eda en la mano para poder<br \/>\nllegar a remotos bosques de druidas o a castillos de nobles normandos<br \/>\nque a\u00fan se mantienen en pie. Son unos lugares en los que uno so\u00f1ar\u00eda<br \/>\ncon cruzarse con Merl\u00edn o con alg\u00fan descendiente de corsarios. O<br \/>\nquiz\u00e1s, con el propio Corto Malt\u00e9s. Pero lo mejor ser\u00eda encontrarse con<br \/>\nI\u00f1igo Dom\u00ednguez.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>I\u00f1igo Dom\u00ednguez me env\u00eda desde Italia una joya sin parang\u00f3n. Se titula, -en mi traducci\u00f3n del italiano-, &#8216;Armorica. Itinerario m\u00e1gico de Corto Malt\u00e9s en Breta\u00f1a, el pa\u00eds del mar&#8217;, y es un libro de viajes en el que acompa\u00f1amos a Corto por la Breta\u00f1a francesa. I\u00f1igo sabe que mi devoci\u00f3n hacia el marinero de Malta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-104","post","type-post","status-publish","format-standard","hentry","category-libros"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/divergencias\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}