{"id":63,"date":"2008-04-23T13:36:00","date_gmt":"2008-04-23T13:36:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=63"},"modified":"2008-04-23T13:36:00","modified_gmt":"2008-04-23T13:36:00","slug":"el-tribunal-pau-absuelve-al-cazador-mato-la-osa","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2008\/04\/23\/el-tribunal-pau-absuelve-al-cazador-mato-la-osa\/","title":{"rendered":"El Tribunal de Pau absuelve al cazador que mat\u00f3 a la osa Cannelle"},"content":{"rendered":"<p>El pasado martes se conoci\u00f3 la noticia que Ren\u00e9 Marqu\u00e8ze, el cazador franc\u00e9s de 65 a\u00f1os que en 2004 el <strong>Tribunal Correccional de Pau<\/strong> ha absuelto al cazador que a finales de 2004 mat\u00f3 a Cannelle, la \u00faltima osa aut\u00f3ctona de los Pirineos, al considerar que el hombre dispar\u00f3 en situaci\u00f3n de necesidad. La sentencia se ajusta a la petici\u00f3n de la Fiscal\u00eda que, en el juicio del pasado mes, argument\u00f3 en todo momento que el acusado, que participaba en una batida de caza en el <strong>valle de Aspe<\/strong>, dispar\u00f3 como &#8216;\u00faltimo recurso&#8217;, despu\u00e9s de haber intentado protegerse del animal que hab\u00eda cargado contra \u00e9l.<span class=\"noticia_firmafoto_pie\"><\/span><\/p>\n<blockquote><\/blockquote>\n<table align=\"right\" border=\"0\" cellpadding=\"2\" cellspacing=\"2\" width=\"310\">\n<tbody>\n<tr>\n<td valign=\"top\">\n<div align=\"center\"><IMG src=\"\/\/www.pirineodigital.com\/2008\/noticias\/fotos\/francia\/rene-marqueze-efe-gr.jpg\" alt=\"Ren\u00e9 Marqu\u00e9ze\" class=\"noticia_imagen\" height=\"300\" width=\"300\"><\/div>\n<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td class=\"noticia_firmafoto_pie\" valign=\"top\">\n<div align=\"right\">R\u00e8ne Marqu\u00e8ze en el juicio del pasdo marzo. EFE <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"textonormal\">El cazador, Ren\u00e9 Marqu\u00e8ze, de 65 a\u00f1os, hab\u00eda sido acusado de &#8216;destrucci\u00f3n de especie protegida&#8217;, ya que se entend\u00eda que el disparo contra la osa Cannelle se pod\u00eda haber evitado, ya que el grupo de cazadores en el que iba Ren\u00e9 Marqu\u00e8ze hab\u00eda sido avisado de la presencia del plant\u00edgrado en la zona. De ah\u00ed, que la absoluci\u00f3n haya suscitado un gran malestar entre las organizaciones ecologistas, como el <strong>Fondo Mundial de la Naturaleza<\/strong>, que han denunciado el fallo del tribunal como, &#8216;un permiso para matar&#8217; y la desaparici\u00f3n en Francia del, &#8216;estatuto de especie protegida&#8217;. <\/p>\n<p class=\"textonormal\"> El juicio por la muerte de Cannelle ha sido un proceso largo  y no exento de vicisitudes. El caso lleg\u00f3 a la Audiencia de Pau a principios de 2007, pero el tribunal decidi\u00f3 archivarlo. Posteriormente, el Tribunal de Apelaci\u00f3n consider\u00f3 que el encuentro con el animal se pod\u00eda haber evitado, decidi\u00f3 anular el sobreseimiento e iniciar el proceso por v\u00eda penal, acusando a Marqu\u00e8ze de &#8216;delito de destrucci\u00f3n de una especie protegida&#8217;. Como acusaci\u00f3n particular tambi\u00e9n se presentaron hasta 19 asociaciones ecologistas francesas. <\/p>\n<p class=\"textonormal\">Adem\u00e1s de las quejas del Fondo Mundial de la Naturaleza, otras asociaciones ecologistas de Francia han reclamado, &#8216;como compensaci\u00f3n a la absoluci\u00f3n del cazador&#8217;, la reintroducci\u00f3n de  al menos dos nuevas osas en el Pirineo. La medida servir\u00eda para reforzar una poblaci\u00f3n compuesta por entre 14 y 20 ejemplares, distribuidos en dos n\u00facleos, Occidental y Oriental, y que en las \u00faltimas semanas ha tenido noticias bastante negativas con respecto al estado de salud de uno de los 4 osos aut\u00f3ctonos del Pirineo que viven en los valles m\u00e1s occidentales, <strong>Camille.<\/strong><\/p>\n<p class=\"textonormal\">La noticia se comenta por s\u00ed sola. Matar osos, en este caso osas, en Francia sale gratis.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El pasado martes se conoci\u00f3 la noticia que Ren\u00e9 Marqu\u00e8ze, el cazador franc\u00e9s de 65 a\u00f1os que en 2004 el Tribunal Correccional de Pau ha absuelto al cazador que a finales de 2004 mat\u00f3 a Cannelle, la \u00faltima osa aut\u00f3ctona de los Pirineos, al considerar que el hombre dispar\u00f3 en situaci\u00f3n de necesidad. La sentencia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":44,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,14,15,16],"tags":[30,254,276,277,737,870,934],"class_list":["post-63","post","type-post","status-publish","format-standard","hentry","category-ecologia","category-seguridad-en-montana","category-senderismo","category-sin-categoria","tag-absuelto","tag-cannelle","tag-caza","tag-cazador","tag-matar","tag-osa","tag-pirineos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=63"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/63\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=63"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=63"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}