{"id":49,"date":"2008-03-26T17:29:00","date_gmt":"2008-03-26T17:29:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=49"},"modified":"2008-03-26T17:29:00","modified_gmt":"2008-03-26T17:29:00","slug":"el-peligro-los-aludes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2008\/03\/26\/el-peligro-los-aludes\/","title":{"rendered":"El peligro de los aludes"},"content":{"rendered":"<p>La muerte de cuatro monta\u00f1eros franceses el pasado 22 de marzo, v\u00edctimas de alud cuando escalaban un couloir en el Midi de Bigorre (Pirineos) apenas ha tenido eco fuera de las fronteras de su pa\u00eds. Seg\u00fan inform\u00f3 el diario Sud-Ouest, los cuatro alpinistas, expertos y bien equipados, ascend\u00edan por un corredor helado en la vertiente NO de esta cima bearnesa cuando, no se sabe si provocada o accidental, se produjo una peque\u00f1a avalancha que arrastr\u00f3 a ambas cordadas.<br \/>\nLos equipos de rescate de Gavarnie se movilizaron casi de inmediato alertados por unos monta\u00f1eros que presenciaron el alud, peor todo fue in\u00fatil. Los cuerpos sin vida de los cuatro desafortunados deportistas, los Taupin, padre e hijo, G\u00e9rard Davon-Bournier y Bruno Ch\u00e2peau yac\u00edan al pie del corredor cubiertos por los bloques de hielo.<br \/>\nLos partes dec\u00edan que el riesgo de ca\u00edda de avalanchas fuera de pista era de 2 sobre 5. Quiz\u00e1 lo minimizaron y la monta\u00f1a nos vino a recordar de una manera cruel que incluso con riesgo 1, siempre que haya nieve, habr\u00e1 peligro.<br \/>\nQuiz\u00e1 no tanto como el que desafiaron Daniel Osambela, I\u00f1igo Zurita y Miguel \u00c1ngel Rodr\u00edguez cuando el pasado 4 de enero salieron a esquiar fuera de pista con un riesgo 4\/5. La nieve los engull\u00f3 en la zona llamada Garmo La  Mina de Formigal.<br \/>\nLas avalanchas acechan a los  imprudentes, a los confiados, a los previsores y a los muy expertos, a todos por igual. Nunca est\u00e1 de m\u00e1s extremar las precauciones y si hay alguna duda, lo m\u00e1s prudente es no salir a la monta\u00f1a.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La muerte de cuatro monta\u00f1eros franceses el pasado 22 de marzo, v\u00edctimas de alud cuando escalaban un couloir en el Midi de Bigorre (Pirineos) apenas ha tenido eco fuera de las fronteras de su pa\u00eds. Seg\u00fan inform\u00f3 el diario Sud-Ouest, los cuatro alpinistas, expertos y bien equipados, ascend\u00edan por un corredor helado en la vertiente [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":44,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,14,16],"tags":[73,142,323,468,493],"class_list":["post-49","post","type-post","status-publish","format-standard","hentry","category-esqui","category-seguridad-en-montana","category-sin-categoria","tag-alud","tag-avalancha","tag-couloir","tag-formigal","tag-gavarnie"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}