{"id":286,"date":"2010-02-09T05:40:00","date_gmt":"2010-02-09T05:40:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=286"},"modified":"2010-02-09T05:40:00","modified_gmt":"2010-02-09T05:40:00","slug":"los-clubes-mello-y-ganzabal-traen-bizkaia-mejor-del","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2010\/02\/09\/los-clubes-mello-y-ganzabal-traen-bizkaia-mejor-del\/","title":{"rendered":"Los clubes Mello y Ganzabal traen a Bizkaia lo mejor del alpinismo y la aventura"},"content":{"rendered":"<p>Es m\u00e1s que de agradecer que en los tiempos que corren, dos modestos clubes de monta\u00f1a como el <A href=\"http:\/\/www.clubmello.org\/\" title=\"http:\/\/www.clubmello.org\/\" id=\"link_0\">Mello (Muskiz)<\/a>  y el <A href=\"http:\/\/ganzabalmt.org\/inicio.htm\" title=\"http:\/\/ganzabalmt.org\/inicio.htm\" id=\"link_1\">Ganzabal (Lemoa)<\/a>  acerquen hasta Bizkaia a algunos de los mejores escaladores y aventureros del planeta. S\u00e9 de primera mano que el esfuerzo que han hecho es considerable, as\u00ed que espero que el p\u00fablico responda a esa incansable labor de promoci\u00f3n del alpinismo que desarrollan desde hace a\u00f1os.<\/p>\n<p>En el caso del Club de Monta\u00f1a <IMG src=\"\/basabide\/files\/Carteljornadasmonta%C3%B1erasMuskiz.jpg\" id=\"img_0\" class=\"imgdcha\">Mello de Muskiz, la relaci\u00f3n de alpinistas que han tra\u00eddo con motivo de sus quintas Jornada de Monta\u00f1a que comienzan hoy mismo dif\u00edcilmente se podr\u00e1 volver a ver. al frente de ellos destaca Simone Moro. El italiano es uno de los referentes actuales del alpinismo de vanguardia y ha reverdecido el himalayismo invernal con sus ascensiones en enero al Shisha Pangma y Malaku, las primeras de la historia. Edurne Pasaban, por su parte, creo que no necesita presentaciones. La alpinista vasca -y espa\u00f1ola- m\u00e1s mediatica que pugna por ser la primera mujer en ascender los catorce ochomiles. Y sobre ese sue\u00f1o versar\u00e1 su proyecci\u00f3n.<\/p>\n<p> Jos\u00e9 Carlos Tamayo, Roberto Rojo &#8216;Gorri&#8217; y Mikel Zabalza conforman la representaci\u00f3n del alpinismo vasco-navarro. El sestaotarra ofrecer\u00e1 una proyecci\u00f3n sobre el Karakorum, el alav\u00e9s relatar\u00e1 su ascensi\u00f3n al Nanga Parbat, mientras que el navarro mostrar\u00e1 sus incre\u00edbles v\u00edas abiertas en Pirineos y Alpes. El catal\u00e1n Ferr\u00e1n Latorre ofrecer\u00e1 un audiovisual que muestra su evoluci\u00f3n como alpinista y como persona, desde que comenz\u00f3 en la escala deportiva hasta convertirse en un consumado ochomilista, mientras que Julian De Miguel ser\u00e1 el representante local hablando de Sudam\u00e9rica. Las proyecciones tendr\u00e1n lugar en Gaztegunea (Edificio Meatzari) o en el Meatzari Aretoa de Muskiz a las 19:30.<\/p>\n<p>El cartel del Ganzabal es un poco m\u00e1s corto, pero no menos selecto. Repetir\u00e1n Simone Moro y Ferr\u00e1n Latorre, a los que se suman la alpinista y aventurera gallega Chus Lago, que adem\u00e1s de ser la primera espa\u00f1ola, y hasta ahora \u00fanica, que ascendi\u00f3 el Everest sin ox\u00edgeno artificial, el a\u00f1o pasado se convirti\u00f3 en la primera mujer en llegar al polo sur en solitario y sin ayuda externa. Finalmente el miembro m\u00e1s ilustre del club, Alex Txikon, cerrar\u00e1 como es habitual las jornadas con la proyecci\u00f3n sobre su \u00faltyimo ochomil, el Kangchenjunga, donde vivi\u00f3 un dram\u00e1tico descenso con Edurne Pasaban. Todas las proyecciones ser\u00e1n en el Lasarte Aretoa de Igorre a partir de las 20.00 horas.<\/p>\n<p>Y si alguna pega habr\u00eda que ponerles a ambos clubes ser\u00eda unicamente que la pr\u00f3xima vez tengan un poquito m\u00e1s de cuidado al elaborar los carteles para evitar coincidencias como que el viernes 19 coincidan Simone Moro (Muskiz) y Chus Lago (Igorre) o justo una semana despu\u00e9s, el d\u00eda 26, suceda lo mismo con Edurne Pasaban (Muskiz) y Alex Txikon (Igorre). <\/p>\n<p><IMG src=\"\/basabide\/files\/193908_mendiamesgarriak2010-kartelafoto.jpg\" id=\"img_2\" class=\"imgcen\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es m\u00e1s que de agradecer que en los tiempos que corren, dos modestos clubes de monta\u00f1a como el Mello (Muskiz) y el Ganzabal (Lemoa) acerquen hasta Bizkaia a algunos de los mejores escaladores y aventureros del planeta. S\u00e9 de primera mano que el esfuerzo que han hecho es considerable, as\u00ed que espero que el p\u00fablico [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,6,8,13,16],"tags":[260,514,659,761,791,905,957,1014,1063,1093,1145,1208],"class_list":["post-286","post","type-post","status-publish","format-standard","hentry","category-alpinismo","category-aventura","category-clubes-de-montana-y-actividades","category-escalada","category-ochomiles","category-sin-categoria","tag-carlos","tag-gorri","tag-lagoalex","tag-miguelchus","tag-moroedurne","tag-pasabanjose","tag-proyecciones","tag-rojojulian","tag-simone","tag-tamayomikel","tag-txikon","tag-zabalzaroberto"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}