{"id":257,"date":"2009-10-04T20:26:00","date_gmt":"2009-10-04T20:26:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=257"},"modified":"2009-10-04T20:26:00","modified_gmt":"2009-10-04T20:26:00","slug":"la-coreana-miss-oh-se-retira-del-annapurna-el-mal-tiempo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2009\/10\/04\/la-coreana-miss-oh-se-retira-del-annapurna-el-mal-tiempo\/","title":{"rendered":"La coreana Miss Oh se retira del Annapurna por el mal tiempo"},"content":{"rendered":"<p><IMG src=\"\/basabide\/files\/MissOh.jpg\" id=\"img_0\" class=\"imgcen\">La alpinista coreana Oh Eun-Sun se retir\u00f3 el s\u00e1bado de su intento de alcanzar la cumbre del Annapurna, la \u00faltima monta\u00f1a que le queda para convertirse en la primera mujer en ascender los catorce ochomiles, seg\u00fan informa en <A href=\"http:\/\/oes.chosun.com\/\" title=\"http:\/\/oes.chosun.com\/\" id=\"link_0\">su p\u00e1gina web<\/a> . Miss Oh abort\u00f3 el ataque a cumbre en el campo 3, a 7.400 metros, debido a &#8220;las malas condiciones meteorol\u00f3gicas&#8221;. Con ella ascend\u00eda su compatriota <font class=\"newstext\">Kim Jae-Soo, compa\u00f1ero habitual de Go Eun-Sun, la otra alpinista coreana que tambi\u00e9n intentaba completar los catorce ochomiles y que falleci\u00f3 el pasado mes de junio en el Nanga Parbat, y a la que pretend\u00eda dedicar esta ascensi\u00f3n.<\/p>\n<p>Ambos descansan ya en el campo base. Al parecer, a <\/span><font class=\"newstext\">Kim Jae-Soo no le quedan muchas ganas de volver a intentarlo y probablemente desmantele sus campamentos e inicie el regreso a casa. Por el contrario, Oh Eun-Sun ha decidido esperar en el CB a que el tiempo mejore para realizar un nuevo intento.<\/p>\n<p>Ese temporal que se abati\u00f3 el s\u00e1bado sobre el Annapurna es el que azota el Everest, y el resto del Himalaya, desde el pasado viernes y que mantiene parados en el CB de la cara norte a Alberto I\u00f1urrategi, Juan Vallejo y Mikel Zabalza, donde a la espera del buen tiempo matan el tiempo a base de <\/span><A href=\"http:\/\/www.basqueteam.com\/hornbein09\/BLOG\/tabid\/178\/articleType\/ArticleView\/articleId\/54\/Tiempo-desapacible-tiempo-de-lectura-y-mus.aspx\" title=\"http:\/\/www.basqueteam.com\/hornbein09\/BLOG\/tabid\/178\/articleType\/ArticleView\/articleId\/54\/Tiempo-desapacible-tiempo-de-lectura-y-mus.aspx\" id=\"link_1\">lectura, sudokus y mus<\/a><font class=\"newstext\">. En parecida situaci\u00f3n se encuentran <\/span><A href=\"http:\/\/www.edurnepasaban.com\/web\/guest\/home\" title=\"http:\/\/www.edurnepasaban.com\/web\/guest\/home\" id=\"link_2\">Edurne Pasaban<\/a> <font class=\"newstext\"> y su grupo en la cara suroeste del Shisha Pangma. Sin embargo, la espera empieza a tornarse un poco tensa ya que el tiempo se acaba al aproximarse el final de la corta temporada postmonz\u00f3nica en el Himalaya. Seg\u00fan la experiencia acumulada por los alpinistas de otros a\u00f1os, entre el 10 y el 15 de octubre entran los fuertes vientos que azotan la cordillera a partir de los 6.500\/7.000 metros, pre\u00e1mbulo de la llegada de las fuertes nevadas invernales y que en todo caso les impiden ya toda incursi\u00f3n en las monta\u00f1as.<br \/>\n<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La alpinista coreana Oh Eun-Sun se retir\u00f3 el s\u00e1bado de su intento de alcanzar la cumbre del Annapurna, la \u00faltima monta\u00f1a que le queda para convertirse en la primera mujer en ascender los catorce ochomiles, seg\u00fan informa en su p\u00e1gina web . Miss Oh abort\u00f3 el ataque a cumbre en el campo 3, a 7.400 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,13,16],"tags":[89,442],"class_list":["post-257","post","type-post","status-publish","format-standard","hentry","category-alpinismo","category-ochomiles","category-sin-categoria","tag-annapurna","tag-everest"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/257\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}