{"id":224,"date":"2009-07-28T00:41:00","date_gmt":"2009-07-28T00:41:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=224"},"modified":"2009-07-28T00:41:00","modified_gmt":"2009-07-28T00:41:00","slug":"el-finlandes-veikka-gustafsson-tambien-completa-14-ochomiles","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2009\/07\/28\/el-finlandes-veikka-gustafsson-tambien-completa-14-ochomiles\/","title":{"rendered":"El finland\u00e9s Veikka Gustafsson tambi\u00e9n completa los 14 ochomiles"},"content":{"rendered":"<p><IMG src=\"\/basabide\/wp-content\/uploads\/sites\/31\" id=\"img_1\" class=\"imgcen\">Ya son diecisiete. El \u00faltimo en sumarse a la lista de alpinistas que han ascendido los 14 ochomiles del planeta es el finland\u00e9s Veikka Gustafsson (41 a\u00f1os). Aunque conviene matizar, atendiendo a la recomendaci\u00f3n de los m\u00e1s puristas, que si bien en la lista completa es el 17\u00ba, Veikka es el noveno escalador que los sube sin la ayuda de ox\u00edgeno artificial, tras <font face=\"verdana, helvetica, arial\" size=\"2\">Reinhold Messner, Erhard Loretan, Juanito Oiarzabal, Alberto I\u00f1urrategi, Ed Viesturs, Silvio Mondinelli, Iv\u00e1n Vallejo y Denis Urubko. En 1993 ascendi\u00f3 el Everest con la ayuda de botellas de ox\u00edgeno (fue adem\u00e1s su primer ochomil), pero en 1997 lo volvi\u00f3 a subir, esta vez sin ellas. <\/p>\n<p>Su \u00faltimo ochomil ha sido el Gasherbrum I y lo logr\u00f3 el pasado domingo en compa\u00f1\u00eda de<font face=\"verdana, helvetica, arial\" size=\"2\">l japon\u00e9s Kazuya Hiraide  y cuatro miembros de una expedici\u00f3n b\u00falgara (<font class=\"newstext\">Nikolay Petkov, Doychin Boyanov, Boyan Petrov and Nikolay Valkov)<font face=\"verdana, helvetica, arial\" size=\"2\">, seg\u00fan informa <A href=\"http:\/\/www.mounteverest.net\/news.php?id=18539\" title=\"http:\/\/www.mounteverest.net\/news.php?id=18539\" id=\"link_0\">www. mountEverest.net<\/a> <font face=\"verdana, helvetica, arial\" size=\"2\">. Estas seis cumbres suponen, adem\u00e1s, las primeras de la temporada en el Gasherbrum m\u00e1s alto (8.065 m.)<\/p>\n<p>Los ochomiles de Gustafsson son los siguientes:<IMG src=\"\/basabide\/wp-content\/uploads\/sites\/31\" id=\"img_0\" class=\"imgdcha\"><br \/>\n<font face=\"verdana, helvetica, arial\" size=\"2\"><br \/>\n<font face=\"verdana, helvetica, arial\" size=\"2\">Everest (8848 m), 1993 (con ox\u00edgeno)<br \/>\nDhaulagiri (8167 m), 1993<br \/>\nK2 (8611 m), 1994<br \/>\nLhotse (8501 m), 1995<br \/>\nMakalu (8483 m), 1995<br \/>\nEverest (8848 m), 1997 (sin ox\u00edgeno)<br \/>\nManaslu (8163 m), 1999<br \/>\nDhaulagiri (8167 m), 1999<br \/>\nShisha Pangma (8046 m), 2001<br \/>\nNanga Parbat (8125 m), 2001<br \/>\nEverest (8848 m), 2004 <font face=\"verdana, helvetica, arial\" size=\"2\"> (con ox\u00edgeno)<br \/>\n<font face=\"verdana, helvetica, arial\" size=\"2\">Cho Oyu (8201 m), 2005<br \/>\nAnnapurna (8091 m), 2005<br \/>\nKanchenjunga (8586 m), 2006<br \/>\nGasherbrum II (8035 m), 2008<br \/>\nBroad Peak (8047 m), 2008<br \/>\nGasherbrum I (8080 m),  2009<br \/>\n<font face=\"verdana, helvetica, arial\" size=\"2\"><br \/>\nGustafsson es el tercer alpinista que este a\u00f1o concluye la carrera de Los Catorce, tras Denis Urubko y Ralf Dujmovits. Y puede no ser el \u00faltimo, ya que hay varios escaladores con 13 ochomiles y todav\u00eda queda la temporada de oto\u00f1o en los ochomiles nepal\u00edes. Es el caso del portugu\u00e9s Joao Garcia, que hace unos d\u00edas ascendi\u00f3 el Nanga Parbat (su 13\u00ba ochomil) y ya ha anunciado que en oto\u00f1o se ir\u00e1 al Annapurna para acabar su particular carrera.<\/p>\n<p>Aunque se anunciaba \u00e9ste como un fin de semana de cima en los ochomiles del Karakorum, al final s\u00f3lo la cumbre del GI ha recibido visitas. En el GII nadie ha pasado del C-II (como explican dram\u00e1ticamente las sobrinas de Luis Barbero en el post en el que relatamos su desaparici\u00f3n a \u00e9l), en el Broad Peak un miembro de una expedici\u00f3n catalana ha llegado a su antecima, y en el K2 las cosas a\u00fan van despacio. Ninguna expedici\u00f3n han llegado a\u00fan al C-IV y todas han  vuelto al CB al no confirmarse las predicciones de tiempo del fin de semana.  La monta\u00f1a sigue muy cargada den ueve en su tramo superior y la ruta hastal a cumbre  en el cuello de Botella se ve tan complicada que  Gerlinde Kantelbrunner y sus compa\u00f1eros de expedici\u00f3n, que intentan subir por la v\u00eda Cessen, han decidido buscar una ruta alternativa que evite ese complicado y peligroso paso.  <\/p>\n<p>Mientras tanto, en el CB del GI y GII se aguarda la llegada de la coreana Ms. Oh, que finalmente ha decidido realizar el tramo final de aproximaci\u00f3n a pie, aunque su equipo est\u00e1 ya en el CB tras haber sido trasladado en helic\u00f3ptero.<\/p>\n<p> <\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya son diecisiete. El \u00faltimo en sumarse a la lista de alpinistas que han ascendido los 14 ochomiles del planeta es el finland\u00e9s Veikka Gustafsson (41 a\u00f1os). Aunque conviene matizar, atendiendo a la recomendaci\u00f3n de los m\u00e1s puristas, que si bien en la lista completa es el 17\u00ba, Veikka es el noveno escalador que los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":43,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,16],"tags":[],"class_list":["post-224","post","type-post","status-publish","format-standard","hentry","category-ochomiles","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=224"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/224\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}