{"id":184,"date":"2009-03-22T23:01:00","date_gmt":"2009-03-22T23:01:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/basabide\/?p=184"},"modified":"2009-03-22T23:01:00","modified_gmt":"2009-03-22T23:01:00","slug":"el-parque-picos-europa-peligro","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/basabide\/2009\/03\/22\/el-parque-picos-europa-peligro\/","title":{"rendered":"El Parque de Picos de Europa en peligro"},"content":{"rendered":"<p><IMG class=imgdcha id=img_0 src=\"\/basabide\/wp-content\/uploads\/sites\/31\">Recojo en este blog, por su inter\u00e9s, una noticia que aparece en la p\u00e1gina desnivel.com y aunque parece alarmista, no dice m\u00e1s que la verdad. Con el t\u00edtulo de <STRONG>\u2018El Parque se divide\u2019 <\/STRONG>nos informa de la<br \/>\nfirma de un convenio de colaboraci\u00f3n entre <STRONG>Asturias, Cantabria y Castilla y Le\u00f3n <\/STRONG>para la \u2018supuesta gesti\u00f3n coordinada\u2019 de este espacio, lo que implica su desmembraci\u00f3n en tres partes, con un director propio para cada una de ellas. Tras el convenio se reelaborar\u00e1 toda su legislaci\u00f3n, siendo de temer una rebaja en su protecci\u00f3n.<\/p>\n<p>En realidad es una carta abierta de <STRONG>Avelino C\u00e1rcaba<\/STRONG>, del <STRONG>Colectivo Monta\u00f1ero por la defensa de los Picos de Europa.<\/STRONG><br \/>\n\u201cEl pasado 9 de marzo se ha firmado por los tres presidentes Aut\u00f3nomos el Convenio de Colaboraci\u00f3n entre Asturias, Cantabria y Castilla y Le\u00f3n para la gesti\u00f3n coordinada del <STRONG>Parque Nacional de los Picos de E<\/STRONG>uropa. Un convenio muy criticable porque implica, en la pr\u00e1ctica, la disgregaci\u00f3n de este parque nacional en tres partes<br \/>\nLos aspectos puntuales de este texto que son rechazables son los siguientes:<br \/>\n1\u00ba) Mediante este Convenio estas comunidades aut\u00f3nomas pretenden elaborar, de nuevo, el PORNPE, el PRUG y el Plan de Desarrollo Sostenible, lo que implica, otra vez, volver a empezar, dejando en bald\u00edo todos los a\u00f1os empleados para que Picos tuviese una legislaci\u00f3n para su protecci\u00f3n. Ello, adem\u00e1s, es preocupante porque, ahora puede significar que cada comunidad tenga m\u00e1s facilidad para rebajar las limitaciones proteccionistas. Eso no es un temor infundado, pues esa es la pretensi\u00f3n hist\u00f3rica de alguna autonom\u00eda. El caso de la caza en Le\u00f3n es un ejemplo.<br \/>\n2\u00ba) La intervenci\u00f3n del Estado Central desaparece, por completo. No hay la m\u00e1s m\u00ednima menci\u00f3n a \u00e9l en ninguno de los nuevos \u00f3rganos de gesti\u00f3n. Con ello, su capacidad de intermediaci\u00f3n ante desacuerdos entre las autonom\u00edas se esfuma.<br \/>\n3\u00ba) En este Convenio se establece el derecho al veto de las autonom\u00edas para actuaciones que afecten en exclusiva a su porci\u00f3n del parque nacional. \u00bfQu\u00e9 posibilidades quedan, entonces, para eliminar actuaciones indeseadas?.<br \/>\n4\u00ba) Se nombrar\u00e1 un director exclusivo para cada sector del parque. Aunque se hable de un director y co-directores, la realidad es que una direcci\u00f3n general no se ve por ning\u00fan lado, pues esa direcci\u00f3n lo es solo a los efectos de representaci\u00f3n externa del parque y de forma rotatoria. Por tanto, cada cual dirigir\u00e1 su parte de manera independiente del resto.<br \/>\nHay que recordar que estos planteamientos son, exactamente, los que postulaban quienes se opusieron, desde el principio, a la declaraci\u00f3n de los tres macizos como parque nacional. Ese es el caso de Castilla y Le\u00f3n que recurri\u00f3 en 1994 el PORNPE ante el Tribunal Constitucional, defendi\u00f3 siempre la caza en su territorio, repudi\u00f3 desde el principio que el <STRONG>Estado Central <\/STRONG>tuviese intervenci\u00f3n en su \u00e1rea y mantiene desde hace a\u00f1os que deber\u00eda haber tres directores en este parque.<br \/>\nTodas las razones anteriores se manten\u00edan con el \u00fanico deseo de poder rebajar la protecci\u00f3n de este espacio natural. Por lo tanto, ahora ha mantenido su postura para aceptar firmar este convenio. Las otras dos autonom\u00edas, sin la presencia, ahora, del Estado Central han aceptado, sin reparos sus condiciones.<br \/>\nEn conclusi\u00f3n, se puede decir que hemos ido hacia la peor de las posibilidades. El parque rebajar\u00e1 su protecci\u00f3n y la gesti\u00f3n ir\u00e1 cada una por su lado: el parque nacional como unidad de gesti\u00f3n habr\u00e1 desaparecido\u201d.<br \/>\nM\u00e1s claro agua. El parque deja de ser Nacional y se convierte en regional, local&#8230;. ll\u00e1mesele como se quiera. Es decir en un espacio que deber\u00eda de estar protegido en su totalidad y ahora \u00a1qui\u00e9n lo sabe\u00a1.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Recojo en este blog, por su inter\u00e9s, una noticia que aparece en la p\u00e1gina desnivel.com y aunque parece alarmista, no dice m\u00e1s que la verdad. Con el t\u00edtulo de \u2018El Parque se divide\u2019 nos informa de la firma de un convenio de colaboraci\u00f3n entre Asturias, Cantabria y Castilla y Le\u00f3n para la \u2018supuesta gesti\u00f3n coordinada\u2019 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":44,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,12,16],"tags":[132,256],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-ecologia","category-naturaleza","category-sin-categoria","tag-asturias","tag-cantabria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/basabide\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}