{"id":90,"date":"2010-01-19T15:51:00","date_gmt":"2010-01-19T15:51:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=90"},"modified":"2010-01-19T15:51:00","modified_gmt":"2010-01-19T15:51:00","slug":"pajaros-y-ratones","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2010\/01\/19\/pajaros-y-ratones\/","title":{"rendered":"P\u00e1jaros y ratones"},"content":{"rendered":"<p><P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><FONT size=3 face=Calibri>Hace casi medio siglo, un investigador de la Universidad de Duke, en los Estados Unidos, llev\u00f3 un grupo de gorriones a un lugar que se encontraba a 6.100 m de altura. Aunque a esa altura hay menos de la mitad de ox\u00edgeno que a nivel del mar, result\u00f3 que los pajarillos<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>se comportaron con absoluta normalidad. No pareci\u00f3 que la escasez de ox\u00edgeno tuviese efecto especial en ellos. A pesar del poco que hab\u00eda, de alg\u00fan modo se las arreglaban para adquirir el ox\u00edgeno que necesitaban.<\/FONT><\/p>\n<p> <P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><FONT size=3 face=Calibri>Junto a los gorriones, tambi\u00e9n llev\u00f3 un grupo de ratones de tama\u00f1o similar al de aqu\u00e9llos. Los ratones, sin embargo, mostraron un comportamiento radicalmente diferente. De hecho, no mostraron comportamiento alguno; quedaron tumbados, patas arriba, en estado semicomatoso.<\/FONT><\/p>\n<p> <P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><FONT size=3 face=Calibri>El investigador pens\u00f3 que los gorriones quiz\u00e1s tuviesen una hemoglobina de alta afinidad por el ox\u00edgeno, de manera que fuese capaz de captar una cantidad apreciable de ox\u00edgeno incluso bajo condiciones de tanta escasez. Al fin y al cabo, esa es una de las caracter\u00edsticas en las que basan algunos mam\u00edferos su capacidad para vivir en zonas muy altas (veas\u00e9 la entrada \u201c<A id=link_0 title=http:\/\/blogs.elcorreodigital.com\/animaladas\/2009\/9\/1\/en-cordillera-andina href=\"http:\/\/blogs.elcorreo.com\/animaladas\/2009\/9\/1\/en-cordillera-andina\">En la cordillera andina<\/A>\u201d). Sin embargo, no encontr\u00f3 diferencias significativas entre la afinidad de la hemoglobina de los gorriones y la de los ratones, por lo que las diferencias entre las dos especies deb\u00edan radicar en el funcionamiento del sistema cardiovascular, del respiratorio, o de ambos a la vez. <\/FONT><\/p>\n<p> <P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><FONT size=3 face=Calibri>En relaci\u00f3n con el sistema cardiovascular hay que decir que las aves tienen el coraz\u00f3n de gran tama\u00f1o. El de un gorri\u00f3n es tres veces m\u00e1s grande que el de un rat\u00f3n. Por esa raz\u00f3n, en cada latido bombea mucha m\u00e1s sangre. Y adem\u00e1s de eso, los pulmones de las aves son tremendamente eficaces, mucho m\u00e1s que los pulmones de mam\u00edferos. Veamos, en primer lugar, c\u00f3mo respiran los mam\u00edferos, para as\u00ed valorar mejor el modo en que lo hacen las aves.<\/FONT><\/p>\n<p> <P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><FONT size=3 face=Calibri>En el pulm\u00f3n de mam\u00edferos el aire inspirado y el espirado se mueven por la misma v\u00eda; el flujo es bidireccional. Adem\u00e1s, el pulm\u00f3n no se vac\u00eda del todo al espirar; siempre queda un cierto volumen de aire sin desalojar. Por ello, el aire inspirado, cargado de ox\u00edgeno, se mezcla en la cavidad pulmonar con el que ha quedado, que tiene mucho menos ox\u00edgeno. As\u00ed pues, el aire cuyo ox\u00edgeno es tranferido desde el interior del pulm\u00f3n hacia los capilares sangu\u00edneos tiene una concentraci\u00f3n de ox\u00edgeno significativamente menor que la atmosf\u00e9rica. Dado que la difusi\u00f3n desde un enclave a otro depende del gradiente (la diferencia de presiones parciales) de ox\u00edgeno entre ambos, esa difusi\u00f3n ser\u00eda m\u00e1s intensa de lo que es si el contenido en ox\u00edgeno del interior pulmonar fuese como el del aire inspirado. <\/FONT><\/p>\n<p> <P style=\"MARGIN: 6pt 0cm\" class=MsoNormal><SPAN style=\"mso-ansi-language: ES-TRAD\" lang=ES-TRAD><FONT size=3><FONT face=Calibri>En las aves las cosas ocurren de otra forma. El aparato respiratorio de las aves es complejo pero, como se ha dicho, muy efectivo. En estos tambi\u00e9n se toma y se expulsa el aire por el mismo lugar, por la boca, pero el itinerario que sigue en el interior es bastante m\u00e1s intrincado. El aparato respiratorio de aves cuenta con cuatro sacos a\u00e9reos, y en cada movimiento respiratorio se produce un desplazamiento del aire inspirado de un saco a otro, de manera que va recorriendolos todos uno a uno. Entre dos de esos sacos se encuentran los bronquios, que tienen forma tubular y el aire pasa por esos tubos, siempre en el mismo sentido, sin que haya posibilidad de que se mezcle el aire inspirado con el espirado. Como consecuencia de ello, la presi\u00f3n parcial de ox\u00edgeno del aire que proporciona el ox\u00edgeno a los capilares bronquiales es bastante alta, lo que facilita considerablemente la transferencia. Por si eso fuese poco, la disposici\u00f3n f\u00edsica de bronquios y capilares tambi\u00e9n contribuye a facilitar esa transferencia.<?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/FONT><\/FONT><\/SPAN><\/p>\n<p><SPAN style=\"FONT-FAMILY: 'Calibri', 'sans-serif'; FONT-SIZE: 12pt; mso-ansi-language: ES-TRAD; mso-fareast-font-family: 'Times New Roman'; mso-bidi-font-family: 'Times New Roman'; mso-fareast-language: ES; mso-bidi-language: AR-SA\" lang=ES-TRAD><FONT face=Calibri>As\u00ed pues, ya sabemos qu\u00e9 es lo que permite a los gorriones encontrarse tan c\u00f3modos a gran altura. En cierto modo podr\u00edamos decir que las aves se encuentran \u201cpreadaptadas\u201d a vivir en lugares tan altos.<\/FONT><\/SPAN><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace casi medio siglo, un investigador de la Universidad de Duke, en los Estados Unidos, llev\u00f3 un grupo de gorriones a un lugar que se encontraba a 6.100 m de altura. Aunque a esa altura hay menos de la mitad de ox\u00edgeno que a nivel del mar, result\u00f3 que los pajarillos se comportaron con absoluta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[39,162,319,522],"class_list":["post-90","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-altura","tag-corazon","tag-hemoglobina","tag-pulmon"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}