{"id":89,"date":"2010-01-13T13:40:00","date_gmt":"2010-01-13T13:40:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=89"},"modified":"2010-01-13T13:40:00","modified_gmt":"2010-01-13T13:40:00","slug":"el-viaje-la-muerte","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2010\/01\/13\/el-viaje-la-muerte\/","title":{"rendered":"El viaje a la muerte"},"content":{"rendered":"<p><P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><FONT face=\"\"><FONT size=2><SPAN lang=EN-US>En m\u00e1s de una ocasi\u00f3n me he ocupado aqu\u00ed de los salmones. Lo hice en las entradas \u201c<A id=link_0 title=http:\/\/blogs.elcorreodigital.com\/animaladas\/2009\/9\/23\/la-esforzada-vida-los-salmones href=\"http:\/\/blogs.elcorreo.com\/animaladas\/2009\/9\/23\/la-esforzada-vida-los-salmones\"><SPAN lang=EN-US>La esforzada vida de los <\/SPAN><SPAN style=\"LINE-HEIGHT: 115%; FONT-SIZE: 12pt\" lang=EN-US>salmones<\/SPAN><\/A><\/SPAN><SPAN lang=EN-US>\u201d y en \u201c<A id=link_1 title=http:\/\/blogs.elcorreodigital.com\/animaladas\/2009\/9\/13\/peces-van-y-vienen href=\"http:\/\/blogs.elcorreo.com\/animaladas\/2009\/9\/13\/peces-van-y-vienen\">Peces que van y vienen<\/A>\u201d. Y lo volver\u00e9 a hacer aqu\u00ed. Vuelvo con otra historia de peces an\u00e1dromos. Recordemos: los peces an\u00e1dromos son los que nacen en agua dulce, se dirigen luego al mar, donde crecen y engordan, para regresar finalmente al r\u00edo a desovar. Todos los salmones pertenecen a <?xml:namespace prefix = st1 ns = \"urn:schemas-microsoft-com:office:smarttags\" \/><st1:PersonName ProductID=\"la familia Salmonidae\" w:st=\"on\">la familia Salmonidae<\/st1:PersonName>, de la que, por cierto, tambi\u00e9n son miembros las truchas.<\/SPAN><\/FONT><\/FONT>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">Los salmones a los que me referir\u00e9 aqu\u00ed son los pertenecientes a la especie cuyo nombre com\u00fan es salm\u00f3n \u201csockeye\u201d y cuyo nombre cient\u00edfico es <I style=\"mso-bidi-font-style: normal\">Oncorhynchus nerka<\/I>. El nombre com\u00fan procede del que se le daba a estos salmones en una lengua de la costa oeste de Norteam\u00e9rica, zona en la que se encuentran. Suk-kegh es la palabra de la lengua amerindia en cuesti\u00f3n y quiere decir pez rojo. De ah\u00ed viene la palabra sockeye, al anglizar los europeos el vocablo amerindio. <\/FONT><\/SPAN> <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><FONT size=2><FONT face=\"\"><SPAN lang=EN-US>Una particularidad curiosa de estos salmones es que hay diferentes patrones migratorios. Hay algunas poblaciones, las menos, cuyos miembros viven en lagos y no migran nunca. Permanecen en el lago toda su vida y alcanzan un tama\u00f1o muy peque\u00f1o.<\/SPAN><SPAN style=\"mso-ansi-language: ES\" lang=EN-US> <\/SPAN><SPAN lang=EN-US>No obstante, la mayor\u00eda s\u00ed migra. Pueden nacer en un r\u00edo o en un lago, pero los que nacen en un r\u00edo, si pueden, se quedan durante uno, dos o tres a\u00f1os en un lago del mismo sistema hidrol\u00f3gico antes de dirigirse al mar. Los que no tienen la oportunidad de pasar su juventud en un lago se dirigen al mar antes, y lo hacen con un tama\u00f1o menor que los que pasan antes por el lago. Por flexibilidad en el ciclo de vida, que no quede.<\/SPAN><\/FONT><\/FONT>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">Como expliqu\u00e9 en \u201c<A id=link_2 title=http:\/\/blogs.elcorreodigital.com\/animaladas\/2009\/9\/13\/peces-van-y-vienen href=\"http:\/\/blogs.elcorreo.com\/animaladas\/2009\/9\/13\/peces-van-y-vienen\">Peces que van y vienen<\/A>\u201d, los peces an\u00e1dromos viajan al mar a crecer y engordar. En el mar pemanecen entre uno y cuatro a\u00f1os, hasta que han adquirido la suficiente biomasa y alcanzado la madurez reproductiva. En ese momento comienza el viaje de regreso al r\u00edo, un viaje que constituye una verdadera haza\u00f1a.<\/FONT><\/SPAN>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">El viaje puede llegar a ser muy largo, de miles de kil\u00f3metros para algunos salmones. Pues bien, en el momento en que lo empiezan dejan de comer, y ya no volver\u00e1n a alimentarse nunca. Durante las semanas o meses que dure el viaje recurrir\u00e1n a las reservas de energ\u00eda que hab\u00edan acumulado durante los meses anteriores para mantenerse y propulsarse, y los gametos ya los han producido. No necesitan nada m\u00e1s.<\/FONT><\/SPAN>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">A lo largo del viaje van gastando las reservas almacenadas, principalmente para satisfacer las demandas de la nataci\u00f3n prolongada. Al comienzo hacen uso de las reservas lip\u00eddicas, y m\u00e1s tarde, cuando se van agotando las grasas, empiezan a catabolizar prote\u00ednas. Por sorprendente que pueda parecer, el gluc\u00f3geno, que es la mol\u00e9cula de reserva que utilizar\u00edan casi todos los vertebrados al principio, lo reservan hasta el \u00faltimo momento.<\/FONT><\/SPAN>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">La raz\u00f3n de ese proceder es que el gluc\u00f3geno constituye para los salmones una reserva de \u201cemergencia\u201d. Lo utilizan cuando saltan para superar los r\u00e1pidos y peque\u00f1as presas del r\u00edo, porque es el sustrato energ\u00e9tico ideal para sostener esfuerzos breves y muy intensos. Pero de esa forma se gasta una cantidad relativamente menor de gluc\u00f3geno. La mayor parte la reservan, para dedicarlo a las \u00faltimas actividades que han de realizar una vez han alcanzado el punto de destino. La freza es una actividad de alta demanda metab\u00f3lica, porque requiere la ejecuci\u00f3n de movimientos muy en\u00e9rgicos para que se produzca la liberaci\u00f3n de los gametos; y despu\u00e9s, tras la fecundaci\u00f3n, para cubrir con grava los huevos.<\/FONT><\/SPAN>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">Una vez completadas la freza, fecundaci\u00f3n y acomodo de los huevos, permanecen otras dos o tres semanas con vida, cuidando el nido las hembras y tratando de fecundar ovocitos de otras hembras los machos.<\/FONT><\/SPAN>  <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal><SPAN lang=EN-US><FONT size=2 face=\"\">Y luego mueren.<\/FONT><\/SPAN><SPAN style=\"mso-ansi-language: ES\"><?xml:namespace prefix = o ns = \"urn:schemas-microsoft-com:office:office\" \/><o:p><\/o:p><\/SPAN><\/p>\n<p> <P style=\"MARGIN: 10pt 0cm\" class=MsoNormal>En el video se puede ver un episodio de freza de salmones sockeye.<\/p>\n<p> <OBJECT style=\"BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; MARGIN: 0px; BACKGROUND: none transparent scroll repeat 0% 0%; BORDER-TOP: 0px; BORDER-RIGHT: 0px\" width=425 height=344><PARAM NAME=\"movie\" VALUE=\"http:\/\/www.youtube.com\/v\/q6zEeunHXJI&#038;hl=es_ES&#038;fs=1&#038;\"><PARAM NAME=\"allowFullScreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"> <embed   src=\"\/\/www.youtube.com\/v\/q6zEeunHXJI&#038;hl=es_ES&#038;fs=1&#038;\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"425\" height=\"344\"><\/embed><\/OBJECT><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En m\u00e1s de una ocasi\u00f3n me he ocupado aqu\u00ed de los salmones. Lo hice en las entradas \u201cLa esforzada vida de los salmones\u201d y en \u201cPeces que van y vienen\u201d. Y lo volver\u00e9 a hacer aqu\u00ed. Vuelvo con otra historia de peces an\u00e1dromos. Recordemos: los peces an\u00e1dromos son los que nacen en agua dulce, se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[299,309,381,472,551,571],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-glucogeno","tag-grasas","tag-lipidos","tag-peces-anadromos","tag-reservas-energeticas","tag-salmones"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}