{"id":22,"date":"2009-05-12T08:59:00","date_gmt":"2009-05-12T08:59:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=22"},"modified":"2009-05-12T08:59:00","modified_gmt":"2009-05-12T08:59:00","slug":"ranas-impermeables","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2009\/05\/12\/ranas-impermeables\/","title":{"rendered":"Ranas impermeables"},"content":{"rendered":"<p><P class=MsoNormal style=\"MARGIN: 6pt 0cm\"><FONT size=3><EM><\/EM>Los anfibios dependen mucho del agua, tambi\u00e9n los que, de adultos, viven en el medio terrestre. Esa es la raz\u00f3n por la que suelen frecuentar zonas h\u00famedas e incluso, tienden a vivir de forma permanente al lado de masas de agua. Su piel es muy permeable y, de hecho, esa es la raz\u00f3n por la que la piel puede desempe\u00f1ar un papel importante en el intercambio de gases respiratorios, ox\u00edgeno y di\u00f3xido de carbono. Pero esa permeabilidad es la que hace que en el medio terrestre lleguen a perder importantes cantidades de agua, porque la permeabilidad o impermeabilidad de una piel o de un epitelio no son espec\u00edficos para un tipo \u00fanico o familia de sustancias. Es una caracter\u00edstica general; as\u00ed, por ejemplo, si una piel es permeable al agua, lo normal es que tambi\u00e9n lo sea al ox\u00edgeno. <SPAN style=\"mso-spacerun: yes\"><\/SPAN><\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 6pt 0cm\"><FONT size=3>No obstante, y aunque pocas, tambi\u00e9n hay excepciones a la norma de la alta dependencia h\u00eddrica de los anfibios. Las ranas de los g\u00e9neros <I style=\"mso-bidi-font-style: normal\">Chiromantis<\/I> (\u00c1frica), <I style=\"mso-bidi-font-style: normal\">Hyperolius<\/I> (\u00c1frica), <I style=\"mso-bidi-font-style: normal\">Phyllomedusa<\/I> (Sudam\u00e9rica), <I style=\"mso-bidi-font-style: normal\">Litoria<\/I> (Australia) y <I style=\"mso-bidi-font-style: normal\">Polypedates<\/I> (India) pierden a trav\u00e9s de la piel mucha menos agua de la que ser\u00eda de esperar. La rana sudamericana <I style=\"mso-bidi-font-style: normal\">Phyllomedusa sauvagei<\/I> pierde en el medio terrestre much\u00edsimo menos de lo que cabr\u00eda esperar en una rana de sus caracter\u00edsticas. As\u00ed, mientras un ejemplar de <?xml:namespace prefix = st1 ns = \"urn:schemas-microsoft-com:office:smarttags\" \/><st1:metricconverter ProductID=\"2 g\" w:st=\"on\">2 g<\/st1:metricconverter> de esa especie pierde entre 0\u201901 y 0\u201902 g de agua por hora, una rana arb\u00f3rea del mismo tama\u00f1o pierde 0\u20195 g y otra no arb\u00f3rea puede llegar a perder hasta <st1:metricconverter ProductID=\"1 g\" w:st=\"on\">1 g<\/st1:metricconverter>. Rep\u00e1rese en el hecho de que esa p\u00e9rdida de agua representa la mitad del peso corporal de la rana.<\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 6pt 0cm\"><FONT size=3>La capacidad para minimizar la p\u00e9rdida de agua constituye una valiosa adaptaci\u00f3n cuando interesa reducir la dependencia h\u00eddrica; esto es, cuando la disponibilidad ambiental de agua es muy baja o cuando no es f\u00e1cil acceder a masas agua.<SPAN style=\"mso-spacerun: yes\"> <\/SPAN><\/FONT><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 6pt 0cm\"><FONT size=3>Ahora bien, la cuesti\u00f3n es c\u00f3mo puede una rana limitar la p\u00e9rdida de agua en el medio terrestre. Hay mecanismos diferentes para conseguirlo y aqu\u00ed, por ahora, nos centraremos en uno de esos mecanismos.<I style=\"mso-bidi-font-style: normal\"> Phyllomedusa sauvagei<\/I>, por ejemplo, utiliza una especie de \u201caceite\u201d, compuesto principalmente por triglic\u00e9ridos, que produce ella misma. El aceite lo producen unas gl\u00e1ndulas de la piel y la rana lo extiende con sus patas por toda su superficie corporal; los movimientos que realiza para extender el aceite son movimientos estereotipados, siempre los mismos. Y el mismo procedimiento utiliza <st1:PersonName ProductID=\"la rana Polypedates\" w:st=\"on\">la rana <I style=\"mso-bidi-font-style: normal\">Polypedates<\/I><\/st1:PersonName><I style=\"mso-bidi-font-style: normal\"> maculatus<\/I>. En ambos casos, para que el m\u00e9todo sea efectivo, las ranas deben permanecer inm\u00f3viles una vez aplicado el aceite; de lo contrario, la pel\u00edcula lip\u00eddica se fragmentar\u00eda y perder\u00eda su efectividad.<\/FONT><\/p>\n<p><SPAN style=\"FONT-SIZE: 11pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt; mso-fareast-font-family: 'Times New Roman'; mso-bidi-font-family: 'Times New Roman'; mso-ansi-language: ES; mso-fareast-language: ES; mso-bidi-language: AR-SA\">Esta adaptaci\u00f3n, sin embargo, tiene una contrapartida que tiene que ver con algo que se ha se\u00f1alado antes. La capa de triglic\u00e9ridos, a la vez que evita la p\u00e9rdida de agua, tambi\u00e9n obstaculiza el intercambio de gases respiratorios. Por ello, bajo esas condiciones las ranas s\u00f3lo incorporan ox\u00edgeno y eliminan di\u00f3xido de carbono a trav\u00e9s de sus pulmones. Pero en cualquier caso, se trata de una contrapartida menor teniendo en cuenta las ventajas que se derivan de reducir su dependencia h\u00eddrica.<\/SPAN><\/p>\n<p> <P class=MsoNormal style=\"MARGIN: 6pt 0cm\"><SPAN style=\"FONT-SIZE: 11pt; FONT-FAMILY: Verdana; mso-bidi-font-size: 12.0pt; mso-fareast-font-family: 'Times New Roman'; mso-bidi-font-family: 'Times New Roman'; mso-ansi-language: ES; mso-fareast-language: ES; mso-bidi-language: AR-SA\"><\/SPAN><\/p>\n<p>No he encontrado im\u00e1genes de estas ranas aplicando la pel\u00edcula de triglic\u00e9ridos, pero a cambio, en este video se ve a un ejemplar de <EM>Pollymedusa sauvagei<\/EM> cazando una presa: <OBJECT  height=344 width=425><PARAM NAME=\"movie\" VALUE=\"http:\/\/www.youtube.com\/v\/2fLL7_nRqwE&#038;hl=es&#038;fs=1\"><PARAM NAME=\"allowFullScreen\" VALUE=\"true\"><PARAM NAME=\"allowscriptaccess\" VALUE=\"always\"> <embed   src=\"\/\/www.youtube.com\/v\/2fLL7_nRqwE&#038;hl=es&#038;fs=1\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"425\" height=\"344\"><\/embed><\/OBJECT><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los anfibios dependen mucho del agua, tambi\u00e9n los que, de adultos, viven en el medio terrestre. Esa es la raz\u00f3n por la que suelen frecuentar zonas h\u00famedas e incluso, tienden a vivir de forma permanente al lado de masas de agua. Su piel es muy permeable y, de hecho, esa es la raz\u00f3n por la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[46,179,489,510,532,555,627],"class_list":["post-22","post","type-post","status-publish","format-standard","hentry","category-balance-hidrico-y-osmotico","tag-anfibios","tag-dependencia-hidrica","tag-phyllomedusa-sauvagei","tag-polypedates-maculatus","tag-ranas","tag-respiracion-cutanea","tag-trigliceridos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/22\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=22"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=22"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}