{"id":215,"date":"2012-03-23T09:11:48","date_gmt":"2012-03-23T08:11:48","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=215"},"modified":"2012-03-23T09:11:48","modified_gmt":"2012-03-23T08:11:48","slug":"a-veces-no-respiran","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2012\/03\/23\/a-veces-no-respiran\/","title":{"rendered":"A veces no respiran"},"content":{"rendered":"<div id=\"attachment_216\" style=\"width: 586px\" class=\"wp-caption aligncenter\"><a href=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/03\/Queen-and-Court.gif\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-216\" class=\"size-full wp-image-216 \" title=\"Queen-and-Court\" src=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/03\/Queen-and-Court.gif\" alt=\"\" width=\"576\" height=\"420\" \/><\/a><p id=\"caption-attachment-216\" class=\"wp-caption-text\">En el centro de la imagen, la abeja reina<\/p><\/div>\n<p style=\"text-align: left;\">Los insectos son animales asombrosos. Lo son por la importancia que tienen en el reino animal. Son, de hecho, el grupo m\u00e1s diverso; hay 1 mill\u00f3n de especies descritas y much\u00edsimas m\u00e1s a\u00fan sin describir<a title=\"\" href=\"#_ftn1\">[1]<\/a>. Tambi\u00e9n son muy abundantes; se estima que hay 200 millones de insectos por cada ser humano.<\/p>\n<p>Los insectos son tambi\u00e9n asombrosos por algunas peculiaridades de su fisiolog\u00eda, de su funcionamiento. Aqu\u00ed nos vamos a ocupar de una de esas peculiaridades, relativa a su fisiolog\u00eda respiratoria. Tienen las tasas metab\u00f3licas m\u00e1s altas en el reino animal. No hay animales que, por unidad de masa, consuman m\u00e1s ox\u00edgeno que los insectos. Por otra parte, su sistema respiratorio es muy especial. El ox\u00edgeno llega directamente, a trav\u00e9s de un sistema de tr\u00e1queas, de la atm\u00f3sfera a las c\u00e9lulas. As\u00ed pues, carecen de pulmones, y por supuesto, tampoco tienen branquias; el ox\u00edgeno llega hasta las c\u00e9lulas sin que medie un sistema circulatorio.<\/p>\n<p>Las tr\u00e1queas son tubos que parten de poros que se encuentran en la cut\u00edcula externa. Esos tubos se van ramificando conforme se introducen en el interior del organismo; de ese modo, las tr\u00e1queas se van subdividiendo en traqueolas, que son tubos que son cada vez m\u00e1s finos seg\u00fan se van ramificando. Cada c\u00e9lula acaba recibiendo una de esas traqueolas de min\u00fasculo di\u00e1metro, y es por ellas por donde llega el ox\u00edgeno a las c\u00e9lulas. El di\u00f3xido de carbono sale, a su vez, por la misma v\u00eda.<\/p>\n<p>Los poros de la cut\u00edcula externa reciben el nombre de espir\u00e1culos y cada uno de ellos tiene una v\u00e1lvula muscular, de la que depende que el espir\u00e1culo est\u00e9 abierto o cerrado. En varias especies se produce un fen\u00f3meno que se denomina respiraci\u00f3n discontinua o respiraci\u00f3n a intervalos. Esos insectos dejan de respirar cada cierto tiempo; respiran a intervalos.<\/p>\n<p>No est\u00e1 claro cu\u00e1l es la raz\u00f3n de ese comportamiento. Hasta la fecha se han propuesto tres interpretaciones y las tres parten del supuesto de que se trata de un comportamiento con valor adaptativo. De acuerdo con la m\u00e1s antigua de las tres, de lo que se trata es de ahorrar agua, ya que al cerrarse los espir\u00e1culos no se evapora agua; el agua que se evapora cuando los espir\u00e1culos est\u00e1n abiertos es la que, al fondo de la traqueola, se encuentra en contacto con la c\u00e9lula. Seg\u00fan la segunda hip\u00f3tesis, se tratar\u00eda de una adaptaci\u00f3n para poder enterrarse, puesto que, al parecer, la respiraci\u00f3n discontinua es muy com\u00fan en especies capaces de introducirse en el suelo, entre los granos de tierra o en orificios o cavidades subterr\u00e1neas. Y de acuerdo con la tercera hip\u00f3tesis, el objetivo de la respiraci\u00f3n a intervalos ser\u00eda evitar o paliar el estr\u00e9s oxidativo.<\/p>\n<p>Pero son tantas y de modo de vida tan diverso las especies que presentan ese comportamiento tan peculiar, que no parece plausible la pretensi\u00f3n de que haya de tener valor adaptativo y que tal valor sea com\u00fan al conjunto de especies o, expresado de otro modo, que responda de forma directa a alguna presi\u00f3n selectiva.<\/p>\n<p>Los insectos con respiraci\u00f3n discontinua comparten, sin embargo, una curiosa caracter\u00edstica: siempre que se interrumpe la respiraci\u00f3n, ocurre tambi\u00e9n que la actividad cerebral se encuentra muy reducida o, sencillamente, no hay actividad cerebral ninguna.<\/p>\n<p>Como es sabido, el funcionamiento del tejido cerebral sale caro, muy caro, debido a su alta actividad metab\u00f3lica. Seguramente por ello, algunos animales han desarrollado modos de limitar ese gasto. Y si la masa cerebral es grande o si hay restricciones energ\u00e9ticas prolongadas, puede revestir gran importancia el poder limitar el gasto en que incurre ese tejido. Lo cierto es que todos los insectos que limitan o interrumpen su actividad cerebral tienen un cerebro relativamente grande o, como las reinas en las especies sociales, grandes necesidades de energ\u00eda. Y resulta que son esos los insectos que muestran respiraci\u00f3n discontinua.<\/p>\n<p>As\u00ed pues, \u00bfexiste alguna conexi\u00f3n entre el coste de la actividad cerebral y la respiraci\u00f3n discontinua? Veamos esto con detalle.<\/p>\n<p>Para empezar, hay que tener en cuenta que el estado, -abierto o cerrado-, de los espir\u00e1culos depende de unos m\u00fasculos, y es el sistema nervioso el que controla a esos m\u00fasculos. As\u00ed pues, existe una conexi\u00f3n entre el sistema respiratorio y el sistema nervioso. Por otro lado, cuando no hay actividad cerebral o cuando esa actividad est\u00e1 limitada, son los ganglios tor\u00e1cicos y abdominales los que asumen el control nervioso del animal, pero resulta que la actividad de esos ganglios y la de los cerebrales son muy diferentes. Por ejemplo, y en lo relativo a la actividad respiratoria, si la actividad cerebral se interrumpe o se reduce, los ganglios tor\u00e1cicos y abdominales no est\u00e1n sometidos a ning\u00fan control superior; y bajo esas condiciones, los generadores de patrones centrales son los que asumen el control de la actividad ventilatoria. El problema es que ese control no es tan fino como el que ejerce el cerebro, y quiz\u00e1s sea esa la raz\u00f3n por la que se interrumpe la respiraci\u00f3n.<\/p>\n<p>As\u00ed pues, de acuerdo con esa hip\u00f3tesis, la respiraci\u00f3n a intervalos no ser\u00eda ninguna adaptaci\u00f3n, sino la consecuencia de las reducciones en la actividad de los ganglios cerebrales. Es cierto que esa reducci\u00f3n conlleva un cierto ahorro de energ\u00eda y que ese ahorro es muy valioso, pero interrumpir la actividad respiratoria, en ese contexto, ser\u00eda una consecuencia secundaria de lo anterior. Por lo tanto, la respiraci\u00f3n discontinua ser\u00eda una consecuencia del \u201csue\u00f1o\u201d o del \u201capagado cerebral\u201d de los insectos.<\/p>\n<p><strong>Fuente:<\/strong> Philip G. D. Matthews &#038; Craig R. White (2011): \u201cDiscontinuous Gas Exchange in Insects: Is It All in Their Heads?\u201d The American Naturalist 177 (1): 130-134<\/p>\n<div><br clear=\"all\" \/><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<div>\n<p><a title=\"\" href=\"#_ftnref1\">[1]<\/a> Aunque hay diferentes opiniones, se estima que al menos hay m\u00e1s de 5 millones de especies de insectos sin describir<\/p>\n<\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los insectos son animales asombrosos. Lo son por la importancia que tienen en el reino animal. Son, de hecho, el grupo m\u00e1s diverso; hay 1 mill\u00f3n de especies descritas y much\u00edsimas m\u00e1s a\u00fan sin describir[1]. Tambi\u00e9n son muy abundantes; se estima que hay 200 millones de insectos por cada ser humano. Los insectos son tambi\u00e9n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[243,283,284,285,355,556,622,623],"class_list":["post-215","post","type-post","status-publish","format-standard","hentry","category-control-nervioso","category-respiracion","tag-espiraculos","tag-ganglios-cerebrales","tag-ganglios-toracicos","tag-ganglios-viscerales","tag-insectos","tag-respiracion-dicontinua","tag-traqueas","tag-traqueolas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}